{"id":4965,"count":1,"description":"","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/tag\/bundesligacoach\/","name":"Bundesligacoach","slug":"bundesligacoach","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags\/4965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts?tags=4965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}