{"id":89895,"date":"2026-02-09T23:03:55","date_gmt":"2026-02-09T22:03:55","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=89895"},"modified":"2026-02-09T23:03:55","modified_gmt":"2026-02-09T22:03:55","slug":"igor-parfenov-greift-beim-insel-salon-in-die-tasten","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2026\/02\/09\/igor-parfenov-greift-beim-insel-salon-in-die-tasten\/","title":{"rendered":"Igor Parfenov greift beim INSEL-Salon in die Tasten"},"content":{"rendered":"<div class=\"bodySlots\">\n<div class=\"bText\">\n<div id=\"attachment_89899\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-89899 size-full\" src=\"\/wp-content\/uploads\/2026\/02\/Igor-Parfenov-Foto-Ensemble-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1721\" \/><span class=\"wp-caption-text\">Der mehrfach ausgezeichnete Pianist Igor Parfenov gibt ein Konzert auf der INSEL &#8211; \u00a9 Foto Ensemble<\/span><\/div>\n<p>Igor Parfenov wurde 1990 in Sankt-Petersburg geboren. Im Alter von 6 Jahren begann er mit dem Klavierspiel. Mit 16 Jahren studierte er am Pre-College des Sankt-Petersburger Konservatoriums, 2009 wurde er am Konservatorium aufgenommen. Im Verlauf des Studiums nahm er an diversen internationalen Wettbewerben und Festivals teil und wurde mehrfach ausgezeichnet. So spielte er beim Chopin-Wettbewerb in Estland oder beim Wettbewerb \u201cDie Kunst des XX. Jahrhunderts\u201d in Finnland.<\/p>\n<p>Meisterkurse besuchte er u.a. bei Dmitriy Baschkirov, Sontruad Speidel und Jos\u00e9 Ribera. 2012\/2013 und 2013\/2014 wurde Parfenov als Stipendiat der Werner Richard-Dr. Carl D\u00f6rken Stiftung zu Konzerten eingeladen, sowohl als Solist als auch mit Orchestern wie der Sinfonietta K\u00f6ln, den Bergischen Symphonikern und dem Symphonieorchester Rheine.<\/p>\n<p>Ab 2011 studierte er im Studiengang \u201cBachelor of Musik\u201d an der Hochschule f\u00fcr Musik und Tanz K\u00f6ln am Standort Wuppertal bei Prof. Josef Anton Scherrer. Im Mai 2012 gewann Igor Parfenov beim Steinway-Wettbewerb f\u00fcr ausgew\u00e4hlte Studentinnen und Studenten der Hochschulen Essen, D\u00fcsseldorf und K\u00f6ln einen 1. Preis. Im April 2014 trat er mit dem Hochschulorchester unter der Leitung von Prof. Werner Dickel mit dem zweiten Klavierkonzert von Rachmaninow in der Historische Stadthalle Wuppertal auf.<\/p>\n<p>Igor Parfenov war Stipendiat der Dr. Arthur Pfungst-Stiftung, der Dr. Gerhard Weil-Stiftung, der Schuler-Stiftung und der Norbert Janssen Stiftung. 2023 absolvierte Igor Parfenov an der Robert Schumann Hochschule D\u00fcsseldorf den Masterstudiengang bei Prof. Lisa Eisner-Smirnova. 2023 erhielt Igor Parfenov den Grand Prix beim Internationalen Vivaldi-Musikwettbewerb. 2024 hat er einen neuen Konzertfl\u00fcgel in der Historischen Stadthalle Wuppertal mit einem Solokonzert eingeweiht. Er ist Preistr\u00e4ger des Springmann-Preises 2025.<\/p>\n<p><strong>Termin:<\/strong><\/p>\n<p><strong>&#8222;I<span style=\"font-family: Avenir-Book;\">NSEL Musiksalon&#8220; &#8211; Musik und mehr\u00a0<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n<h4><span style=\"font-family: Avenir-Book;\">Pianist Igor Parfenov\u00a0<\/span><\/h4>\n<p>Programm:<br \/>\nFr\u00e9d\u00e9ric Chopin &#8211; Mazurkas<br \/>\nClaude Debussy &#8211; Images, 1re s\u00e9rie<br \/>\nArvo P\u00e4rt &#8211; F\u00fcr Alina<\/p>\n<p><strong><span style=\"font-family: Avenir-Book;\">Sonntag &#8211; 22. Februar 2026 &#8211; 18:00 Uhr (Einlass: 17:30 Uhr)<\/span><\/strong><\/p>\n<p><span style=\"font-family: Avenir-Book;\">Kulturzentrum INSEL &#8211; Wiesenstr. 6 &#8211; 42105 Wuppertal<br \/>\nEintritt: 12\/6 (VVK) &#8211; 14\/8 (AK)<br \/>\nF\u00fcr Besucher unter 21 Jahren ist der Eintritt frei. Bitte sendet uns bei Interesse eine kurze Nachricht an <a href=\"mailto:post@insel.news\">post@insel.news<\/a>.<\/span><\/p>\n<div class=\"bodySlots\">\n<div class=\"bLink\"><span style=\"font-family: Avenir-Book;\"><a href=\"https:\/\/www.insel.news\/Musiksalon\/category\/igor-parfenov-klavier\" target=\"_blank\" rel=\"noopener\">www.insel.news\/Musiksalon\/category\/igor-parfenov-klavier<\/a><\/span><\/div>\n<div class=\"bLink\"><\/div>\n<\/div>\n<div class=\"bodySlots\">\n<div class=\"bLink\"><a href=\"https:\/\/www.igor-parfenov.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Avenir-Book;\">www.igor-parfenov.com<\/span><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der &#8222;INSEL Musiksalon&#8220; bringt Menschen und Musiker zusammen &#8211; und das immer wieder sonntags. Die hochkar\u00e4tige Musik-Reihe wird vom Pianisten Mark Kantorovic kuratiert. Musikerinnen und Musiker von Klassik bis Neue Musik spielen und singen und erz\u00e4hlen von ihrer Musik. Star-Gast am Sonntag (22.02) ist der Pianist Igor Parfenov. Die Bar ist ge\u00f6ffnet. Das interessierte Publikum lauscht.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-89895","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:35:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/89895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=89895"}],"version-history":[{"count":4,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/89895\/revisions"}],"predecessor-version":[{"id":89900,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/89895\/revisions\/89900"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=89895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=89895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=89895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}