{"id":84978,"date":"2025-06-20T04:29:00","date_gmt":"2025-06-20T02:29:00","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=84978"},"modified":"2025-06-28T15:07:02","modified_gmt":"2025-06-28T13:07:02","slug":"tischtennis-profi-olga-koop-als-schlagfertiger-podcast-gast","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2025\/06\/20\/tischtennis-profi-olga-koop-als-schlagfertiger-podcast-gast\/","title":{"rendered":"Tischtennis-Profi Olga Koop als schlagfertiger Podcast-Gast"},"content":{"rendered":"<div id=\"attachment_84982\" class=\"wp-caption alignnone\" style=\"max-width: 1580px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-84982 size-full\" src=\"\/wp-content\/uploads\/2025\/06\/1603206537.png\" alt=\"\" width=\"1570\" height=\"1080\" \/><span class=\"wp-caption-text\">Olga Koop &#8211; schlagferig und erfolgreich &#8211; auch im im Podcast &#8222;Mut zur L\u00fccke &#8211; \u00a9 TTT OK!<\/span><\/div>\n<p>\u201eMut zur L\u00fccke\u201c haben Natalie-Christine Toussaint und Dr. Detlef Schulz ihren Podcast getauft. Die Consulting-Leiterin eines gro\u00dfen internationalen Unternehmens und der Zahnarzt, der sich selbst als Mundgesundheits-Coach sieht, stellen Menschen vor, die auf Umwegen ihre Traumberuf oder ihr Lebensgl\u00fcck gefunden haben. Episode 03 mit Olga Koop\u00a0k\u00f6nnen Sie sich ab sofort auf dem \u201eYouTube\u201c-Kanal unter \u201eMut zur L\u00fccke \u2013 der Podcast\u201c (siehe unten) anschauen.<\/p>\n<p>Mit 16 Jahren kam Olga Koop nach Deutschland. Die Ruhr-Metropole Essen wurde ihre neue Heimat. Hier machte sie ihr Abitur und studierte anschlie\u00dfend Volkswirtschaftslehre. 13 Jahre lang spielte Olga Koop beim TuS Essen-Holsterhausen\u00a0 in der Tischtennis-Bundesliga auf h\u00f6chstem Niveau.<\/p>\n<p>Auch jetzt &#8211; mit Anfang 40 &#8211; ist sie noch als Tischtennis-Profi unterwegs. Sie schwingt ihren Schl\u00e4ger erfolgreich f\u00fcr den Club Z\u00fcrich-Affoltern, der in der zweith\u00f6chsten Schweizer Frauen-Tischtennisliga spielt. Auch ihr zweites Standbein hat sehr viel mit ihrem Lieblingssport zu tun. Olga Koop betreibt in Essen die Tischtennisschule \u201eTischTennisTreff\u00a0 OK!&#8220; (ttt ok). Olga Koop veranstaltet regelm\u00e4\u00dfig Workshops \u2013 und das nicht nur bei \u201eTTT OK\u201c in Essen, sondern auch auf der Ferieninsel Mallorca (Spanien).<\/p>\n<div id=\"attachment_84983\" class=\"wp-caption alignnone\" style=\"max-width: 1610px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-84983 size-full\" src=\"\/wp-content\/uploads\/2025\/06\/PHOTO-2025-05-10-14-08-08.jpg\" alt=\"\" width=\"1600\" height=\"1196\" \/><span class=\"wp-caption-text\">Natalie Toussaint und Dr. Detlef Schulz im Gespr\u00e4ch mit Tischtennis-Profi Olga Koop &#8211; \u00a9 Marc Waterwiese<\/span><\/div>\n<p>Bei \u201eMut zur L\u00fccke \u2013 der Podcast\u201c gew\u00e4hrt sie viele Einblicke in ihre Gef\u00fchlswelt \u2013 pr\u00e4sentiert sich glaubw\u00fcrdig und authentisch als selbstbewusste, erfolgreiche Frau, die mit beiden Beinen fest im Leben steht und genau wei\u00df, was sie will.<\/p>\n<p>Gast im n\u00e4chsten Podcast, der im Juli ver\u00f6ffentlicht wird, ist \u00fcbrigens Ex-Theater-Prinzipal Christian Stratmann, fr\u00fcher Betreiber des Mond-Palasts in Herne-Wanne-Eickel und Bruder des verstorbene Comedy-Stars Dr. Ludger Stratmann. Wann der Podcast online ist, erfahren Sie hier.<\/p>\n<p><strong>Link zum Podcast mit Olga Koop:<\/strong><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=iFBDX2B2vaE&amp;t=2993s\">https:\/\/www.youtube.com\/watch?v=iFBDX2B2vaE&amp;t=2993s<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schon als Teenager schmetterte Olga Koop ihren Gegnerinnen die Zelluloidb\u00e4lle nur so um die Ohren und war Tischtennis-Sch\u00fcler-Nationalspielerin ihres Heimatlandes Kasachstan. Damals ahnte sie noch nicht, dass der kleine wei\u00dfe Ball auch in Zukunft ihr Leben pr\u00e4gen w\u00fcrde. Nicht nur diesen kleinen wei\u00dfen Ball griffen jetzt Natalie Toussaint und Dr. Detlef Schulz in ihrem Podcast \u201eMut zur L\u00fccke\u201c mit Olga Koop als sympathische, quirlige Gespr\u00e4chspartnerin auf.\u00a0<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-84978","post","type-post","status-publish","format-standard","hentry","category-weitblick"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:41:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/84978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=84978"}],"version-history":[{"count":6,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/84978\/revisions"}],"predecessor-version":[{"id":84990,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/84978\/revisions\/84990"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=84978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=84978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=84978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}