{"id":82635,"date":"2025-03-31T22:46:05","date_gmt":"2025-03-31T20:46:05","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=82635"},"modified":"2025-04-06T08:24:17","modified_gmt":"2025-04-06T06:24:17","slug":"die-gewalt-gegen-amtspersonen-hat-zugenommen","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2025\/03\/31\/die-gewalt-gegen-amtspersonen-hat-zugenommen\/","title":{"rendered":"Die Gewalt gegen Amtspersonen hat zugenommen"},"content":{"rendered":"<div id=\"attachment_82639\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-82639 size-full\" src=\"\/wp-content\/uploads\/2025\/03\/Joris_Steg-Presse-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1932\" \/><span class=\"wp-caption-text\">Dr. Joris Steg, Wissenschaftlicher Mitarbeiter am Institut f\u00fcr Soziologie der Fakult\u00e4t f\u00fcr Human- und Sozialwissenschaften der Bergischen Universit\u00e4t &#8211; \u00a9 privat<\/span><\/div>\n<p>\u00dcber die Hintergr\u00fcnde der Anfeindungen und Gewalt im \u00f6ffentlichen Dienst hat sich Autor Uwe Blass im Rahmen der beliebten Uni-Reihe &#8222;Transfergeschichten&#8220; mit dem Soziologen Joris Steg unterhalten.<\/p>\n<p><strong>Sie selber forschen zur Gewalt gegen Politikerinnen, Politiker\u00a0 und Amtsmenschen. Zeigt die Studie des Innenministeriums besonders dramatische Zahlen oder kommen andere Studien zu vergleichbaren Ergebnissen? Wie ist es um die Gewalt gegen Politikerinnen und Politiker sowie Besch\u00e4ftigte im \u00f6ffentlichen Dienst bestellt?<\/strong><\/p>\n<p>Joris Steg: &#8222;Die Gewalt gegen Personen, die \u00c4mter aus\u00fcben und im \u00f6ffentlichen Dienst arbeiten \u2013 also z.B. Politikerinnen und Politiker auf der Bundes-, Landes- oder kommunalen Ebene, Einsatzkr\u00e4fte der Polizei, der Feuerwehr und des Rettungsdienstes, Beamte bzw. Angestellte in B\u00fcrokratie und Verwaltung sowie Lehrkr\u00e4fte \u2013, ist ein gravierendes Problem und hat in den letzten Jahren einen besorgniserregenden Umfang angenommen. Repr\u00e4sentative L\u00e4ngsschnittstudien, die Auskunft dar\u00fcber geben, wie sich die Gewalt gegen Amtsmenschen im Zeitverlauf entwickelt hat, sind zwar leider Mangelware, aber weil das Ph\u00e4nomen der Gewalt gegen Amtsmenschen in den letzten Jahren verst\u00e4rktes Interesse in der politisch-medialen \u00d6ffentlichkeit gefunden hat, existieren mittlerweile viele Untersuchungen \u00fcber diese Thematik.<\/p>\n<div id=\"attachment_44822\" class=\"wp-caption alignnone\" style=\"max-width: 440px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-44822\" src=\"\/wp-content\/uploads\/2022\/01\/Logo-Transfergeschichten.jpg\" alt=\"\" width=\"430\" height=\"138\" \/><span class=\"wp-caption-text\">\u00a9 Bergische Universit\u00e4t<\/span><\/div>\n<p>Weil die Studien selten repr\u00e4sentativ sind, sich auf unterschiedliche Berufsgruppen beziehen, unterschiedliche Stichproben haben und spezifische Ausschnitte abbilden, sind verallgemeinerbare Aussagen problematisch. Dennoch lassen sich einige generelle Trends beobachten. So zeigt sich erstens, dass Gewalt gegen Amtsmenschen ein gravierendes und weit verbreitetes Ph\u00e4nomen ist. Die Ergebnisse der Studie des Innenministeriums sind leider kein Ausnahmefall, ganz im Gegenteil. Viele Studien zeigen sogar eine noch h\u00f6here Quote der Gewaltbetroffenheit \u2013 unsere eigene Studie \u00fcber die Bedrohungslage von Politikerinnen und Politiker im Bergischen St\u00e4dtedreieck hat z.B. gezeigt, dass bereits ein Drittel der befragten Politikerinnen und Politiker Gewalt erlebt hat.<\/p>\n<p>Andere Studien kommen zu noch h\u00f6heren Ergebnissen. Der DGB etwa hat in seinem Faktenbuch zur Gewalt im \u00f6ffentlichen Dienst festgestellt, dass zwischen 2018 und 2020 mehr als zwei Drittel der Besch\u00e4ftigten im \u00f6ffentlichen Dienst und privatisierten Sektor Opfer verbaler oder physischer Gewalt wurden. Der zweite Trend ist, dass alle Studien zu der Schlussfolgerung kommen, dass die Gewalt in den letzten Jahren zugenommen hat. Drittens stimmen alle Studien darin \u00fcberein, dass verbale und psychische Gewalt in Form von Beleidigungen und Bedrohungen weitaus h\u00e4ufiger vorkommt als rohe physische Gewalt.&#8220;<\/p>\n<p><strong>Der Gewaltanteil h\u00e4ngt aber auch vom Besch\u00e4ftigungsbereich ab, oder?<\/strong><\/p>\n<p>Joris Steg: &#8222;Ja, eine nach Berufsgruppen differenzierte Betrachtung ist definitiv n\u00f6tig. Zum einen h\u00e4ngt der Gewaltanteil vom Besch\u00e4ftigungsbereich ab. Zum anderen gibt es auch je spezifische individuelle, akzidentielle, situative und berufsspezifische Ursachen, Motive, Gelegenheiten und Hintergr\u00fcnde, die bei der Gewalt gegen verschiedene Gruppen von Amtsmenschen eine Rolle spielen und betrachtet werden m\u00fcssen. Besonders betroffen von Gewalt sind etwa Polizistinnen und Polizisten \u2013 das ergibt sich schon alleine aus dem Grund, dass Gewalt(aus\u00fcbung) integraler Bestandteil des Berufes ist. Die Polizei ist die wesentliche Tr\u00e4gerin des staatlichen Gewaltmonopols und Polizistinnen und Polizisten k\u00f6nnen und m\u00fcssen sowohl bei der Strafverfolgung als auch zur Abwendung einer drohenden Gefahr unmittelbaren Zwang anwenden. Die Einsatzkr\u00e4fte der Polizei bewegen sich qua ihres Amtes h\u00e4ufig in risikoreichen und gef\u00e4hrlichen Situationen \u2013 u.a. Streitigkeiten, Ruhest\u00f6rungen, Straftaten, Festnahmen, Demonstrationen, Gro\u00dfveranstaltungen oder Fu\u00dfballspiele.<\/p>\n<div id=\"attachment_82645\" class=\"wp-caption alignnone\" style=\"max-width: 652px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-82645 size-full\" src=\"\/wp-content\/uploads\/2025\/03\/faust-schlaegt-durch-glasscheibe-Pixabay-1.jpg\" alt=\"\" width=\"642\" height=\"305\" \/><span class=\"wp-caption-text\">Die Gewalt im \u00f6ffentlichen Dienst nimmt zu &#8211; \u00a9 Pixabay<\/span><\/div>\n<p>Diese Situationen beg\u00fcnstigen Gewalt. Justizvollzugsbeamte sind aufgrund ihrer berufsspezifischen Eigenheiten ebenfalls besonders stark von Gewalt betroffen. Auch Politikerinnen und Politiker machen h\u00e4ufig Gewalterfahrungen. Sie sind in der Regel \u00f6ffentlich bekannte Personen, die in B\u00fcrgersprechstunden, bei Vorort-Terminen, \u00f6ffentlichen Ereignissen und Wahlkampfauftritten viel Kontakt mit B\u00fcrgerinnen und B\u00fcrgern haben. Zudem sind die meisten Politikerinnen und Politiker im Internet pr\u00e4sent und haben social media-Kan\u00e4le. Dadurch gibt es viele Gelegenheiten, sie verbal oder auch k\u00f6rperlich zu attackieren.<\/p>\n<p>W\u00e4hrend Polizistinnen, Polizisten und auch Justizvollzugsbeamte eher aufgrund ihrer beruflichen T\u00e4tigkeit attackiert werden, werden Politikerinnen und Politiker \u00fcberwiegend wegen ihrer eigenen politischen Einstellungen Opfer von Anfeindungen und Gewalt. Die Positionierung in Grundsatzfragen sowie in kontroversen Themenbereichen \u2013 etwa in der Migrationspolitik \u2013 ist, neben der Unzufriedenheit mit der Politik im Allgemeinen und mit konkreten politischen Entscheidungen im Besonderen, oftmals der entscheidende Faktor f\u00fcr die Gewalt gegen Politikerinnen und Politiker.&#8220;<\/p>\n<p><strong>Wo kommt die Gewalt gegen Amtsmenschen her? Und was sind die Ursachen f\u00fcr die zunehmende Gewalt? <\/strong><\/p>\n<p>Joris Steg: &#8222;Die Gewalt gegen Amtsmenschen ist ein komplexes und kompliziertes Ph\u00e4nomen, f\u00fcr das es keine monokausale oder lineare Erkl\u00e4rung gibt. N\u00f6tig ist eine differenzierte Analyse der vielschichtigen Ursachen und Hintergr\u00fcnde der Gewalt gegen Amtsmenschen. Dabei ist es von entscheidender Bedeutung, sowohl die Mikro- als auch die Makroperspektive zu ber\u00fccksichtigen. Das hei\u00dft, dass neben der Analyse der individuellen, akzidentiellen, situativen und berufsspezifischen Ursachen und Hintergr\u00fcnde auch der gesellschaftshistorische Kontext und gesellschaftliche Langfristtrends in den Blick genommen werden m\u00fcssen, weil sonst das Ph\u00e4nomen das Gewalt gegen Amtsmenschen weder verstanden noch ad\u00e4quat erkl\u00e4rt werden kann.<\/p>\n<p>Denn die zunehmende Gewalt resultiert nicht zuletzt aus einem Zusammenspiel und Zusammenwirken verschiedener sozio-\u00f6konomischer, politisch-kultureller und medialer Entwicklungen. Hier sind u.a. die Krisen und Konflikte der Gegenwart, die gestiegenen sozialen Ungleichheiten, das Erstarken des (Rechts-)<br \/>\nPopulismus, Autoritarismus sowie Nationalismus, der Autorit\u00e4ts- und Vertrauensverlust staatlicher Institutionen sowie der mediale Strukturwandel mit dem Aufstieg des Internets und der sozialen Medien zu nennen.<\/p>\n<div id=\"attachment_82641\" class=\"wp-caption alignnone\" style=\"max-width: 656px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-82641\" src=\"\/wp-content\/uploads\/2025\/03\/violence-against-women-4209778_640.jpg\" alt=\"\" width=\"646\" height=\"401\" \/><span class=\"wp-caption-text\">Die Zahl der Angriffe auf Amtspersonal nimmt zu &#8211; \u00a9 Pixabay<\/span><\/div>\n<p>Diese Entwicklungen haben zu einem starken Unzufriedenheits- und Frustrationspotenzial, das sich zum Teil gewaltsam entl\u00e4dt, gef\u00fchrt. Und sie haben zu einer Enthemmung der Sprache, einer Verrohung der Umgangsformen und des gesellschaftlichen Klimas beigetragen sowie zu einer Verschiebung sowohl der Grenze des Sagbaren als auch der Grenzen der als legitim angesehenen Handlungen beigetragen. Das Resultat dieser Verrohungstendenzen ist ein gesellschaftliches Klima, in dem Aggressionen und Gewalt gegen \u00f6ffentliche Personenkreise immer st\u00e4rker zunehmen und Akzeptanz finden.&#8220;<\/p>\n<p><strong>Die Hemmschwelle, \u00fcbergriffig zu werden, scheint zu sinken. Woran liegt das?<\/strong><\/p>\n<p>Joris Steg: &#8222;Die gesunkene Hemmschwelle, \u00fcbergriffig zu werden, ist mehr als besorgniserregend und leider ein allgemeiner Trend. Wie bereits angedeutet, erleben wir gerade eine zunehmende Enthemmung der Sprache und eine grunds\u00e4tzliche Verrohung des gesellschaftlichen Klimas, der politischen Kultur und des politischen Diskurses. Diese Verrohung artikuliert sich u.a. in Unzivilisiertheiten im gesellschaftlichen Miteinander, in Beleidigungen, Bedrohungen und Beschimpfungen im Internet und der realen Welt, in leicht eskalierenden sozialen Protesten sowie in roher physischer Gewalt, die sich gegen Mitmenschen oder \u00f6ffentliche Personenkreise wie Politikerinnen und Politiker, Einsatzkr\u00e4fte der Polizei, der Feuerwehr und des Rettungsdienstes, Beamte sowie Angestellte in B\u00fcrokratie und Verwaltung, Journalistinnen und Journalisten oder Lehrkr\u00e4fte richtet.<\/p>\n<p>Hinzu kommt der Autorit\u00e4ts- und Respektverlust gegen\u00fcber staatlichen Institutionen und staatlichen Autorit\u00e4ten. Dies f\u00fchrt in manchen F\u00e4llen zu Weigerungen, den Anordnungen von staatlichen Autorit\u00e4ten wie der Polizei Folge zu leisten. Zum Teil geht der Autorit\u00e4tsverlust auch so weit, dass staatliche Autorit\u00e4ten \u00fcberhaupt nicht mehr anerkannt und g\u00e4nzlich abgelehnt werden, wie es zum Beispiel bei der Bewegung der Reichsb\u00fcrger der Fall ist.<\/p>\n<p>In jedem Fall steht der Autorit\u00e4ts- und Respektverlust mit der gesunkenen Hemmschwelle zur verbalen und physischen Gewalt in Verbindung. Nicht zu vernachl\u00e4ssigen ist zudem die Rolle des Internets und der sozialen Medien. Die Hemmschwelle, Menschen zu beleidigen und zu bedrohen, scheint in der Anonymit\u00e4t des Netzes rasant zu sinken, w\u00e4hrend Hass und Hetze in der Anonymit\u00e4t des Netzes rapide zu steigen scheinen.&#8220;<\/p>\n<p><strong>Seit 2008 gibt es das von der Unfallkasse NRW sogenannte \u201eAachener Model\u201c der Gewaltpr\u00e4vention zur <\/strong><strong>Reduzierung von Bedrohungen und \u00dcbergriffen an Arbeitspl\u00e4tzen mit Publikumsverkehr. Hat sich das Model bew\u00e4hrt?<\/strong><\/p>\n<p>Joris Steg: &#8222;Das \u201eAachener Modell\u201c der Gewaltpr\u00e4vention hat sich in verschiedenen Bereichen als hilfreich erwiesen, insbesondere an Arbeitspl\u00e4tzen mit hohem Publikumsverkehr wie in Beh\u00f6rden oder sozialen Einrichtungen. Das Modell basiert auf einem systematischen Ansatz zur Pr\u00e4vention von Gewalt und Bedrohungen am Arbeitsplatz. Es umfasst Schulungen, Fortbildungen, Sensibilisierungsma\u00dfnahmen und klare Handlungsempfehlungen f\u00fcr die Besch\u00e4ftigten, wie sie gef\u00e4hrliche Situationen fr\u00fchzeitig erkennen und in Krisensituationen reagieren k\u00f6nnen.<\/p>\n<p>Auf diese Weise f\u00fchrt das Modell zum einen dazu, dass f\u00fcr das Ph\u00e4nomen der Gewalt am Arbeitsplatz \u00fcberhaupt erst sensibilisiert und ein Problembewusstsein geschaffen wird. Zum anderen wird den Besch\u00e4ftigten pr\u00e4ventiv geholfen, potenzielle Gef\u00e4hrdungen fr\u00fchzeitig zu erkennen und zu vermeiden. Und schlie\u00dflich geht es um konkrete Handlungsm\u00f6glichkeiten und Handlungsempfehlungen f\u00fcr die Besch\u00e4ftigten. Dazu geh\u00f6ren auch die Entwicklung eines Sicherheitskonzeptes f\u00fcr Notfall- und Krisensituationen sowie die Entwicklung eines Nachsorgekonzeptes f\u00fcr berufsbedingte Krisensituationen und psychische Belastungen.&#8220;<\/p>\n<p><strong>Die Stadt Wuppertal trat 2022 dem Pr\u00e4ventionsnetzwerk #sicherimDienst bei. Wie hilfreich sind solche Netzwerke und k\u00f6nnen Sie den Besch\u00e4ftigten Sicherheit geben?<\/strong><\/p>\n<p>Joris Steg: &#8222;Es gibt diverse Netzwerke, die Politiker*innen und Besch\u00e4ftigte im \u00f6ffentlichen Dienst, die von Gewalt betroffen sind, unterst\u00fctzen. Neben #sicherimDienst gibt es etwa die <em>starke Stelle<\/em> \u2013 eine bundesweite Ansprechstelle f\u00fcr durch Hass und Gewalt bedrohte kommunale Amts- und Mandatstr\u00e4gerinnen und Mandatstr\u00e4ger, die das Innenministerium gemeinsam mit der Stiftung Deutsches Forum f\u00fcr Kriminalpr\u00e4vention (DFK) eingerichtet hat. Zudem gibt es das Internetportal stark-im-amt.de, das als zentrale Anlaufstelle f\u00fcr kommunale Amts- und Mandatstr\u00e4gerinnen Mandatstr\u00e4ger fungiert, die praktische Hilfe und Unterst\u00fctzung bei der Bew\u00e4ltigung von Beleidigungen, Bedrohungen oder Angriffen ben\u00f6tigen.<\/p>\n<p>Das Portal, auf Initiative der K\u00f6rber-Stiftung in Zusammenarbeit mit dem Deutschen St\u00e4dtetag, dem Deutschen Landkreistag, dem Deutschen St\u00e4dte- und Gemeindebund und unter der Schirmherrschaft des Bundespr\u00e4sidenten entwickelt wurde, unterst\u00fctzt pr\u00e4ventiv und beratend und gibt Handlungsratschl\u00e4ge f\u00fcr Krisensituationen. Alle diese Netzwerke leisten wertvolle Arbeit, sie sind hilfreich und notwendig. Netzwerke dieser Art bieten eine Plattform zum Austausch von Erfahrungen und Erlebnissen sowie zur Diskussion von pr\u00e4ventiven und reaktiven Ma\u00dfnahmen und zum Wissenstransfer.<\/p>\n<div id=\"attachment_82642\" class=\"wp-caption alignnone\" style=\"max-width: 650px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-82642 size-full\" src=\"\/wp-content\/uploads\/2025\/03\/faust-1971727_640.jpg\" alt=\"\" width=\"640\" height=\"425\" \/><span class=\"wp-caption-text\">Amtspersonen und Politikerinne und Politiker sehen sich immer h\u00e4ufiger Gewalt ausgesetzt &#8211; \u00a9 Pixabay<\/span><\/div>\n<p>So kann den von Gewalt betroffenen Menschen geholfen werden, weil sie nicht alleine gelassen, sondern unterst\u00fctzt werden. Zudem kann Institutionen, Organisationen und Arbeitgeber bei der Umsetzung von Unterst\u00fctzungsma\u00dfnahmen geholfen werden. Insgesamt k\u00f6nnen solche Netzwerke dazu beitragen, das Sicherheitsgef\u00fchl und die Sicherheit zu erh\u00f6hen. Allerdings ist es wichtig zu betonen, dass solche Netzwerke allein nicht ausreichen, um umfassende Sicherheit zu gew\u00e4hrleisten und das Problem der Gewalt gegen Politikerinnen und Politiker und Besch\u00e4ftige im \u00f6ffentlichen Dienst in den Griff zu bekommen. Daf\u00fcr ist es auch n\u00f6tig, die tieferliegenden Ursachen der Gewalt gegen Amtsmenschen anzugehen und strafrechtlich konsequent gegen T\u00e4ter vorzugehen.&#8220;<\/p>\n<p><strong>Konzepte zur Gewaltpr\u00e4vention sind alle sch\u00f6n und gut. Aber was kann konkret gegen die zunehmende Gewalt getan werden?<\/strong><\/p>\n<p>Joris Steg: &#8222;Die Verrohung der Gesellschaft und die zunehmende Gewalt gegen Amtsmenschen sind nicht monokausal zu erkl\u00e4ren. Es gibt nicht den einen Grund, das eine Motiv oder den einen Ausl\u00f6ser f\u00fcr die Gewalt. Daher f\u00e4llt die Bek\u00e4mpfung auch so schwer. Es gibt nicht die eine Stellschraube, an der gedreht werden kann, damit die Gewalt gegen Amtsmenschen verschwindet. Um die zunehmende Gewalt bek\u00e4mpfen und eind\u00e4mmen zu k\u00f6nnen, sind in jedem Fall vielf\u00e4ltige pr\u00e4ventive, proaktive und reaktive Ma\u00dfnahmen erforderlich. Hier sind vor allem die Politik und die Strafverfolgungsbeh\u00f6rden aus Polizei und Justiz sowie, da das Internet kein rechtsfreier Raum ist, die Online-Plattformen gefordert.<\/p>\n<p>Aufgabe der Politik ist es, einen klaren (straf-)rechtlichen Rahmen in Bezug auf Gewalt gegen Amtsmenschen vorzugeben und Online-Plattformen wie Facebook oder X wirksam zu regulieren, da Selbstregulierung offensichtlich nicht funktioniert. Polizei und Justiz m\u00fcssen st\u00e4rker und entschiedener gegen T\u00e4ter vorgehen. Es bedarf einer konsequenten Strafverfolgung und der Aussch\u00f6pfung aller zur Verf\u00fcgung stehenden Rechtsmittel, denn viel zu h\u00e4ufig bleiben T\u00e4ter unbekannt und kommen ohne Strafe davon. Eine Versch\u00e4rfung der Strafma\u00dfnahmen ist meiner Meinung nach nicht n\u00f6tig, die bestehenden Rechtsmittel reichen aus, m\u00fcssen aber auch konsequent angewendet werden.<\/p>\n<p>Nur mit Repressionen und strafrechtlichen Ma\u00dfnahmen allein wird die Gewalt aber nicht wirksam zu bek\u00e4mpfen sein. Die Politik muss auch die tieferliegenden gesellschaftlichen Ursachen, die zur Verrohung der Gesellschaft beitragen, angehen, um dem Vertrauens-, Autorit\u00e4ts- und Legitimit\u00e4tsverlust staatlicher Instanzen entgegenzuwirken und das gesellschaftliche Unzufriedenheits- und Frustrationspotenzial einzuhegen. Es sind aber nicht nur Politik und Strafverfolgungsbeh\u00f6rden gefordert. Es ist vielmehr eine gesamtgesellschaftliche Aufgabe, gegen Verrohung, Hass und Gewalt anzugehen und stattdessen f\u00fcr eine offene, demokratische Gesellschaft und ein ziviles Miteinander einzutreten.<\/p>\n<p>Hier ist eine klare und entschiedene Haltung der Zivilgesellschaft n\u00f6tig. Dabei ist es zuallererst entscheidend, dass verbale, psychische und physische Gewalt gegen Politikerinnen, Politiker und Besch\u00e4ftigte im \u00f6ffentlichen Dienst nicht normalisiert oder bagatellisiert wird. Gew\u00f6hnungseffekte sind gef\u00e4hrlich, Gewalt darf niemals allt\u00e4glicher Bestandteil des \u00f6ffentlichen Lebens werden und auch nicht als solcher angesehen werden. Gewalt gegen \u00f6ffentliche Personenkreise gedeiht und floriert nur in einem gesellschaftlichen Klima, in dem mit Indifferenz, Desinteresse oder gar mit Zustimmung und Unterst\u00fctzung reagiert wird: Viele T\u00e4ter glauben, dass Gewalt ein akzeptables und legitimes Mittel der politischen Auseinandersetzung sei und dass solches Handeln von einer schweigenden Mehrheit gebilligt werde oder gar erw\u00fcnscht sei. Daher braucht es einen klaren gesellschaftlichen Konsens gegen Gewalt. Der Kultur der Gewalt muss mit einer Kultur des Respekts begegnet werden.&#8220;<\/p>\n<p><strong>Welche Folgen haben die Anfeindungen und Gewalt?<\/strong><\/p>\n<p>Joris Steg: Die Gewalt hat immer und zuallererst Folgen und Konsequenzen auf der individuellen Ebene, denn es sind Menschen betroffen von der Gewalt. Dabei zeigt sich auch, dass nicht nur schwerwiegende k\u00f6rperliche Gewalt, sondern auch verbale und psychische Gewalt bereits weitrechende Folgen haben kann. Die Gewalt gegen Amtsmenschen hat aber stets auch Auswirkungen auf die Demokratie als Staats- und Lebensform und auf die liberale Gesellschaft insgesamt. Politikerinnen, Politiker und andere Amts- und Mandatstr\u00e4ger haben eine zentrale Funktion f\u00fcr das Gemeinwesen, die unersetzlich f\u00fcr eine lebendige und funktionierende Demokratie und eine offene Gesellschaft ist.<\/p>\n<p>Wenn Amtsmenschen um Gesundheit und Unversehrtheit, um Leib und Leben f\u00fcrchten m\u00fcssen, ist das nicht nur eine Stilfrage. Vielmehr werden grundlegende Mechanismen der Demokratie angegriffen. Gewalt gegen Amtsmenschen unterminiert die Grundlagen des zivilen Miteinanders, zieht demokratische Procedere in Mitleidenschaft und f\u00fchrt dazu, demokratisches Engagement einzusch\u00fcchtern. Gewalt gegen Amtsmenschen als Gewalt gegen Vertreterinnen und Vertreter sowie Repr\u00e4sentanten des Staates zeugt insofern nicht nur von einer Verachtung f\u00fcr den jeweiligen Menschen, sondern auch und gerade von einer Verachtung f\u00fcr die Demokratie als Staats- und Regierungsform. Gewalttaten gegen Amtsmenschen sind Angriffe auf das Herz, auf das Fundament der Demokratie.&#8220;<\/p>\n<p><strong>Uwe Blass<\/strong><\/p>\n<div id=\"attachment_82646\" class=\"wp-caption alignnone\" style=\"max-width: 210px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-82646 size-full\" src=\"\/wp-content\/uploads\/2025\/03\/Joris_Steg-Presse-Kopie.jpg\" alt=\"\" width=\"200\" height=\"316\" \/><span class=\"wp-caption-text\">Dr. Joris Steg &#8211; \u00a9 privat<\/span><\/div>\n<h4>\u00dcber Dr. Joris Steg<\/h4>\n<p>Dr. Joris Steg ist Wissenschaftlicher Mitarbeiter am Institut f\u00fcr Soziologie der Fakult\u00e4t f\u00fcr Human- und Sozialwissenschaften der Bergischen Universit\u00e4t.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2022 gab es beim Bundesministerium des Inneren und f\u00fcr Heimat eine Studie zur Gewalt gegen Besch\u00e4ftigte des \u00f6ffentlichen Dienstes (die Polizei wurde nicht in die Untersuchungen mit einbezogen) mit dem Ergebnis:\u00a0 Jede und jeder Vierte erlebt Gewalt.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-82635","post","type-post","status-publish","format-standard","hentry","category-wissen"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:36:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/82635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=82635"}],"version-history":[{"count":7,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/82635\/revisions"}],"predecessor-version":[{"id":82648,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/82635\/revisions\/82648"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=82635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=82635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=82635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}