{"id":81977,"date":"2025-02-27T08:44:23","date_gmt":"2025-02-27T07:44:23","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=81977"},"modified":"2025-03-07T09:26:52","modified_gmt":"2025-03-07T08:26:52","slug":"wsv-droht-bedeutungslosigkeit-relaunch-unausweichlich","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2025\/02\/27\/wsv-droht-bedeutungslosigkeit-relaunch-unausweichlich\/","title":{"rendered":"WSV droht Bedeutungslosigkeit &#8211; Relaunch unausweichlich?"},"content":{"rendered":"<div id=\"attachment_81980\" class=\"wp-caption alignnone\" style=\"max-width: 2106px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-81980 size-full\" src=\"\/wp-content\/uploads\/2025\/02\/Norbert-Mueller-3.jpg\" alt=\"\" width=\"2096\" height=\"1371\" \/><span class=\"wp-caption-text\">Ex-WSV-Verwaltungsrat und Buchautor Norbert M\u00fcller an der Wupper &#8211; \u00a9 privat<\/span><\/div>\n<p>Im Raum steht eine siebenstellige Summe, von der nicht klar ist, ob es sich um eine Schenkung oder ein Darlehen handelt. Und die dazu auch noch eine steuerrechtliche Komponente besitzt. Das Dilemma: Eine Opposition ist in diesem Verein scheinbar nicht mehr auszumachen oder hat keine Stimme mehr. Eine der letzten kritischen Stimmen wurde nach eigenen bekunden auf der letzten Mitgliederversammlung f\u00f6rmlich abgekanzelt.<\/p>\n<p>Allein die Erw\u00e4hnung des Namens \u201eNorbert M\u00fcller\u201c l\u00f6st bei den heute Verantwortlichen, vorsichtig ausgedr\u00fcckt, Ablehnung aus.\u00a0Warum? Norbert M\u00fcller selbst lieferte ausf\u00fchrliche Antworten in seinem lesenswerten Buch \u201eKein Rentner-Blues in Wuppertal\u201c. Seine Thesen muss man nicht teilen, man sollte sie aber vielleicht doch einmal einer n\u00e4heren Betrachtung unterziehen.<\/p>\n<p>Wir haben uns mit dem fr\u00fcheren, 2023 zur\u00fcckgetretenen Sprecher des Finanzausschusses des Verwaltungsrates, ausf\u00fchrlich unterhalten. Er ist heute nicht nur Buchautor, sondern auch Dozent in Wirtschafts- und Marketing-Fragen. Vom WSV f\u00fchlt er sich inzwischen ausgegrenzt. \u201eWenn man eine andere Meinung vertritt, und nicht mehr dem \u201aInneren Circle\u2018 angeh\u00f6rt, wird man zum Unber\u00fchrbaren und der vermeintliche Freundeskreis reduziert sich erheblich\u201c, dieses schmerzliche Fazit zog er in seinem Buch.<\/p>\n<p><strong>DS: \u201eSie haben dem WSV In ihrem 2024 erschienen zweiten Buch rund 120 Seiten gewidmet. Ihre Begr\u00fcndung: Sie w\u00fcrden den Verein vor Sch\u00e4den bewahren, aber auch Wege aus der vermeintlichen Sackgasse aufzeigen wollen. Gab es da im Hinterkopf auch so ein Motiv\u00a0wie Revanche oder gar Rache?\u201c<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eBei weitem nicht, warum auch und was h\u00e4tte ich davon? H\u00e4tte ich darauf gesonnen, h\u00e4tte ich andere Mittel einsetzen k\u00f6nnen. Oder aber das Kapitel im Buch h\u00e4tte doppelten Umfang erreicht.\u00a0Die Aufgabe eines Verwaltungsrates ist doch einzig, den Verein vor Schaden zu bewahren. Das war und ist mein Antrieb und mein Versprechen gewesen, welches ich den Mitgliedern vor meiner Wahl gegeben habe. Nur daran f\u00fchlte und f\u00fchle ich mich gebunden.\u201c<\/p>\n<p><strong>DS: K\u00f6nnen Sie bitte konkreter werden?<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eNun, gibt es leider eine finanzielle Fehlentwicklung, die die Zukunftsf\u00e4higkeit des Vereins erheblich beeintr\u00e4chtigt. Die Frage wieviel EMKA denn nun noch pro Saison zahlt, ist dagegen fast schon sekund\u00e4r. Es geht um existenzbedrohende bilanzierte Verbindlichkeiten in siebenstelliger Gr\u00f6\u00dfenordnung, deren Akzeptanz einer \u00dcberpr\u00fcfung bedarf. Es kann doch nicht sein, dass dieser Verein st\u00e4ndig die gleichen Fehler wiederholt und dies nur, weil es beim Verwaltungsrat keine Lernkurve gibt.\u201c<\/p>\n<div id=\"attachment_81984\" class=\"wp-caption alignnone\" style=\"max-width: 410px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-81984 size-full\" src=\"\/wp-content\/uploads\/2025\/02\/81HlBVSdeUL._SL1500_-Kopie-1.jpg\" alt=\"\" width=\"400\" height=\"637\" \/><span class=\"wp-caption-text\">&#8222;Kein Rentner-Blues in Wuppertal&#8220; &#8211; Norbert M\u00fcller &#8211; BoD Books on Demand &#8211; 248 Seiten &#8211; ISBN 10: 3769300459 &#8211; ISBN 13: 978-3769300451<\/span><\/div>\n<p><strong>DS: \u201eSie f\u00fchlten sich, wie sie schreiben, als WSV-Organ, zu Traumzielen eingeladen worden zu sein, dem dann Mitten auf dem Atlantik erkl\u00e4rt wurde, sie seien gar nicht eingeladen, sondern dass Geld f\u00fcr die Reise (in diesem Falle f\u00fcr den WSV) w\u00e4re nur vorgeschossen worden. Wo liegen die rechtlichen Aspekte?\u201c<\/strong><\/p>\n<p>M\u00fcller: \u201eIch m\u00f6chte heute keinen Staub mehr aufwirbeln, das l\u00e4ge kaum im Interesse des WSV, dem ich mich bis heute verbunden f\u00fchle und dessen Mitglied ich immer noch bin.\u00a0 Aber ich will doch so viel sagen, dass ich in entscheidenden Momenten von der Mehrheit meiner Verwaltungsrat-Kollegen keine Unterst\u00fctzung hatte, obwohl diesen, wie auch mir, \u201edie Zeichen an der Wand\u201c sichtbar vor Augen standen.\u201c<\/p>\n<p><strong>DS: Welche Motivlage sehen Sie hier?<\/strong><\/p>\n<p>Norbert M\u00fcller: Bei einigen Kollegen ging wohl die Angst um, durch eine eigentlich zwingende Reaktion auf diese sichtbare Fehlentwicklung, ggf. bei einer n\u00e4chsten Wahl abgestraft werden zu k\u00f6nnen, damit also nicht mehr privilegiert zu sein. Nur, dies darf und kann nicht der Leitfaden f\u00fcr die Handlungsweisen eines Aufsichtsorgans sein. Treffend finde ich da die Beschreibung von Rainer Werner Fassbinder, der einem seiner Filme den Titel \u201aAngst essen Seele auf\u2018 gab.\u201c<\/p>\n<p><strong>DS: Was sagen sie zu einer Meinung, Ihnen h\u00e4tte einiges gefehlt, um die Abl\u00e4ufe in einem gro\u00dfen Fu\u00dfballverein beurteilen zu k\u00f6nnen? \u00a0<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eDa kann ich nur schmunzeln. Beruflich war ich als Key-Account-Manager bei einer Investitionsg\u00fcter-Bank f\u00fcr Gro\u00dfkunden zust\u00e4ndig. Ich habe eine betriebswirtschaftliche Ausbildung, unterrichte als Dozent u.a. Rechnungswesen, sowie Marketing und Vertrieb sowie einige rechtliche Themen an einer der gr\u00f6\u00dften Akademien f\u00fcr Erwachsenenbildung. Im Verwaltungsrat war ich wohl nur einer von zwei Kollegen, der mit unserem Finanzvorstand \u00fcberhaupt auf Augenh\u00f6he Bilanz-Kennzahlen diskutieren konnte.\u201c<\/p>\n<p><strong>DS: Und wie sch\u00e4tzen Sie Ihre Fachkenntnisse im modernen Fu\u00dfballgesch\u00e4ft ein?<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eIch r\u00e4ume ein, dass es Leute mit mehr fu\u00dfballerischen Sachkenntnissen gab und auch noch gibt. In dem Bereich w\u00fcrde ich mich nie als Ratgeber sehen. Da habe ich mich immer zur\u00fcckgehalten.\u00a0 Dar\u00fcber hinaus haben mir \u201ain meinem Fachgebiet\u2018 meine vielf\u00e4ltigen Kontakte aber immer geholfen und mich darin best\u00e4tigt, dass der WSV erst einmal ein durchg\u00e4ngiges Marketingkonzept ben\u00f6tigt. So z.B. auch Lars Nierfeld, der beim 1. FC K\u00f6ln \u00fcber viele Jahre als Gesch\u00e4ftsf\u00fchrer Marketing und Vertrieb t\u00e4tig war und in der Branche einen so guten Ruf hatte, dass nicht nur WSV-M\u00e4zen Friedhelm Runge ihn als Berater engagierte und beim WSV einsetzte. Leider hatte Lars Nierfeld nicht die Befugnis, diese notwendigen Reformen umzusetzen. Meine Hoffnung war, ihn fester an den WSV zu binden. Heute ist er Gesch\u00e4ftsf\u00fchrer beim Rheinischen Turnerbund\u201c.<\/p>\n<div id=\"attachment_81985\" class=\"wp-caption alignnone\" style=\"max-width: 510px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-81985 size-full\" src=\"\/wp-content\/uploads\/2025\/02\/Mein-Bild-fuer-Cover.jpg\" alt=\"\" width=\"500\" height=\"668\" \/><span class=\"wp-caption-text\">Ist immer noch Mitglied des WSV: Norbert M\u00fcller &#8211; \u00a9 privat<\/span><\/div>\n<p><strong>DS: Wie sehen sie den WSV heute aufgestellt?<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eSchauen Sie sich die Zuschauerzahlen an, die reichen nicht mehr, die laufenden Kosten eines Spieltages zu decken. Sehen Sie sich die Jahreshauptversammlung an, fr\u00fcher kamen mal Hunderte, heute ist man froh, wenn \u00fcberhaupt noch 140 kommen, um die satzungsm\u00e4\u00dfig geforderte Mehrheit f\u00fcr eine Abstimmung zu erreichen. Das WSV Forum rot-blau.com hatte fr\u00fcher einmal tausende von Nachfragen und Meinungs\u00e4u\u00dferungen, heute kommen sie vielleicht noch auf ein Zehntel. Eine Opposition gib es nicht mehr, oder ist unsichtbar. Daf\u00fcr gibt es jetzt einen vierk\u00f6pfigen Vorstand, wovon einer hauptamtlich t\u00e4tig ist,\u00a0 mit Zust\u00e4ndigkeiten, die sich mir nicht erschlie\u00dfen. So etwas, also einen hauptamtlichen Vorstand zu haben, ist bei einem Regionalliga-Verein eher ungew\u00f6hnlich. Ob sich dies rechnet, kann ich nicht beurteilen, m\u00fcsste man aber an erheblich gestiegenen Sponsoring-Einnahmen erkennen k\u00f6nnen. Sind sie das?<\/p>\n<p><strong>DS: Sie sehen sich auch als Mann des Marketings. Wie sieht ihre Bewertung aus?.<\/strong><\/p>\n<p>M\u00fcller: \u201eDer WSV lebt nur noch von seinem Namen, der \u201aGott sei Dank\u2018 noch einen Wert darstellt. Ich sehe die dringende Notwendigkeit eines Relaunchs, also f\u00fcr ver\u00e4nderte Strukturen. Eine solche Ver\u00e4nderung ist immer n\u00f6tig, wenn sich die aktuelle Positionierung einer Marke nicht mehr im Wettbewerb um Sponsoren behaupten kann. Das st\u00e4ndige Rufen nach Unterst\u00fctzung durch die Bergische Wirtschaft ignoriert die tats\u00e4chlichen Probleme. Einem Unternehmen, das einen WSV unterst\u00fctzen soll, muss ein Gegenwert, oder ein \u00fcberzeugendes Motiv geboten werden. Hier hatten wir damals schon Konzepte entwickelt, die jetzt irgendwo in einer Schublade verstauben. Sinkende Zuschauerzahlen koalieren dann zwangsl\u00e4ufig mit sinkendem Interesse potenzieller Sponsoren. Mir fehlt es auch an einer echten Vision, die \u00fcber das Wohl und Wehe der ersten Fu\u00dfballmannschaft hinausgeht. Tats\u00e4chlich lebt der Verein heute unter Marketinggesichtspunkten nur noch von seinem guten Namen, der im Fu\u00dfball-Deutschland einmal eine Nummer war, aber immer noch einen Erkennungswert hat. Die Zeiten von G\u00fcnter Pr\u00f6pper und Co. geh\u00f6ren ja leider schon lange der Vergangenheit an\u201c.<\/p>\n<p><strong>DS: Reicht da die Neuformulierung einer Vision?<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eEs kann niemanden entgangen sein, dass mehrere Jahre sehr viel Geld, mit dem Ziel Aufstieg 3. Liga,\u00a0 verbrannt worden ist, welches jetzt die Bilanz belastet, ohne das gesteckte Aufstiegsziel zu erreichen. Ich will es auch noch anders sagen, in der Politik spricht man von \u201aehrenhaften\u2019 R\u00fccktritten, wenn einer einsieht, nicht mehr am richtigen Platz zu sein. In der Politik sieht man aber auch, dass man durch den Wechsel im F\u00fchrungspersonal kleine Wunder bewirken kann. Die politische \u201aLinke\u2018 ist ein gutes Beispiel, wo der Austausch ohne Programm\u00e4nderung einen kleinen Erdrutsch ausl\u00f6ste. Man hat bei der \u2019Linken\u2019 gesehen, dass der Ausstieg von Frau Wagenknecht pl\u00f6tzlich dazu gef\u00fchrt hat, andere Kr\u00e4fte freizusetzen. Dort sind zweihundert ausgetreten, aber zwanzigtausend daf\u00fcr eingetreten. Neue, unverbrauchte K\u00f6pfe k\u00f6nnten auch beim WSV Wunder bewirken und die Zukunft wieder positiv gestalten.\u201c<\/p>\n<p><strong>DS: Sehen Sie da geeignete Pers\u00f6nlichkeiten, die eine Bereicherung des\u00a0 Verwaltungsrates sein k\u00f6nnten und haben Sie diesbez\u00fcglich vielleicht sogar selbst Ambitionen?\u00a0<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eIch habe keine Ambitionen und w\u00fcrde ja meine eigenen Tr\u00e4ume sonst ad absurdum f\u00fchren. Ich w\u00fcrde mich allenfalls noch f\u00fcr Beratungsaufgaben einbinden lassen. Schauen Sie sich um, der WSV hat ganz herausragende Pers\u00f6nlichkeiten, die in ihren Verantwortungsbereichen einen super Job machen und diese k\u00f6nnten den ganzen Verein v\u00f6llig neu beleben.\u00a0 Da nenne ich gerne beispielhaft den jungen Leiter des \u201aL\u00f6wenstalles\u2018 Tom Welz oder aber auch die Leiterinnen der Kinder-Turnabteilung Kerstin Mau und Sarina Mantick. Solche Pers\u00f6nlichkeiten braucht der WSV jetzt in seinen Gremien. Welche Geschichte w\u00fcrde der WSV pl\u00f6tzlich erz\u00e4hlen, wenn der Vorstand nun j\u00fcnger und vielleicht sogar auch weiblicher w\u00e4re? \u201c<\/p>\n<p><strong>DS: Was muss sich nach Ihrer Meinung beim WSV noch \u00e4ndern?<\/strong><\/p>\n<p>Norbert M\u00fcller: \u201eEs w\u00fcrde dem Verein schon damit am besten gedient sein, wenn in dem einzigen Kontroll-Organ Verwaltungsrat auch Leute gew\u00e4hlt w\u00fcrden, die nicht nur geschmeidig reden, sondern auch pr\u00e4sent sind und am Ende eine Bilanz lesen k\u00f6nnen. Das ist eigentlich das Mindestr\u00fcstzeug f\u00fcr ein Mitglied eines Aufsichtsorgans. Dann muss man ab und zu auch in die Satzung schauen um zu sehen, welche Pflichten man hat und schon d\u00fcrfte es nie mehr zu einer Schief-Lage kommen. Am 10. April 2025 ist beim WSV im Barmer Bahnhof wieder Jahreshauptversammlung. Da setze ich meine ganze Hoffnung drauf, dass es mit entsprechenden Beschl\u00fcssen beim WSV endlich wieder aufw\u00e4rts geht\u201c.<strong>\u00a0<\/strong><\/p>\n<p><strong>DS: Wir bedanken uns f\u00fcr das offene, interessante Gespr\u00e4ch.<\/strong><\/p>\n<p><strong>Das Interview f\u00fchrte SIEGFRIED J\u00c4HNE <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Buch-Tipp:<\/strong> \u201eKein Rentner-Blues in Wuppertal\u201c in Kommission von Buchhandlung Laurenz und Luise ist dort am Elberfelder Laurentiusplatz zu erhalten.<\/p>\n<p><strong>Leseprobe oder Online bestellbar:<\/strong><\/p>\n<p><a href=\"https:\/\/buchshop.bod.de\/kein-rentner-blues-in-wuppertal-norbert-mueller-9783769300451\">https:\/\/buchshop.bod.de\/kein-rentner-blues-in-wuppertal-norbert-mueller-9783769300451<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum Niedergang des Traditionsvereins WSV tauchen mehr Fragen als Antworten auf. Das einstige Flaggschiff und Aush\u00e4ngeschild des Wuppertaler Sports l\u00e4uft Gefahr, in die v\u00f6llige Bedeutungslosigkeit abzudriften. Besonders auff\u00e4llig ist eine gut gemeinte, aber oft nach innen gerichtete, von au\u00dfen gesehen aber vielfach mangelhafte Kommunikationspolitik.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-81977","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:36:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/81977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=81977"}],"version-history":[{"count":9,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/81977\/revisions"}],"predecessor-version":[{"id":81999,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/81977\/revisions\/81999"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=81977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=81977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=81977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}