{"id":80789,"date":"2025-01-10T17:30:01","date_gmt":"2025-01-10T16:30:01","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=80789"},"modified":"2025-01-10T17:30:01","modified_gmt":"2025-01-10T16:30:01","slug":"bergische-uni-50-hochschulen-abschied-von-plattform-x","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2025\/01\/10\/bergische-uni-50-hochschulen-abschied-von-plattform-x\/","title":{"rendered":"Bergische Uni &#038; 50 Hochschulen: Abschied von Plattform X"},"content":{"rendered":"<div id=\"attachment_80791\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-80791\" src=\"\/wp-content\/uploads\/2025\/01\/Ait-Djoudi__privat-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1789\" \/><span class=\"wp-caption-text\">Jasmine Ait-Djoudi, Leiterin der Universit\u00e4tskommunikation &#8211; \u00a9 Foto privat<\/span><\/div>\n<p>Ver\u00e4nderte Algorithmen und eine dadurch bedingte geringe Reichweite haben X unattraktiv f\u00fcr die Verbreitung und den Austausch wissenschaftsbasierter Informationen gemacht, da zentrale Zielgruppen kaum noch erreicht werden.<\/p>\n<p>Jasmine Ait-Djoudi, Leiterin der Universit\u00e4tskommunikation der Bergischen Universit\u00e4t erl\u00e4utert: \u201eF\u00fcr uns sind soziale Medien ein zentraler Baustein, um unsere Forschungserkenntnisse mit der Gesellschaft zu teilen und zur Diskussion zu stellen. Auf X keine relevante Reichweite mehr zu erzielen, uns stattdessen inmitten bezahlter und oft tendenzi\u00f6ser Inhalte wiederzufinden, bietet f\u00fcr uns als Universit\u00e4t keine Perspektive.\u201c Das bedeute auch, Ressourcen an sinnvoller Stelle einsetzen zu k\u00f6nnen, so die Kommunikationsexpertin.<\/p>\n<h4>Alternativen im Blick<\/h4>\n<p>Nat\u00fcrlich setzt die Wissenschaftscommunity weiterhin auf Dialog und Transparenz mit der \u00d6ffentlichkeit. Die Wuppertaler Universit\u00e4t \u2013 ebenso wie viele der ausgetretenen Institutionen \u2013 plant ihre Aktivit\u00e4ten auf andere Plattformen zu verlagern.<\/p>\n<p>F\u00fcr Wuppertal gilt: Neben Instagram, Facebook und LinkedIn, auf denen insgesamt derzeit rund 80.000 Menschen der Bergischen Universit\u00e4t folgen, werden in Zukunft weitere, ebenfalls bekannte Kan\u00e4le wie Mastodon und Bluesky das Social Media-Portfolio vervollst\u00e4ndigen.<\/p>\n<p>Um X weiterhin beobachten zu k\u00f6nnen, bleibt der Account im \u201eeingefrorenen\u201c Zustand bestehen \u2013 ohne aktive Inhalte, jedoch weiterhin sichtbar, nicht zuletzt, um eventuellen Missbrauch des Accountnamens durch Dritte zu vermeiden.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcber 50 deutschsprachige Hochschulen und Forschungsinstitutionen haben am heutigen Freitag (10.01.) \u00a0ihre Aktivit\u00e4ten auf der Social-Media-Plattform X (ehemals Twitter) eingestellt. Darunter auch die Bergische Universit\u00e4t Wuppertal. Sie verstehen diese Ma\u00dfnahme das als \u00a0weitreichendes Signal f\u00fcr die St\u00e4rkung von Demokratie und Wissenschaft.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-80789","post","type-post","status-publish","format-standard","hentry","category-wissen"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:36:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/80789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=80789"}],"version-history":[{"count":2,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/80789\/revisions"}],"predecessor-version":[{"id":80792,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/80789\/revisions\/80792"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=80789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=80789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=80789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}