{"id":79881,"date":"2024-11-17T13:41:49","date_gmt":"2024-11-17T12:41:49","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=79881"},"modified":"2024-11-28T10:05:31","modified_gmt":"2024-11-28T09:05:31","slug":"wsv-meldet-sich-mit-starker-leistung-eindrucksvoll-zurueck","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/11\/17\/wsv-meldet-sich-mit-starker-leistung-eindrucksvoll-zurueck\/","title":{"rendered":"WSV meldet sich mit starker Leistung eindrucksvoll zur\u00fcck"},"content":{"rendered":"<div id=\"attachment_34347\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34347 size-full\" src=\"\/wp-content\/uploads\/2021\/03\/classen-2020-Mar-20-0201-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" \/><span class=\"wp-caption-text\">Zeigten beide ein starkes Spiel in Lotte: Kevin Hagemann (l.) und Semir Saric, Sch\u00fctze des Goldenen Tores &#8211; \u00a9 Archivfoto Jochen Classen<\/span><\/div>\n<p>Keine Frage, f\u00fcr den Wuppertaler Traditionsverein hat angesichts des zuletzt anhaltenden Misserfolges l\u00e4ngst auch der finanzielle \u00dcberlebenskampf begonnen. Der sportlichen Leiter des Regionalligisten, Gaetano Manno, brachte es auf den Punkt. Es gehe inzwischen nicht nur darum, ein bisschen Fu\u00dfball zu spielen, sondern es gehe auch um den Verein, die Fans und um die Arbeitspl\u00e4tze.<\/p>\n<p>Er hatte noch vor dem Spiel bemerkt: \u201eBei unserer Mannschaft stimmt etwas nicht, ich vermisse die Spielfreude.\u201c Diesmal durfte er indessen zufrieden sein: \u201eDie 18 Spieler, die die heute dabei waren, haben verstanden, um was es geht, sie haben gek\u00e4mpft, sind gerannt und Siegeswillen gezeigt. Das ist es, was wir alle sehen wollen!\u201c<\/p>\n<h4>Erfolgreich gegen das torreichste Team<\/h4>\n<p>Aber auch dem neuen Trainer Sebastian Tyrala sind nach seinen letzten beiden Niederlagen Steine vom Herzen gefallen. \u201eDer Sieg ist unfassbar wichtig, heute haben die Jungs bis zur letzten Minute gek\u00e4mpft!\u201c Tyrala hatte der Mannschaft Qualit\u00e4t bescheinigt, den Sieg schon im Vorfeld trotz zahlreicher Ausf\u00e4llen vorausgesagt und damit letztlich auch an Glaubw\u00fcrdigkeit gewonnen, nachdem er mit den Prognosen in seinen ersten beiden Spielen gegen die Spitzenteams MSV Duisburg noch knapp (1:2), aber in Oberhausen (0:3) beim Pokal klar daneben lag.<\/p>\n<p>Seine Mannschaftsaufstellung und seine Taktik haben sich diesmal in G\u00e4nze als richtig erwiesen. Es galt die Ausf\u00e4lle von Levin M\u00fcller, Vincent Gembalies, Pedro Cejas und Timo Bornemann (alle verletzt) zu kompensieren und im \u201eStadion am Lotter Kreuz\u201c im Tecklenburger Land vor allem die bis dahin mit 35 Toren erfolgreichste Sturmreihe der Liga mit einer defensiven Einstellung zu stoppen.<\/p>\n<div id=\"attachment_79831\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79831 size-full\" src=\"\/wp-content\/uploads\/2024\/11\/Wozniak-Krystian-JC-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1617\" \/><span class=\"wp-caption-text\">War auch in Lotte ein sicherer R\u00fcckhalt seiner Mannschaft: WSV-Torh\u00fcter Krystian Wozniak &#8211; \u00a9 Archvifoto Jochen Classen<\/span><\/div>\n<p>Deshalb geh\u00f6rte Tyralas erstes Augenmerk der Stabilit\u00e4t seiner Abwehr, in der Torwart Kristian Wozniak sowie Dams und Wimmer im Zentrum sowie Nashimura und Demir auf den Fl\u00fcgeln die Defensiv-Aufgaben bekamen. Nach den Ausf\u00e4llen der St\u00fcrmer Bornemann, Cejas und Atmaca waren hier die Mittelfeld-Akteure jetzt auch in der Offensive gefordert. Insbesondere Niek Munsters, der in der Spitze von Hagemann und Saric zu unterst\u00fctzen war, sollten es bringen<\/p>\n<p>Das Duell auf zunehmend holprigen Rasen war dann nicht immer hochklassig, aber trotzdem zu jedem Zeitpunkt spannend. Lotte verpasste zu Beginn den m\u00f6glichen F\u00fchrungstreffer. Der WSV blieb zwar zun\u00e4chst ohne echten Abschluss, wirkte aber dennoch bei Gegenst\u00f6\u00dfen immer wieder gef\u00e4hrlich. So verfehlte Defensivmann Niklas Dams in Minute 25. das Tor nur knapp.<\/p>\n<p>Die SF Lotte bem\u00fchten sich zwar weiter, brachte den WSV aber nur selten in ernsthafte Bedr\u00e4ngnis. Trotz einer Vielzahl an Strafraum-Szenen sowie h\u00e4ufigen Sturml\u00e4ufen, fehlten dem Tabellendritten gegen die stabile WSV-Abwehr bis zum Schluss die n\u00f6tige Durchschlagskraft.<\/p>\n<p>So setzten der fortan deutlich gef\u00e4hrlichere Gast aus dem Bergischen Land den entscheidende Treffer. Semir Saric war es in der 51. Spielminute vorbehalten, das Siegtor zu erzielen. Eine Flanke von Subar Nishimura hatte Dilhan Demir verwertet, sein Schuss konnte von Lottes Keeper Beckemeyer noch abgewehrt werden, doch der 27j\u00e4hrige Saric war zur Stelle und schoss aus kurzer Distanz unhaltbar ein.<\/p>\n<h4>Auch ein 3:0 w\u00e4re m\u00f6glich gewesen<\/h4>\n<p>Danach hatte Kevin Hagemann in der 72. sogar noch das 2:0 auf den F\u00fcssen, scheiterte aus guter Position erneut an dem stark reagierenden Beckemeyer. Die G\u00e4ste aus dem Bergischen waren nun eindeutig das gef\u00e4hrlichere Team. Als Elezi den Ball unweit des eigenen Sechzehners ungl\u00fccklich an Saric verlor, bediente Riccardo Grym den herausragenden Hagemann einmal mehr, der scheiterte allerdings an dem wieder hellwachen Beckemeyer. Nicht besser erging es Dilhan Demir, dessen Ball von Felix Mensings Bein (72.) abgelenkt wurde.<\/p>\n<p>In der Schlussphase brachten die Gastgeber noch einmal alles nach vorne, doch der WSV warf sich in jeden einzelnen Schuss. Die mitgereisten treuen WSV-Fans hatten ihr Team w\u00e4hrend der gesamten Spielzeit lautstark unterst\u00fctzt und nun allen Grund, den Erfolg zu feiern. Dies best\u00e4tigt auch Lottes junger Trainer Fabian L\u00fcsters (33), der von einem verdienten Wuppertaler Sieg sprach.<\/p>\n<h4>Trainingslager oder Verst\u00e4rkung?<\/h4>\n<p>Mit nunmehr 18 Punkten belegte der Wuppertaler SV jetzt den 13. Tabellenplatz. Drei Punkte vom ersten Abstiegsrang entfernt.<\/p>\n<p>Nach dem Spiel ist vor dem Spiel hei\u00dft es nicht ohne Grund. Beim WSV hat man jetzt zun\u00e4chst die beiden Spiele bis zum Jahresende im Auge. Es folgen noch die ganz wichtige Heimspiele auf dem gepflegten Rasen im Stadion am Zoo: m 30. November gegen G\u00fctersloh und am 07. Dezember gegen T\u00fcrkspor, dem ehemaligen Club von Trainer Tyrala.<\/p>\n<div id=\"attachment_79885\" class=\"wp-caption alignnone\" style=\"max-width: 2210px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-79885\" src=\"\/wp-content\/uploads\/2024\/11\/Classen-10-11-2024-086-1-1.jpg\" alt=\"\" width=\"2200\" height=\"1467\" \/><span class=\"wp-caption-text\">Lagen diesmal mit ihrer Taktik genau richtig: WSV-Trainer Sebastian Tyrala (l.) mit den Co-Trainern Fohs und Lachheb &#8211; \u00a9 Archivfoto Jochen Classen<\/span><\/div>\n<p>\u201eDa werden wir noch einmal alles geben. Wir wollen Weihnachten unbedingt \u00fcber dem Strich und nicht auf einem Abstiegsplatz stehen\u201c, sagte WSV-Sport-Chef Gaetano Manno. Nach dem letzten Spiel des Jahres werden Trainer und Sportdirektor sich zusammensetzen und eine Bilanz ziehen. Jeder Spieler habe bis dahin die Chance, sich noch zu beweisen. Manno: \u201eDie 18 heute haben das sehr gut gemacht. Darauf k\u00f6nnen wir auf jeden Fall aufbauen\u201c. Dann erg\u00e4nzte er vielsagend: \u201eManchmal ist auch weniger mehr\u201c.<\/p>\n<p>Ideal w\u00e4re es, k\u00f6nnte der Trainer sein Team in der Winterpause eine Woche lang beisammen haben. H\u00e4tte der Trainer jedoch die Wahl zwischen Trainingslager und eine Verst\u00e4rkung des Teams, w\u00fcrde er sich f\u00fcr eine Verst\u00e4rkung entscheiden und in Wuppertaler Umfeld bleiben. Man arbeite an einer L\u00f6sung und suche noch Sponsoren, ist zu h\u00f6ren.<\/p>\n<p><strong>Text: Siegfried J\u00e4hne<\/strong><\/p>\n<h4>Sportfreunde Lotte &#8211; Wuppertaler SV 0:1 (0:0)<\/h4>\n<p><b>Aufstellung Sportfreunde Lotte:<\/b><\/p>\n<p>Beckemeyer \u2013 Brodersen (69. Determann), Mensah, Sabah, Thaqi, Nyuydine (69. Fontein) \u2013 Elezi, Krasniqi (69. Mensing) \u2013 Thier, Heider (78. Wendt), Demaj &#8211; Trainer: Fabian L\u00fcsters<\/p>\n<p><b>Aufstellung Wuppertaler SV:<\/b><\/p>\n<p>Wozniak \u2013 Nishimura, Wimmer, Dams, Demir \u2013 Bilogrevic (90.+ 3 Bielitza), J. Munsters, Grym (79. Dal) \u2013 Saric (74. Reck), N. Munsters (79. Ametov), Hagemann (90.+ 3 Qashi) &#8211; Trainer: Sebastian Tyrala<\/p>\n<p><b>Schiedsrichter:<\/b> Tobias Esch<\/p>\n<p><b>Tor:<\/b> 0:1 Saric (51.)<\/p>\n<p><b>Gelbe Karten:<\/b> Krasniqi (48.) \/ Saric (28.), Nishimura (58.), Grym (62.), Hagemann (77.)<\/p>\n<p><b>Zuschauer:<\/b> 1.062<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es ist ein erstes Lebenszeichen im Kampf ums \u00dcberleben. Mit einem 0:1 (0:0) Ausw\u00e4rtssieg bei den hoch favorisierten und titelambitionierten Sportfreunden Lotte meldet sich der abstiegsgef\u00e4hrdete WSV mit einer starken Leistung eindrucksvoll zur\u00fcck. Der Motor ist wieder angesprungen. F\u00fcr Trainer Sebastian Tyrala war es der erste Sieg in seinem dritten Spiel, f\u00fcr den WSV der erste sportliche Erfolg seit Mitte September.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-79881","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:59:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=79881"}],"version-history":[{"count":8,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79881\/revisions"}],"predecessor-version":[{"id":79891,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79881\/revisions\/79891"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=79881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=79881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=79881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}