{"id":79213,"date":"2024-11-01T08:45:01","date_gmt":"2024-11-01T07:45:01","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=79213"},"modified":"2024-11-01T08:45:01","modified_gmt":"2024-11-01T07:45:01","slug":"bayer-startfestival-mit-vielen-kuenstlerischen-highlights","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/11\/01\/bayer-startfestival-mit-vielen-kuenstlerischen-highlights\/","title":{"rendered":"Bayer: &#8217;stARTfestival&#8216; mit vielen k\u00fcnstlerischen Highlights"},"content":{"rendered":"<div id=\"attachment_79218\" class=\"wp-caption alignnone\" style=\"max-width: 1836px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79218 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/Iris-Berben-Laurence-Chaperson.jpg\" alt=\"\" width=\"1826\" height=\"1200\" \/><span class=\"wp-caption-text\">Die begnadete Schauspielerin Iris Berben liest die Briefe von Sasha Marianna Salzmann &#8211; \u00a9 Laurence Chaperson<\/span><\/div>\n<p>Die Musik von Komponisten wie Dmitri Schostakowitsch, Arvo P\u00e4rt und Maurice Ravel steht im Mittelunkt &#8211; mit Musiktheater, Tanz, Kabarett oder Oratorium.<\/p>\n<p>\u201eKunst kann den Menschen inspirieren, zum Nachdenken anregen und im besten Fall gl\u00fccklich machen. All das wollen wir unserem Publikum bieten,\u201d sagt Festivalleiter Christoph B\u00f6hmke. \u201eWir bringen K\u00fcnstlerpers\u00f6nlichkeiten aus aller Welt an unsere Festivalstandorte und laden auch dieses Mal Mitglieder der stARTacademy ein, wenig geh\u00f6rte Kompositionen exklusiv f\u00fcr das Festival einzustudieren, wie im kommenden Jahr in Darmstadt.\u201d<\/p>\n<h4>Das sind die Highlights<\/h4>\n<p>Die neue Festivalsaison beginnt mit dem kostenfreien Er\u00f6ffnungsfest \u201eKaribische Nacht\u201c im Leverkusener Erholungshaus am 26. April 2025. Mit ihrer musikalischen Melange aus lateinamerikanischen Rhythmen und Pop wollen die Band Palito Ach\u00e9 und die Bayer Big Band nicht nur Partystimmung verbreiten, sondern zugleich Lebensfreude und Leichtigkeit vermitteln.<\/p>\n<p>Violinist Augustin Hadelich kommt mit der Academy of St. Martin in the Fields nach Leverkusen. Im Gep\u00e4ck: Meisterwerke von Mozart, Tschaikowsky und Schostakowitsch. Dafn\u00e9 Kritharas und Band spannen den musikalischen Bogen zwischen Griechenland und dem Balkan mit melodischen Eigenkompositionen, die zum Tr\u00e4umen einladen.<\/p>\n<div id=\"attachment_79222\" class=\"wp-caption alignnone\" style=\"max-width: 2314px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79222 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/Dafne-Krithares-Cloe-Krithares-Devienne.jpg\" alt=\"\" width=\"2304\" height=\"1535\" \/><span class=\"wp-caption-text\">Dafne Kritharas und Band spannen einen musikalischen Bogen zwischen Griechenland und dem Balkan &#8211; \u00a9 Chloe Kritharas Devienne<\/span><\/div>\n<p>Der Superstar an der New Yorker MET und Opernintendant der Philadelphia Opera Anthony Roth Costanzo kehrt nach seinem umjubelten Deb\u00fct in Leverkusen zur\u00fcck zum stARTfestival. Mit einer carte blanche wird er das Publikum mit einem kreativen Mash-up aus Countertenor-Klassik und Falsett-Pop in den Bann ziehen. l\u2019arte del mondo, orchestra in residence von Bayer Kultur, bringt Tschaikowskis Ballettklassiker \u201eSchwanensee\u201c mit einem Jahrtausende alten indischen Tempeltanz in Leverkusen zusammen.<\/p>\n<p>Zum ersten Mal in seiner viele Jahrzehnte andauernden Karriere kommt \u201eKlavierunterhalter\u201d Robert Kreis auf Einladung des stARTfestivals nach Weimar, um legend\u00e4re, fast vergessene K\u00fcnstlerinnen und K\u00fcnstler der Weimarer Zeit zu ehren.<\/p>\n<h4>Kunst als Fundament einer vielf\u00e4ltigen Gesellschaft<\/h4>\n<p>\u201eIn einer Zeit, in der Festivals unter kommerziellen Druck geraten und sich immer mehr dem Mainstream zuwenden, schafft Bayer Kultur mit seinem Engagement Freir\u00e4ume,\u201c sagt Thomas Helfrich, Leiter von Bayer Kultur.<\/p>\n<div id=\"attachment_79224\" class=\"wp-caption alignnone\" style=\"max-width: 561px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79224\" src=\"\/wp-content\/uploads\/2024\/10\/Anush-Hovhannisyan-Bayer-AG.jpg\" alt=\"\" width=\"551\" height=\"826\" \/><span class=\"wp-caption-text\">Die weltweit erfolgreiche Operns\u00e4ngerin Anush Hovhannisyan &#8211; \u00a9 BAYER AG<\/span><\/div>\n<p><span style=\"font-size: 16px;\">\u201eIn diesen k\u00f6nnen sich K\u00fcnstlerinnen und K\u00fcnstler sowie das Publikum wenig geh\u00f6rten Kompositionen zuwenden, zeitgen\u00f6ssischen Fragestellungen k\u00fcnstlerisch widmen und Choreografien erleben, die anregen und erheitern sollen. Dabei ist Kunst f\u00fcr uns weit mehr als nur gute Unterhaltung: sie bereichert unser Leben, erweitert Horizonte und inspiriert zu Innovation. Sie ist, wie Sasha Marianna Salzmann sagt: der Beweis daf\u00fcr, dass wir (Menschen) sind,\u201c so Helfrich weiter.<\/span><\/p>\n<h4>Jahr der Jubil\u00e4en<\/h4>\n<p>Briefe von Sasha Marianna Salzmann werden beim Konzert mit den Bayer-Philharmonikern von der gro\u00dfartigen Schauspielerin Iris Berben gelesen. Sie schl\u00e4gt damit einen Bogen zum Liederzyklus \u201eAus j\u00fcdischer Volkspoesie\u201c von Dmitri Schostakowitsch. J\u00fcdisches Leben einst und heute.<\/p>\n<p>Neben der Academy of St. Martin in the Fields komplettieren das vision string quartet mit Schostakowitschs ber\u00fchmtem Streichquartett Nr. 8, sowie Alexander Krichel, Tobias Feldmann, Benedict Kloeckner und Anush Hovhannisyan mit seiner \u201eRomanzen-Suite\u201c den Schostakowitsch Schwerpunkt.<\/p>\n<div id=\"attachment_79219\" class=\"wp-caption alignnone\" style=\"max-width: 561px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79219\" src=\"\/wp-content\/uploads\/2024\/10\/Horiwitz-Jim-Rakete.jpg\" alt=\"\" width=\"551\" height=\"735\" \/><span class=\"wp-caption-text\">Schauspieler Dominique Horwitz geht mit dem Publikum auf eine poetischen Reise in die Welt des Komponisten Maurice Ravel &#8211; \u00a9 Jim Rakete<\/span><\/div>\n<p>Der tiefreligi\u00f6se estnische Komponist Arvo P\u00e4rt wird aus Anlass seines anstehenden 90. Geburtstags mit einem Abend in Dormagen geehrt, in dessen Mittelpunkt sein zentrales Werk \u201eStabat Mater\u201c steht, aufgef\u00fchrt vom Estnischen Philharmonischen Kammerchor unter der Leitung des Gr\u00fcnders T\u00f5nu Kaljuste und dem Concerto Copenhagen.<\/p>\n<p>Zum 150. Geburtstag von Maurice Ravel l\u00e4dt Schauspieler Dominique Horwitz zu einer poetischen Reise in die Welt des faszinierenden Komponisten ein \u2013 ein genre\u00fcbergreifendes Konzerterlebnis der au\u00dfergew\u00f6hnlichen Art in Leverkusen mit dem Aris Quartett, der Pianistin Ulrike Payer und Sopranistin Christiane Karg.<\/p>\n<h4>B\u00fchne frei f\u00fcr stARTacademy-Talente<\/h4>\n<p>F\u00fcr sein Programm \u201eThe Human Voice\u201c hat sich der vielfach ausgezeichnete Pianist Giorgi Gigashvili mit der jungen S\u00e4ngerin Kato Kvaratskhelia zusammengetan. Gemeinsam haben sie ein Programm f\u00fcr das Weimarer Publikum zusammengestellt, das von der Liebe zu ihrer georgischen Heimat gepr\u00e4gt ist.<\/p>\n<p>Bei seinem Begr\u00fc\u00dfungskonzert in Wuppertal im Mai tritt das j\u00fcngste stARTacademy-Mitglied, der brasilianische Geiger Guido Sant&#8217;Anna, gemeinsam mit einem Jugendensemble aus seiner Heimat an \u2013 Virtuosit\u00e4t trifft Spielfreude!<\/p>\n<div id=\"attachment_79216\" class=\"wp-caption alignnone\" style=\"max-width: 561px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79216\" src=\"\/wp-content\/uploads\/2024\/10\/Jashua-Williams-Joshua-Williams.jpg\" alt=\"\" width=\"551\" height=\"871\" \/><span class=\"wp-caption-text\">Joshua Williams gibt ein Tuba-Konzert in der Historischen Stadthalle Wuppertal &#8211; \u00a9 Joshua Williams<\/span><\/div>\n<p>Im zweiten Jahr seiner F\u00f6rderung pr\u00e4sentiert sich der aus den USA stammende Tubist Joshua Williams, ebenfalls in Wuppertal, als Solist mit einem eindrucksvollen Tuba-Konzert. Das herausragende Symfonieorkest Vlaanderen unter der Leitung von Stardirigentin Kristiina Poska begleitet ihn exklusiv.<\/p>\n<h4>Moderner Tanz<\/h4>\n<p>Zwei Abende widmen sich dem modernen Tanz. Philippe Kratz, geb\u00fcrtiger Leverkusener, einst als T\u00e4nzer der stARTacademy gef\u00f6rdert, kehrt erneut als Choreograf mit der Preziose \u201eUnfolding\u201c zur\u00fcck \u2013 Teil eines Doppelpacks mit dem Ensemble tanzmainz, in dem auch das St\u00fcck \u201ePromise\u201c der Choreografin Sharon Eyal aufgef\u00fchrt wird.<\/p>\n<p>Die Choreografin und \u201eProphetin des befreiten K\u00f6rpers\u201c Silvia Gribaudi hinterfragt in ihrem St\u00fcck \u201eGraces\u201c mit leidenschaftlichem Humor, Charme und Einf\u00fchlungsverm\u00f6gen herk\u00f6mmliche Vorstellungen von menschlicher (Un-) Vollkommenheit.<\/p>\n<div id=\"attachment_79225\" class=\"wp-caption alignnone\" style=\"max-width: 2133px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79225 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/Graces-Fabio-Sau.jpg\" alt=\"\" width=\"2123\" height=\"1417\" \/><span class=\"wp-caption-text\">Das Ensemble des St\u00fcckes &#8222;Graces&#8220; der Choreografin Silvia Gribaudi &#8211; \u00a9 Fabio Sau<\/span><\/div>\n<h4>Die Hamburger Staatsoper zu Gast<\/h4>\n<p>Die multimediale Umsetzung von Grigori Frids Oper \u201eDas Tagebuch der Anne Frank\u201c als Graphic Opera in Leverkusen sp\u00fcrt der Geschichte von Anne Frank im ihrem niederl\u00e4ndischen Exil nach. Die begleitende Wanderausstellung \u201cDeine Anne. Ein M\u00e4dchen schreibt Geschichte\u201d des Anne Frank Zentrums dokumentiert das Leben der Autorin, die durch die Ver\u00f6ffentlichung ihres Tagebuchs zum Symbol f\u00fcr Millionen von J\u00fcdinnen und Juden geworden ist, die der rassistischen Vernichtungspolitik der Nationalsozialisten zum Opfer fielen.<\/p>\n<p>Die Ausstellung findet in Kooperation von Bayer Kultur mit der Hans und Berthold Finkelstein Stiftung statt. Kostenfreie Besuche f\u00fcr Schulen erm\u00f6glicht das Die Choreografin und \u201eProphetin des befreiten K\u00f6rpers\u201c Silvia Gribaudi hinterfragt in ihrem St\u00fcck \u201eGraces\u201c, neben dem Besuch der Oper \u201eDas Tagebuch der Anne Frank\u201c und der dazugeh\u00f6rigen Ausstellung, auch f\u00fcr Konzerte mit dem Ensemble Farbton (Grundschulen) und f\u00fcr die Werkstatt-Konzerte mit Olivia Trummer und Leonie Klein (Mittel- und Oberstufe).<\/p>\n<div id=\"attachment_79226\" class=\"wp-caption alignnone\" style=\"max-width: 560px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79226\" src=\"\/wp-content\/uploads\/2024\/10\/Christoph-Boehmke-Chris-Rausch.jpg\" alt=\"\" width=\"550\" height=\"825\" \/><span class=\"wp-caption-text\">Christoph Boehmke, k\u00fcnstlerischer Leiter des stARTfestival &#8211;\u00a0\u00a9 Chris Rausch<\/span><\/div>\n<p>Ein Wiedersehen wird es mit Marc Schw\u00e4mmleins bereits 2022 vom Publikum gefeierter Inszenierung von Felix Mendelssohn Bartholdys \u201eEin Sommernachtstraum\u201c geben \u2013 ein buntes Spektakel f\u00fcr die ganze Familie im Leverkusener Erholungshaus.<\/p>\n<h4>Die Spielst\u00e4tten<\/h4>\n<p>Neben dem Erholungshaus, der Heimspielst\u00e4tte von Bayer Kultur, und dem Scala-Club in Leverkusen ist als traditioneller Spielort die Historische Stadthalle in Wuppertal dabei.<\/p>\n<p>Neu hinzu kommen das historische Kloster Knechtsteden westlich von Dormagen und die Friedenskirche in Monheim, eine Ikone des Brutalismus. Zum zweiten Mal gastiert das stARTfestival am Bayer-Standort Weimar \u2013 und das mit gleich zwei Konzerten: im Bauhaus-Museum und im Studienzentrum der Herzogin Anna Amalia Bibliothek. Eine Premiere gibt es am Bayer-Standort Darmstadt am quirligen studentischen Kulturort 806qm.<\/p>\n<h4>Tickets und Erm\u00e4\u00dfigungen<\/h4>\n<p>Tickets sowie den Festivalpass, der den Besuch aller Veranstaltungen erm\u00f6glicht, gibt es online \u00fcber www.startfestival.de sowie an allen bekannten Vorverkaufsstellen von k\u00f6lnticket und Eventim. Kontakt f\u00fcr die kostenlose Teilnahme von Kinderg\u00e4rten und Schulen an den fr\u00fchstART-Veranstaltungen: <a href=\"mailto:christoph.boehmke@bayer.com\">christoph.boehmke@bayer.com<\/a>.<\/p>\n<p>Kulturgenuss zum Freundschaftspreis erm\u00f6glicht der \u201eKultur-Buddy\u201c: Bis zum 24. Dezember 2024, 15 Uhr, k\u00f6nnen Kulturbegeisterte online zwei Tickets zum Preis von einem erwerben. Beim Er\u00f6ffnungsfest sind im Leverkusener Erholungshaus zudem Tickets f\u00fcr alle Konzerte an der Abendkasse inklusive Rabatt erh\u00e4lt.<\/p>\n<p><strong>Link zur Webseite der Festival-Webseite:<\/strong><\/p>\n<p><a href=\"http:\/\/www.startfestival.de\">http:\/\/www.startfestival.de<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcnstlerische Highlights im Akkord! Vom 26. April bis zum 29. Juni 2025 l\u00e4dt Bayer Kultur zum neuen stARTfestival ein, das f\u00fcr k\u00fcnstlerische Vielfalt steht. Auf der B\u00fchne stehen Stars der Klassik-Branche, junge Talente, etablierte Kompanien und Ensembles.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-79213","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:58:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=79213"}],"version-history":[{"count":7,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79213\/revisions"}],"predecessor-version":[{"id":79227,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79213\/revisions\/79227"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=79213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=79213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=79213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}