{"id":79128,"date":"2024-10-28T12:20:21","date_gmt":"2024-10-28T11:20:21","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=79128"},"modified":"2024-12-03T18:34:06","modified_gmt":"2024-12-03T17:34:06","slug":"leverkusens-meistermacher-kommt-zum-circular-valley-forum","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/10\/28\/leverkusens-meistermacher-kommt-zum-circular-valley-forum\/","title":{"rendered":"Leverkusens Meistermacher kommt zum Circular Valley Forum"},"content":{"rendered":"<div id=\"attachment_79129\" class=\"wp-caption alignnone\" style=\"max-width: 1199px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-79129 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/Fernando-Carro-Bayer-Leverkusen-Kopie.jpg\" alt=\"\" width=\"1189\" height=\"985\" \/><span class=\"wp-caption-text\">Fernando Carro, CEO des Deutschen Fu\u00dfballmeisters Bayer 04 Leverkusen &#8211; \u00a9 Bayer Leverkusen<\/span><\/div>\n<p class=\"text-build-content\">Es gab in der vergangenen Fu\u00dfball-Saison immer wieder den Moment, in dem Bayer 04 Leverkusen eine Niederlage oder ein ungl\u00fcckliches Unentschieden drohte. Und es gab ebenso oft den Moment, in dem die Mannschaft von Trainer Xabi Alonso sich zusammen gegen diesen Verlauf stemmte und in den letzten Minuten einer Partie oder in der Nachspielzeit doch noch ein Tor schoss.<\/p>\n<p class=\"text-build-content\">So wurde Bayer 04 zum ersten Verein seit mehr als einem Jahrzehnt, der es schaffte, Bayern M\u00fcnchen hinter sich zu lassen, Deutscher Meister und Deutscher Pokalsieger zu werden. Dies gelang nicht durch den Kauf teurer Spieler, sondern durch die richtige Zusammenstellung der Mannschaft \u2013 auf und neben dem Platz.<\/p>\n<p class=\"text-build-content\">Wie man die Organisation rund um das sportliche Team kreiert, wird der CEO des Bundesligisten, Fernando Carro, am 15. November beim Circular Valley Forum in der Historischen Stadthalle Wuppertal erkl\u00e4ren. Der spanische Manager h\u00e4lt einen der zentralen Vortr\u00e4ge des gro\u00dfen Treffens der Kreislaufwirtschaft. Er tr\u00e4gt den Titel \u201eMeistermacher Carro &#8211; Erfolgsfaktoren aus der Sicht eines Quereinsteigers\u201c.<\/p>\n<div id=\"attachment_78295\" class=\"wp-caption alignnone\" style=\"max-width: 2410px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-78295\" src=\"\/wp-content\/uploads\/2024\/09\/Steffi-Lemke-BMUV-Klaus-Mellenthin.jpg\" alt=\"\" width=\"2400\" height=\"1601\" \/><span class=\"wp-caption-text\">Bundesumweltministerin Steffi Lembke nimmt am Circular Valley Forum teil &#8211; \u00a9 BMUV\/Klaus Mellenthin<\/span><\/div>\n<p class=\"text-build-content\">Zusammen mit dem sportlichen Ehrengast werden mehr als 1.200 Entscheiderinnen und Entscheider aus Wirtschaft, Politik und Wissenschaft zum Forum erwartet. Aus Bundes- und Landesregierung haben unter anderem Bundesumweltministerin Steffi Lemke, Sarah Ryglewski, Staatsministerin im Kanzleramt, und Mona Neubaur, stellvertretende Ministerpr\u00e4sidentin von Nordrhein-Westfalen zugesagt. Zudem kommen die CEOs von Dax-Konzernen, innovativen Mittelst\u00e4ndlern und gro\u00dfen Forschungseinrichtungen ins Circular Valley. Au\u00dferdem pr\u00e4sentieren Startups von sechs Kontinenten ihre Gesch\u00e4ftsmodelle.<\/p>\n<p class=\"text-build-content\">F\u00fcr Bayer 04 Leverkusen spielt Nachhaltigkeit eine wichtige Rolle. Der Klub hat im Jahr 2022 eine Stabsstelle zum Thema eingerichtet und f\u00fcr 2023 erstmals einen Nachhaltigkeitsbericht ver\u00f6ffentlicht. Der 82-seitige Report zeigt, was der Verein in den Feldern Umwelt, Gesellschaft und Klubf\u00fchrung tut, welche Projekte derzeit laufen und welche Ziele er sich vorgenommen hat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Liste der prominenten Teilnehmer am Circular Valley Forum wird immer l\u00e4nger! Jetzt hat auch Fernando Carro, CEO des Fu\u00dfball-Bundesligisten Bayer 04 Leverkusen, einer der V\u00e4ter des Double-Gewinns, sein Kommen zugesagt. Beim gro\u00dfen Treffen der Kreislaufwirtschaft am 15. November wird er erkl\u00e4ren, wie man die passende Organisation f\u00fcr gro\u00dfe Ziele formt.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-79128","post","type-post","status-publish","format-standard","hentry","category-wirtschaft"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:58:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=79128"}],"version-history":[{"count":1,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79128\/revisions"}],"predecessor-version":[{"id":79130,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/79128\/revisions\/79130"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=79128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=79128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=79128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}