{"id":78936,"date":"2024-10-21T14:14:33","date_gmt":"2024-10-21T12:14:33","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=78936"},"modified":"2024-10-21T14:14:33","modified_gmt":"2024-10-21T12:14:33","slug":"das-erste-hoerspiel-der-versuch-einer-rundfunk-groteske","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/10\/21\/das-erste-hoerspiel-der-versuch-einer-rundfunk-groteske\/","title":{"rendered":"Das erste H\u00f6rspiel: Der Versuch einer Rundfunk-Groteske"},"content":{"rendered":"<div id=\"attachment_78940\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-78940\" src=\"\/wp-content\/uploads\/2024\/10\/Prof._Lukas-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1709\" \/><span class=\"wp-caption-text\">Prof. Wolfgang Lukas, Lehrstuhl f\u00fcr Neuere deutsche Literaturgeschichte und Editionswissenschaft &#8211; \u00a9 Friederike von Heyden<\/span><\/div>\n<p>Autor Uwe Blass hat sich in der beliebten, spannenden Uni-Reihe &#8222;Jahr100Wissen&#8220; mit Wolfgang Lukas, Lehrstuhl-Inhaber\u00a0 f\u00fcr Neuere deutsche Literaturgeschichte und Editionswissenschaft an der Bergischen Universit\u00e4t, \u00fcber das erste\u00a0deutsche H\u00f6rspiel \u201eZauberei auf dem Sender\u201c im Rundfunk unterhalten .<\/p>\n<p><strong>\u00a0Worum ging es in \u201eZauberei auf dem Sender\u201c?<\/strong><\/p>\n<p><strong>Wolfgang Lukas: &#8222;<\/strong>In &#8218;<em>Zauberei auf dem Sender&#8216;<\/em> von Hans Flesch wurden St\u00f6rungen im Rundfunk inszeniert, d.h. da kamen scheinbar zuf\u00e4llig Personen herein, eine M\u00e4rchentante wollte ein M\u00e4rchen erz\u00e4hlen, also alles so Dinge, die eigentlich nicht f\u00fcr das Publikum gedacht waren, die mit Absicht als versehentlich inszeniert worden waren. Da hat man mit der Verunsicherung des H\u00f6rers gespielt, weil nie klar war, ob es nun dazugeh\u00f6rt oder von hinter den Kulissen kam. Und das war der Trick, die Verunklarung der Grenze zwischen Fiktion und Wirklichkeit. Schlie\u00dflich stellte sich heraus, dass das alles Machenschaften eines Zauberers waren, der im St\u00fcck (bzw. in der 1924 publizierten Textfassung \u2013\u00a0die ersten H\u00f6rspiele wurden ja noch nicht aufgezeichnet) Cagliostro genannt wird, mit Rekurs auf den ber\u00fchmten Spieler und Abenteurer des 18. Jahrhunderts.<\/p>\n<div id=\"attachment_53830\" class=\"wp-caption alignnone\" style=\"max-width: 440px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-53830\" src=\"\/wp-content\/uploads\/2022\/07\/Logo-Jahr100Wissen.jpg\" alt=\"\" width=\"430\" height=\"138\" \/><span class=\"wp-caption-text\">\u00a9 Bergische Universit\u00e4t<\/span><\/div>\n<p>Dieser Zauberer hatte Sendezeit gefordert, um akustische Zaubereien vorzuf\u00fchren. Und da hat man ihn ausgelacht und gesagt: \u201eZaubereien m\u00fcsse man doch sehen\u201c! Bis dahin gab es Zaubereien ja nur f\u00fcrs Auge. Um es zu beweisen, hat er dann eben diese St\u00f6rungen verursacht. Das f\u00fchrt uns dann auch zu dem Untertitel, der da hei\u00dft: &#8222;Versuch einer Rundfunkgroteske&#8220;. Das ist ja ein bestimmtes Genre, was auch mit einer phantastischen bis komischen Realit\u00e4t spielt. Es gibt ja die Tradition des Dadaismus, das ist sicherlich ein Bezugspunkt (der K\u00fcnstler und Maler Kurt Schwitters hat ja solche Sachen in der Zeit auch gemacht). Dann ist es auch interessant zu sehen, dass diese Tendenz zur phantastischen Realit\u00e4t sich fortsetzt.<\/p>\n<p>Ein Jahr sp\u00e4ter kommt das H\u00f6rspiel &#8222;<em>Spuk&#8220;<\/em> von Rolf Gunold, auch einem der ersten H\u00f6rspielautoren, heraus und noch ein Jahr danach von demselben das H\u00f6rspiel <em>Radiobolo, der Funkdeibel<\/em>. Also d.h., letzten Endes geht es um die Selbstthematisierung des Mediums, und das ist die eigentliche Botschaft. Es werden die M\u00f6glichkeiten der akustischen Illusionsbildung von Realit\u00e4t ausgelotet. Das kann man analog zum ganz fr\u00fchen Film sehen, der n\u00e4mlich in der 1890er Jahren mit den Trickfilmen und den kleinen Zauberst\u00fcckchen des Georges M\u00e9li\u00e8s in Frankreich, wo u.a. mit stop-motion gearbeitet wurde, genauso anf\u00e4ngt.&#8220;<\/p>\n<div id=\"attachment_78943\" class=\"wp-caption alignnone\" style=\"max-width: 810px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-78943\" src=\"\/wp-content\/uploads\/2024\/10\/Im-Kontrollraum-waehrend-einer-Hoerspielproduktion-1946-CC-BY-SA-3.0-de.jpg\" alt=\"\" width=\"800\" height=\"526\" \/><span class=\"wp-caption-text\">Im Kontrollraum w\u00e4hrend einer H\u00f6rspielproduktion (1946) &#8211; \u00a9 CC BY-SA 3.0 de\u00a0 Foto Schwahn-Illus.<\/span><\/div>\n<p><strong style=\"font-size: 16px;\">In der Kritik eine Woche sp\u00e4ter fragte der Autor: \u201e<\/strong><strong style=\"font-size: 16px;\">Aber w\u00e4re es nicht m\u00f6glich, mit dem Radio k\u00fcnstlerische Wirkungen zu erzielen, die weder das Theater, noch das Konzert, noch das Kino zu Wege bringen?&#8220; Was ist also das Besondere am Radioh\u00f6rspiel?<\/strong><\/p>\n<p>Wolfgang Lukas: &#8222;Das Besondere ist die Idee der rein akustischen T\u00e4uschung, also die zeichenhafte Abbildung der Realit\u00e4t allein mit akustischen Mitteln. Da habe ich dann nicht nur die Sprache, sondern auch die Musik und die Ger\u00e4usche. Diese akustischen Wirkungen haben noch einmal einen anderen Status als das Optische\/Visuelle. Da w\u00fcrde ich noch einmal einen Bogen schlagen zu den Bestrebungen nach einem \u2019unmittelbaren Leben\u2019, die am Ende des 19. Jahrhunderts auftauchen im Kontext der sogenannten \u2019Lebensideologie\u2019. Das sind Str\u00f6mungen, die das gesamte Kulturleben, die K\u00fcnste und die Wissenschaften sozusagen durchsetzen und wo, ausgehend von Nietzsches Kritik an der erstarrten, lebensfeindlichen b\u00fcrgerlichen Zivilisation und Kultur, die Parole ausgegeben wird: \u2019Wir wollen das unmittelbare Leben!\u2019.<\/p>\n<p>In der Kunst f\u00fchrt das dann zu neuen Formen des Sprechens. Zum Beispiel im Expressionismus, wo man sich von einer herk\u00f6mmlichen begrifflich-abstrakten Sprache abwendet und bildhaft wird. Ein wenig sp\u00e4ter, zeitgleich zur Erfindung des H\u00f6rspiels, gab es das ber\u00fchmte Manifest von B\u00e9la Bal\u00e1sz zum Stummfilm (<em>Der sichtbare Mensch oder die Kultur des Films<\/em> 1924), in dem er schreibt, dass das Tolle am Stummfilm just sei, dass man gar keine Sprache brauche, dass sie durch Gestik und Mimik ersetzt werden k\u00f6nne. Also zumal das nichtsprachliche Akustische ist noch einmal viel unmittelbarer.<\/p>\n<div id=\"attachment_78945\" class=\"wp-caption alignnone\" style=\"max-width: 1290px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-78945 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/old-radio-931432_1280.jpg\" alt=\"\" width=\"1280\" height=\"901\" \/><span class=\"wp-caption-text\">Ein Radio der ersten Stunde &#8211; \u00a9 Pixabay<\/span><\/div>\n<p>In &#8222;<em>Zauberei auf dem Sender&#8220;<\/em> ist das noch einmal sehr sch\u00f6n durch eine Musikeinspielung zu erkennen, die auch scheinbar ungeplant erklingt. Sicher kannte man damals schon Musik vom Grammophon, die man sich in trauter Stube anh\u00f6ren konnte, aber \u00fcber das Radio war das offenbar etwas v\u00f6llig Anderes, denn es war situationsentbunden.&#8220;<\/p>\n<p><strong>Ein Jahr sp\u00e4ter jedenfalls wurden bereits 43 H\u00f6rspielstunden eingeplant und in den 90er Jahren waren es schon knapp 2800 Stunden. Welche Themen sind denn am ehesten h\u00f6rspieltauglich?<\/strong><\/p>\n<p>Wolfgang Lukas: &#8222;Das ist sicherlich nicht absolut beantwortbar, denn eigentlich gibt es keine strikte Koppelung zwischen Medium, Genre und einem bestimmten Inhalt. Das ist zun\u00e4chst ganz offen. Klar ist, dass so gr\u00f6\u00dfere epische Formate wie z.B. Romane sicherlich eher nicht geeignet sind. Da es mit Unmittelbarkeit verbunden wird, sind es immer wieder so kleine Momentaufnahmen. Es gibt eine signifikante H\u00e4ufung von menschlichen Extremsituationen. Das geht eigentlich schon in der Literatur mit dem Inneren Monolog los. Beide Monolognovellen von Arthur Schnitzler etwa, &#8222;<em>Lieutenant Gustl&#8220;<\/em> (1900) und &#8222;<em>Fr\u00e4ulein Else&#8220;<\/em> (1924), bieten uns scheinbar unvermittelt die Gedanken von Figuren in deren letzten Stunden vor ihrem Tod.<\/p>\n<p>Das erste britische H\u00f6rspiel <em>Danger<\/em> macht etwas \u00c4hnliches. Da sind drei Menschen in einem Bergwerk verungl\u00fcckt und die m\u00fcssen sich auf den Tod gefasst machen. Sie werden am Ende zwar gerettet, aber das H\u00f6rspiel f\u00e4ngt Figuren in einer Extremsituation ein und ist ganz nah dran. Dazu findet das H\u00f6rspiel in der Fiktion im Bergwerk, also in der v\u00f6lligen Dunkelheit statt, d.h. das ist nat\u00fcrlich programmatisch, das Visuelle soll keine Rolle spielen. Die beiden ersten franz\u00f6sischen H\u00f6rspiele aus demselben Jahr 1924 spielen auf einem in Seenot geratenen Schiff bzw. inszenieren den Monolog eines Sterbenden (Paul Camille, <em>Mar\u00e9moto<\/em> und <em>Agonie<\/em>).<\/p>\n<div id=\"attachment_78946\" class=\"wp-caption alignnone\" style=\"max-width: 1290px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-78946 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/retro-4579735_1280.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><span class=\"wp-caption-text\">Pure Nostalgie &#8211; \u00a9 Pixabay<\/span><\/div>\n<p>Bis auf den heutigen Tag legen H\u00f6rspiele gerne den Fokus auf solche existentiellen Extremsituationen, man denke nur an die H\u00f6rspiele von Andreas Ammer, die wiederholt solche Fiktionen erfinden (<em>Radio Inferno<\/em> 1993, <em>Apocalypse live<\/em> 1994, <em>Crashing Aeroplanes<\/em> 2001, <em>Spacemen \u201985<\/em> 2005).&#8220;<\/p>\n<p><strong>1931 beschwerten sich B\u00fcrger beim Sender, weil sie sich mit drei H\u00f6rspielen pro Woche \u00fcberfordert f\u00fchlten und die Entspannung in der Musik suchten. Zu einem handfesten Skandal und Panik in der Bev\u00f6lkerung kam es 1938 durch das H\u00f6rspiel &#8222;Krieg der Welten&#8220; nach H.G. Wells in New York. Was war geschehen?<\/strong><\/p>\n<p>Wolfgang Lukas: &#8222;Die Macher des H\u00f6rspiels haben wieder mit dem Ph\u00e4nomen der \u2019Authentizit\u00e4t\u2019 gespielt. Dieser Roman von Wells von 1898 beinhaltet einen Angriff der Marsmenschen auf die Erde, der nur durch Bakterien verhindert werden kann. Orson Welles schrieb mit seinem Kompagnon eine H\u00f6rspieladaption und erzielte damit seinen k\u00fcnstlerischen Durchbruch. Es geht darum, dass das H\u00f6rspiel, sehr viel mehr als der Film, absolute Authentizit\u00e4t verhei\u00dft. Au\u00dferdem muss man sagen, die Menschen waren in den 1930er Jahren zwar das Radio gew\u00f6hnt, aber es gab nicht nur H\u00f6rspiele, sondern vor allem auch Nachrichten. Das Radio war zun\u00e4chst einmal das Medium f\u00fcr das Dokumentarische. Da wird \u00fcber Reales berichtet und dann kam dieses H\u00f6rspiel und l\u00f6ste Panik aus.&#8220;<\/p>\n<p><strong>Nach dem Zweiten Weltkrieg erlebte das H\u00f6rspiel noch einmal einen Boom. Woran lag das?<\/strong><\/p>\n<p>Wolfgang Lukas: &#8222;Dieser Boom hat sich eigentlich bis zum Beginn des Fernsehens fortgesetzt. Das hat sich dann aber erst in den 60er Jahren als neues Massenmedium durchgesetzt. In den 40er und 50er Jahren ist das Radio noch vorherrschend. Man muss aber auch sagen, das Radio wurde vor allem in Deutschland im Zweiten Weltkrieg massiv instrumentalisiert. Es war <em>das<\/em> Propagandainstrument f\u00fcr Joseph G\u00f6bbels, man kann ja im Haus des Rundfunks in Berlin immer noch den Raum besichtigen, wo er in der Ecke stand und dort seine Hetzreden gehalten hat. Das war sein Machtinstrument. Und nach dem Krieg war das dann anders zu erleben.&#8220;<\/p>\n<div id=\"attachment_78947\" class=\"wp-caption alignnone\" style=\"max-width: 1290px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-78947 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/radio-1954856_1280.jpg\" alt=\"\" width=\"1280\" height=\"803\" \/><span class=\"wp-caption-text\">Die schon etwas modernere Version des guten, alten Radios &#8211; \u00a9 Pixabay<\/span><\/div>\n<p><strong>In den 1950er Jahren \u00e4nderte sich die Machart der H\u00f6rspiele und man sprach oft auch vom &#8222;Worth\u00f6rspiel&#8220;. Was war damit gemeint?<\/strong><\/p>\n<p>Wolfgang Lukas: &#8222;Das ist in gewisser Weise zwar neu, aber aus sp\u00e4terer Perspektive eigentlich das alte H\u00f6rspiel. Erst in den 60er Jahren kommt dann die neue Bewegung. In den 50 Jahren haben wir das traditionelle H\u00f6rspiel, d.h. es sind Kammerspiele, kleine Theaterst\u00fccke, die stark handlungsbetont sind, eine traditionelle Narration bringen und relativ wenig mit Musik und Ger\u00e4usch arbeiten, also stark wortlastig sind.&#8220;<\/p>\n<p><strong>Den gr\u00f6\u00dften Skandal in der deutschen H\u00f6rspielgeschichte gab es 1969 mit Ludwig Harigs H\u00f6rspiel \u201eStaatsbegr\u00e4bnis oder Vier Lektionen politischer Gemeinschaftskunde\u201c. Was hat der Autor gemacht?<\/strong><\/p>\n<p>Wolfgang Lukas: &#8222;Das ist sozusagen eines der ersten O-Ton-H\u00f6rspiele, die wohl prominenteste Auspr\u00e4gung des sog. \u2019neuen H\u00f6rspiels\u2019. Es setzt sich von dem alten wort- und handlungszentrierten H\u00f6rspiel der Adenauer\u00e4ra der 50er Jahre ab. Ende der 60er Jahre ist es dann auch technikgeschichtlich als Voraussetzung so weit, dass die Autoren selber auf die Stra\u00dfe gehen und O-T\u00f6ne einsammeln k\u00f6nnen, es also keine reinen Studioproduktionen mehr gibt. Harig greift allerdings ausschlie\u00dflich auf Dinge zur\u00fcck, die im Radio gesendet wurden. Paul W\u00fchr und auch Paul P\u00f6rtner, die in der selben Zeit arbeiteten, gingen da schon freier vor.<\/p>\n<p>Harig montiert hier die offizielle Berichterstattung \u00fcber das Begr\u00e4bnis Adenauers. Wir erleben also am Radio in seiner Schnittfolge und Montage dieses Begr\u00e4bnis. Der k\u00fcnstlerische Effekt ist dabei die Selektion und Montage der Texte. Er w\u00e4hlt Szenen aus, die auf die Verquickung von Politik und Kirche hinweisen, also der ganze katholische K\u00f6lner Kirchenkl\u00fcngel wird hier akustisch evoziert.<\/p>\n<p>Kardinal Frings mit seiner liturgischen Sprache, seinem Sing-Sang wird durch starke Schnitte unterbrochen und mit Texten aus einem anderen Zusammenhang kontrastiert. Durch die Montage entsteht z.T. ein semantischer Effekt der Verkehrung ins Gegenteil. Das wurde von manchen Zeitgenossen als despektierlich empfunden und es gab Sender, die das nicht ausstrahlten. Tats\u00e4chlich war es ja auch eine Art Abgesang auf eine Epoche. Diese Art von Montage jedenfalls hat dann Paul W\u00fchr perfektioniert, und zwar mit selbst aufgenommenen T\u00f6nen.&#8220;<\/p>\n<div id=\"attachment_78948\" class=\"wp-caption alignnone\" style=\"max-width: 1290px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-78948 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/transistor-1064568_1280.jpg\" alt=\"\" width=\"1280\" height=\"960\" \/><span class=\"wp-caption-text\">War vor vielen Jahren der letzte Schrei: Ein Transistor-Radio &#8211; \u00a9 Pixabay<\/span><\/div>\n<p><strong>Bis heute ist Deutschland wegen seiner f\u00f6deralen Rundfunkstruktur das Land, in dem die meisten H\u00f6rspiele produziert werden. Mit am erfolgreichsten ist mit \u00fcber 50 Millionen verkauften Tontr\u00e4gern die Serie &#8222;Die drei ???&#8220;. Welchem Genre des H\u00f6rspiels lauschen Sie denn in Ihrer Freizeit?<\/strong><\/p>\n<p>Wolfgang Lukas: &#8222;Ich h\u00f6re in meiner Freizeit relativ regelm\u00e4\u00dfig die abendliche H\u00f6rspielreihe im Deutschlandfunk. Aktuell besch\u00e4ftige ich mich mit dem O-Ton-H\u00f6rspiel der 70er Jahre, speziell mit Paul W\u00fchr, einem Schriftsteller der experimentellen Gegenwartsliteratur, der zahlreiche H\u00f6rspiele verfasst hat und aus dessen Teilnachlass (der hier an der Universit\u00e4t aufbewahrt wird) ich im Rahmen einer kleinen Ausstellung beim diesj\u00e4hrigen Jubil\u00e4ums-H\u00f6rspielfestival an der Berliner Akademie der K\u00fcnste zusammen mit einer Doktorandin und einem Doktoranden einige Archivst\u00fccke zeigen kann.&#8220;<\/p>\n<p><strong>Uwe Blass<\/strong><\/p>\n<div id=\"attachment_78941\" class=\"wp-caption alignnone\" style=\"max-width: 210px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-78941 size-full\" src=\"\/wp-content\/uploads\/2024\/10\/Prof._Lukas-Kopie.jpg\" alt=\"\" width=\"200\" height=\"282\" \/><span class=\"wp-caption-text\">Prof. Wolfgang Luks &#8211; \u00a9 Friederike von Heyden<\/span><\/div>\n<h4>\u00dcber Prof. Wolfgang Lukas<\/h4>\n<p>Wolfgang Lukas studierte Germanistik und Romanistik an der Ludwig-Maximilians-Universit\u00e4t M\u00fcnchen und promovierte ebenda. Er habilitierte sich an der Universit\u00e4t Passau. Nach akademischen Zwischenstationen in Kiel und Z\u00fcrich \u00fcbernahm er 2006 den Lehrstuhl f\u00fcr Neuere deutsche Literaturgeschichte und Editionswissenschaft an der Bergischen Universit\u00e4t Wuppertal.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das erste europ\u00e4ische H\u00f6rspiel wurde am 15. Januar 1924 von der BBC ausgestrahlt. Das erste bekannte deutsche H\u00f6rspiel ging am 24. Oktober 1924 unter dem Titel \u201eZauberei auf dem Sender\u201c \u00fcber den \u00c4ther.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-78936","post","type-post","status-publish","format-standard","hentry","category-wissen"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:59:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/78936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=78936"}],"version-history":[{"count":6,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/78936\/revisions"}],"predecessor-version":[{"id":78949,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/78936\/revisions\/78949"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=78936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=78936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=78936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}