{"id":77921,"date":"2024-09-15T14:39:35","date_gmt":"2024-09-15T12:39:35","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=77921"},"modified":"2024-09-15T14:39:35","modified_gmt":"2024-09-15T12:39:35","slug":"uwe-blass-der-uni-und-oeffentlichkeits-versteher","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/09\/15\/uwe-blass-der-uni-und-oeffentlichkeits-versteher\/","title":{"rendered":"Uwe Blass, der Uni-und-\u00d6ffentlichkeits-Versteher"},"content":{"rendered":"<div id=\"attachment_77923\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77923 size-full\" src=\"\/wp-content\/uploads\/2024\/09\/DSC0714-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1700\" \/><span class=\"wp-caption-text\">Uwe Blass, Autor der beliebten Uni-Reihen &#8222;Transfergeschichten&#8220; und &#8222;Jahr100Wissen&#8220; &#8211; \u00a9 Iris Rudolph<\/span><\/div>\n<p>Manche Protagonisten kennt man gut, andere weniger. Ob bekannt oder weniger bekannt: Wer ihre Portraits liest, m\u00f6chte vermutlich die eine oder den anderen pers\u00f6nlich kennenlernen. Bisher hat der Jorunalist und Autor Dr. Matthias Dohmen an gleicher Stelle Dorothea Brandt, Klaus Burandt, Christine Flunkert, Uwe Flunkert, Peter Klassen, Heidemarie Koch, Werner Kleine, Johannes Nattland, Josa Oehme, Willfried Penner, Reiner Rhefus, Klaus Saalmann, Erika Schneider, Ingrid Schuh, Hermann Schulz, Klaus Schumann, Michael Walter und Wolf von Wedel Parlow vorgestellt.<\/p>\n<p>Uwe Blass ist davon \u00fcberzeugt, dass der \u201eCampus noch viele geheime Wissenssch\u00e4tze beherbergt, die man f\u00fcr die B\u00fcrgerinnen und B\u00fcrger entdecken kann\u201c.<\/p>\n<h4>Hans Dampf in alle Gassen<\/h4>\n<p>\u201eMan\u201c, das ist im gegebenen Fall der am 25.8.1964 in Wuppertal geborene Uwe Blass, Landesangestellter an der Universit\u00e4t Wuppertal und Hans Dampf in allen Gassen, wenn es um die Popularisierung dessen geht, was an auf dem Johannisberg erforscht, ausget\u00fcftelt und entwickelt wird. In der WZ und in der Internet-basierten \u201eStadtzeitung\u201c popularisiert Blass, der sein Studium der Germanistik, Geschichte und der Allgemeinen Literaturwissenschaft mit einer Magisterarbeit \u00fcber Georg B\u00fcchner und Victor Hugo abgeschlossen hat, Forschungsergebnisse der Bergischen Universit\u00e4t.<\/p>\n<p>Neben den Beitr\u00e4gen f\u00fcr \u201eStadtzeitung\u201c und WZ sind eine Reihe von B\u00fcchern erschienen. Nehmen wir nur den Band I der \u201eBergischen Transfergeschichten \u2013 100 Wissenschaftler*innen und ihre Projekte\u201c, in denen es beispielsweise um Chormusik und Computerspiel, um die Jesuiten als Wegbereiter einer organisierten Musikerziehung oder um Anna von Cleve geht, eine \u201ebergische Tochter auf dem englischen Thron\u201c.<\/p>\n<div id=\"attachment_77924\" class=\"wp-caption alignnone\" style=\"max-width: 561px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77924\" src=\"\/wp-content\/uploads\/2024\/09\/Uwe-Blass-Foto-Iris-Rudolph.jpg\" alt=\"\" width=\"551\" height=\"367\" \/><span class=\"wp-caption-text\">Der Autor Uwe Blass &#8211; \u00a9 Iris Rudolph<\/span><\/div>\n<p>Und das sind jetzt nur geistes- und kulturwissenschaftlichen Themen. \u00dcberschriften von Beitr\u00e4gen aus der Fakult\u00e4t f\u00fcr Human- und Sozialwissenschaften lauten etwa \u201eDie kleine Universit\u00e4tsambulanz in unserer Stra\u00dfe\u201c, das immer wieder aktuelle Thema \u201eUnerw\u00fcnschte Ber\u00fchrungen im Breitensport\u201c oder \u201eDie Pandemie hat uns wieder daran erinnert, dass wir als Individuen Mitglieder einer Gesellschaft sind\u201c.<\/p>\n<p>Uwe Blass: \u201eDie Transfergeschichten entstanden 2016, als wir Gespr\u00e4che mit unseren Wissenschaftlern gef\u00fchrt haben, um sie im Binnenaustausch besser kennenzulernen. Dabei kam mir dann die Idee, dass es doch viel sinnvoller w\u00e4re, wenn wir durch Geschichten \u00fcber die Projekte unserer Forscher auch die B\u00fcrgerinnen und B\u00fcrger informieren k\u00f6nnten.\u201c<\/p>\n<p>R\u00fcckmeldungen erh\u00e4lt er immer wieder: \u201eSowohl die Wissenschaftler, \u00fcber die ich berichte, melden sich \u2013 und haben im Idealfall auch schon wieder ein neues Thema -, als auch Leser schreiben mich an, um sich zu bedanken oder um den Kontakt zu den Wissenschaftlern zu erhalten.\u201c<\/p>\n<h4>Wissenschaftler liefern ihm die Themen<\/h4>\n<p>Die Ideen gehen ihm nicht aus: \u201eManchmal recherchiere ich im Uninetz, finde Wissenschaftler und deren Projekte, manchmal finde ich ein interessantes Thema in der Presse und \u00fcberlege, ob wir an der Hochschule dazu vielleicht auch einen Fachmann oder eine Fachfrau haben, die oder der dazu etwas sagen kann.\u201c Auch bei Treffen f\u00fcr ein Transfergespr\u00e4ch sto\u00dfe er oft auf weitere Themen, \u00fcber die man sich sp\u00e4ter noch einmal austauscht, um daraus eine neue Geschichte zu schreiben.<\/p>\n<p>Nicht selten geht der Blick zur\u00fcck: Die turbulenten Jahre 1919 bis 1923 umfasst das Buch \u201eJahr100Wissen\u201c, das Blass und Dr. Peter Jonk 2023 f\u00fcr die Uni herausgegeben haben. Dort spricht dann ein Historiker \u00fcber die Abdankung von Wilhelm I. (\u201eVom deutschen Kaiser zum G\u00e4rtner von Doorn\u201c), ein Maschinenbauer \u00fcber den Jungfernflug des ersten Gesamtmetallflugzeuges, ein Architekt \u00fcber den Geheimbund \u201eGl\u00e4serne Kette\u201c, ein Bauingenieur \u00fcber die erste Rolltreppe in den USA, ein Germanist \u00fcber Ph\u00e4nomene eines Dschungelhelden (\u201eIch Tarzan, du Jane \u2026\u201c) \u00a0oder ein Lebensmittelchemiker \u00fcber \u201eSchaumzucker aus der M\u00e4usefabrik\u201c.<\/p>\n<div id=\"attachment_77927\" class=\"wp-caption alignnone\" style=\"max-width: 560px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77927 size-full\" src=\"\/wp-content\/uploads\/2024\/09\/Uwe-Blass-Foto-Privat-Kopie.jpg\" alt=\"\" width=\"550\" height=\"413\" \/><span class=\"wp-caption-text\">Liefert spannende und wissenwerte Lekt\u00fcre: Uwe Blass &#8211; \u00a9 privat<\/span><\/div>\n<p>Oftmals spricht man \u00fcber die praxisfernen Wissenschaftler im Elfenbeinturm. Stimmt das, oder stimmt es nicht? Blass ist fest davon \u00fcberzeugt, dass die meisten Professoren, Akademischen R\u00e4te und wissenschaftlichen Assistenten nicht vor sich hin forschen, \u201esondern oft in Projekten an tats\u00e4chlichen Problemen arbeiten, mit deren L\u00f6sung sich unser Leben oder unser Alltag vereinfachen l\u00e4sst\u201c.<\/p>\n<p>Nicht nur alte B\u00fccher haben es Blass angetan. Er interessiert sich auch f\u00fcr antike M\u00f6bel und ist viel mit dem Hund, einem <em>spinone italiano <\/em>unterwegs, einem italienischen Jagdhund. Literarische Interessen? \u201eGanz aktuell habe ich gerade den Roman &#8222;Der Markisenmann&#8220; von Jan Weiler gelesen, eine wunderbar bewegende, witzige Geschichte einer Vater-Tochter-Beziehung.<\/p>\n<p>Blass\u2018 Quintessenz aus der jahrzehntelangen Besch\u00e4ftigung mit der Popularisierung von Wissenschaft: \u201eIch denke, viele Menschen im Tal wissen gar nicht, an welcher gro\u00dfen Anzahl an Themen die Bergische Uni in all ihren F\u00e4chern forscht.\u201c Die Arbeit, glaubt man ihm gern, geht ihm so schnell nicht aus.<\/p>\n<p><strong>Dr. Matthias Dohmen<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eUpdate\u201c hei\u00dft unsere Serie, in der Matthias Dohmen, Journalist, Dozent und Historiker, Pers\u00f6nlichkeiten aus dem Bergischen Land vorstellt. Mit alten und neuen Texten. Mit Fotos und Dokumenten. Menschen, die ihm etwas bedeuten. Diesmal steht Uwe Blass im Fokus.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-77921","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:59:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=77921"}],"version-history":[{"count":5,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77921\/revisions"}],"predecessor-version":[{"id":77930,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77921\/revisions\/77930"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=77921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=77921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=77921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}