{"id":77671,"date":"2024-09-04T10:47:23","date_gmt":"2024-09-04T08:47:23","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=77671"},"modified":"2024-09-04T15:46:36","modified_gmt":"2024-09-04T13:46:36","slug":"klaus-saalmann-hat-viel-ueber-die-stille-nachgedacht","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/09\/04\/klaus-saalmann-hat-viel-ueber-die-stille-nachgedacht\/","title":{"rendered":"Klaus Saalmann hat viel \u00fcber die Stille nachgedacht"},"content":{"rendered":"<div id=\"attachment_77693\" class=\"wp-caption alignnone\" style=\"max-width: 1062px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-77693\" src=\"\/wp-content\/uploads\/2024\/09\/20230911_104712.jpg\" alt=\"\" width=\"1052\" height=\"788\" \/><span class=\"wp-caption-text\">Klaus Saalmann, der Mann, der die Stille sucht und breitgef\u00e4chert interessiert ist &#8211; \u00a9 privat<\/span><\/div>\n<p>Manche Protagonisten kennt man gut, andere weniger. Ob bekannt oder weniger bekannt: Wer ihre Portraits liest, m\u00f6chte vermutlich die eine oder den anderen pers\u00f6nlich kennenlernen. Bisher hat Dr. Matthias Dohmen an gleicher Stelle Dorothea Brandt, Klaus Burandt, Christine Flunkert, Uwe Flunkert, Peter Klassen, Heidemarie Koch, Werner Kleine, Johannes Nattland, Josa Oehme, Willfried Penner, Reiner Rhefus, Erika Schneider, Ingrid Schuh, Hermann Schulz, Klaus Schumann, Michael Walter und Wolf von Wedel Parlow vorgestellt.<\/p>\n<p>\u00dcber Stille hat Klaus Saalmann viel nachgedacht. Und \u00fcber Buddhismus. Zum Beispiel bei Meditationswochenenden oder Aufenthalten in Kl\u00f6stern. Acht Mal war Klaus Saalmann auf dem Jakobsweg unterwegs: \u201eNach einer Woche h\u00f6rt man anders, sieht anders, riecht anders und nimmt Mitmenschen anders wahr\u201c, ist Klaus Saalmann \u00fcberzeugt.<\/p>\n<p>Hermann Hesse geh\u00f6rt zu seinen Lieblingsautoren, aber auch der vielfach als Exot verschriene Philosoph Arthur Schopenhauer, der von 1788 bis 1860 gelebt hat und der auf den Fotos, die man in Lexika findet, meist griesgr\u00e4mig aussieht. Wie Hesse und Schopenhauer steht auch Saalmann fern\u00f6stliches Gedankengut sehr nahe.<\/p>\n<p>Geboren wurde Klaus Saalmann, der in Wuppertal als Leiter des Finanzamtes Elberfeld bekannt wurde, am 3. April 1948 in Recklinghausen als Sohn einer Verk\u00e4uferin und eines Schlossers. Also ein Arbeiterkind. \u00dcber 40 Jahre war er verheiratet, bis seine Frau 2016 starb. Er hat einen 40j\u00e4hrigen Sohn, der als Jurist in Berlin lebt. Heute ist er gl\u00fccklich mit einer Apothekerin liiert, die ebenfalls im Ruhestand lebt, aber gelegentlich noch an ihrer alten Wirkungsst\u00e4tte t\u00e4tig ist.<\/p>\n<div id=\"attachment_77684\" class=\"wp-caption alignnone\" style=\"max-width: 510px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77684 size-full\" src=\"\/wp-content\/uploads\/2024\/09\/Mark-Rothko-Kopie.jpg\" alt=\"\" width=\"500\" height=\"750\" \/><span class=\"wp-caption-text\">Klaus Saalmann vor einem Werk des US-K\u00fcnstlers Mark Rothko &#8211; \u00a9 privat<\/span><\/div>\n<p>Klaus Saalmann studierte in M\u00fcnster und K\u00f6ln Jura und trat 1975 in die nordrhein-westf\u00e4lische Finanzverwaltung ein und arbeitete eine Zeitlang als Dozent, sieben Jahre als stellvertretender Schulleiter und eine Dekade als Chef der Landesfinanzschule von Nordrhein-Westfalen. Von 2001 bis 2014, dem Jahr, als er verabschiedet wurde, war er Chef des Finanzamtes an der Kasinostra\u00dfe.<\/p>\n<p>Wo heute Steuerbescheide erarbeitet werden, stand zu Beginn der 1820er-Jahre ein \u201eMuseum\u201c, das einem elit\u00e4ren Publikum zum Austausch von Literatur und Kunst diente und das mit Namen wie Goethe und Jung-Stilling verbunden ist und den Spott von Friedrich Engels auf sich gezogen hat. Der damals 19j\u00e4hrige Gesellschaftstheoretiker und Politiker aus Barmen schrieb w\u00f6rtlich: \u201e\u00dcbrigens ist das Geb\u00e4ude so plump in allen Dimensionen, dass man es abends f\u00fcr ein Kamel h\u00e4lt.\u201c<\/p>\n<p>Als der Musentempel 1858 einem Brand zum Opfer fiel, wurde an gleicher Statt ein \u201eCasino\u201c errichtet, ebenfalls ein Ort der Kultur, in dem 1927 Thomas Mann aus seinem Roman \u201eJoseph und seine Br\u00fcder\u201c las. Doch auch dieser Kulturort \u00fcberlebte nicht, sondern wurde im Juni 1943 ein Opfer des von den Nationalsozialisten provozierten Bombenhagels der Alliierten.<\/p>\n<p>Nicht nur, dass Klaus Saalmann \u00fcber die Geschichte des Finanzamtes an der Casinostra\u00dfe und seiner Vorg\u00e4nger und Nachfolger gearbeitet hat, er veranstaltete dort auch regelm\u00e4\u00dfig Ausstellungen. Daneben zog es ihn 40 Jahre lang in Sachen Aus- und Fortbildung in die weite Welt, so nach Brasilien, Kenia, Namibia, Nepal, Russland, Serbien, S\u00fcdafrika und Tansania, also Staaten h\u00f6chst unterschiedlicher Klimazonen, politischer Strukturen und Kontinente.<\/p>\n<div id=\"attachment_77685\" class=\"wp-caption alignnone\" style=\"max-width: 510px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77685 size-full\" src=\"\/wp-content\/uploads\/2024\/09\/Wanderer-ueber-dem-Nebelmeer-Caspar-David-Friedrich.jpg\" alt=\"\" width=\"500\" height=\"631\" \/><span class=\"wp-caption-text\">Das ber\u00fchmte Bild \u201eWanderer \u00fcber dem Nebelmeer\u201c von Caspar David Friedrich &#8211; \u00a9 privat<\/span><\/div>\n<p>Er reist viel, er liest viel. Und hat auch schon Karikaturenb\u00fccher herausgegeben zu von ihm organisierten, bundesweit gezeigten Wanderausstellungen wie \u201eOhne Moos nix los\u201c oder \u201eKr\u00f6tenwanderung \u2013 Karikaturisten sehen Steuerstress und Steuerrecht in Deutschland\u201c. Zitiert werden in dem letztgenannten Werk Georg Lichtenberg, Benjamin Franklin, Horaz und viele andere politische und Geistesgr\u00f6\u00dfen, die unter der Last beh\u00f6rdlicher Finanzforderungen gelitten haben.<\/p>\n<p>Der am Katernberg wohnhafte vielseitig interessierte Mensch, der so gar nicht an einen B\u00fcrokraten denken l\u00e4sst, war 15 Jahre im Aufsichtsrat der \u00f6rtlichen Caritas und acht Jahre im Stiftungsvorstand des St.-Josef-Krankenhauses. Er sitzt weiter im Kuratorium der \u201eStiftung Seelsorge\u201c, die sich zur Aufgabe gestellt hat, \u201eMenschen, Ideen und Finanzen\u201c f\u00fcr gute Zwecke zusammenzuf\u00fchren.<\/p>\n<p>Schlie\u00dflich engagiert sich Klaus Saalmann am Simonsh\u00f6fchen in der Gefangenenf\u00fcrsorge mit unterschiedlichen Projekten wie einem Deutschkurs f\u00fcr Analphabeten oder \u2013 gegenw\u00e4rtig \u2013 einem Schachkurs. Einem anderen Publikum als dem der Steuerzahler ist er \u00fcber die Friedrich-Spee-Akademie und das Katholische Bildungswerk bekannt geworden: Mit Powerpoint-Pr\u00e4sentationen \u00fcber so disparat erscheinende Themen wie \u201eBilder und Geschichten rund um den Kasinokreisel und den Laurentiusplatz\u201c und \u201eDie Kathedrale von Chartres und der Geist des Mittelalters\u201c.<\/p>\n<div id=\"attachment_77686\" class=\"wp-caption alignnone\" style=\"max-width: 510px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77686 size-full\" src=\"\/wp-content\/uploads\/2024\/09\/20240828_100947.jpg\" alt=\"\" width=\"500\" height=\"651\" \/><span class=\"wp-caption-text\">Ein belesener Mensch: Klaus Saalmann &#8211; \u00a9 privat<\/span><\/div>\n<p>Die \u201eFaszination der Stille\u201c demonstrierte er k\u00fcrzlich bei seinem im Katholischen Stadthaus gehaltenen Vortrag anhand von Bildern von Mark Rothko und Caspar David Friedrich. \u201eR\u00fcckenfigur\u201c auf dem Rothko-Bild zeigt im \u00dcbrigen Klaus Saalmann selbst in der Neuen Nationalgalerie vor dem Bild eines der popul\u00e4rsten US-amerikanischen Maler, der \u201eWanderer \u00fcber dem Nebelmeer\u201c ist eines der Schl\u00fcsselwerke aus der deutschen Romantik.<\/p>\n<p><strong>Dr. Matthias Dohmen<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eUpdate\u201c hei\u00dft unsere Serie, in der Dr. Matthias Dohmen, Journalist, Dozent und Historiker, Pers\u00f6nlichkeiten aus dem Bergischen Land vorstellt. Mit alten und neuen Texten. Mit Fotos und Dokumenten. Menschen, die ihm etwas bedeuten. Diesmal steht Klaus Saalmann im Fokus.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-77671","post","type-post","status-publish","format-standard","hentry","category-wuppertal"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:57:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=77671"}],"version-history":[{"count":5,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77671\/revisions"}],"predecessor-version":[{"id":77695,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77671\/revisions\/77695"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=77671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=77671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=77671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}