{"id":77386,"date":"2024-08-24T10:24:05","date_gmt":"2024-08-24T08:24:05","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=77386"},"modified":"2024-11-12T13:28:37","modified_gmt":"2024-11-12T12:28:37","slug":"abschied-von-peter-koeppel-ulrike-von-der-groeben","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/08\/24\/abschied-von-peter-koeppel-ulrike-von-der-groeben\/","title":{"rendered":"Abschied von Peter Koeppel &#038; Ulrike von der Groeben"},"content":{"rendered":"<div id=\"attachment_77389\" class=\"wp-caption alignnone\" style=\"max-width: 811px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77389 size-full\" src=\"\/wp-content\/uploads\/2024\/08\/1724483706_peter-kloeppel-ulrike-von-der-groe.jpeg\" alt=\"\" width=\"801\" height=\"510\" \/><span class=\"wp-caption-text\">Frauke Ludowig (l.) &#8222;platzte&#8220; in die letzte &#8222;RTL aktuell&#8220;-Sendung von Peter Kloeppel und Ulrike von der Groeben, um sich sehr emotional von ihren langj\u00e4hrigen Kolldegen zu verabschieden &#8211; \u00a9 screenshot \/ RTL<\/span><\/div>\n<p>Ich bin sehr stolz darauf, dass ich beide Legenden fast 12 Jahre lang als Kollege begleiten durfte. Als ich Peter Kloeppel auf einer RTL-Weihnachtsfeier in K\u00f6ln kennenlernte, war er noch RTL-Korrespondent in den USA und berichte beispielsweise \u00fcber die Golfkriege. Sp\u00e4ter, als er Anchorman der Hauptnachrichtensendung \u201eRTL aktuell\u201c war, hatten wir regelm\u00e4\u00dfig Kontakt. Ein toller Kollege.<\/p>\n<p>Ulrike von der Groeben (67) war unsere Ansprechpartnerin, wenn es um Sportbeitr\u00e4ge in der Sendung \u201eRTL aktuell\u201c ging. Die Ehefrau des erfolgreichen Judokas und gefragten TV-Moderaters Alexander von der Groeben (z.B. ZDF) und Mutter des bekannten Schauspielers Max von Groeben\u00a0 (u.a. \u201eFack ju G\u00f6the\u201c) habe ich die ganze Zeit \u00fcber als immer freundliche, verst\u00e4ndnisvolle und professionelle Kollegin erlebt.<\/p>\n<p>Das deutsche Fernsehen wird ohne Peter Kloeppel und Ulrike von der Groeben sehr viel \u00e4rmer sein. RTL verliert zwei \u00fcberaus informierte, kompetente und beliebte TV-Journalisten, echte Sympathietr\u00e4ger. Beide hinterlassen gro\u00dfe Fu\u00dfabdr\u00fccke, immerhin waren sie \u00fcber 30 Jahre lang als Duo fast jeden Abend gern gesehene G\u00e4ste in den deutschen Wohnzimmern.<\/p>\n<div id=\"attachment_77391\" class=\"wp-caption alignnone\" style=\"max-width: 661px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-77391\" src=\"\/wp-content\/uploads\/2024\/08\/RTL-Quartett.jpg\" alt=\"\" width=\"651\" height=\"422\" \/><span class=\"wp-caption-text\">Die beiden neuen Moderatoren-Duos von \u201eRTL aktuell\u201c: (v.l.): Christopher Wittich, Anna Fleischhauer, Roberta Bieling und Andreas von Thien \u2013 \u00a9 RTL \/ Boris Breuer<\/span><\/div>\n<p>Ein G\u00e4nsehaut-Moment, als Frauke Ludowig, beliebte Moderatorin des Promi-Magazins \u201eExclusiv\u201c, w\u00e4hrend der letzten \u201eRTL aktuell\u201c-Sendung live im News-Studio auftauchte und sich sehr emotional von ihren langj\u00e4hrigen Kollegen Peter Kloeppel und Ulrike von der Groeben verabschiedete.<\/p>\n<p>Frauke Ludowig ist jetzt beim K\u00f6lner Privatsender eine der letzten Protagonistinnen einer sehr erfolgreichen \u00c4ra. Peter Kloeppel und Ulrike von der Groeben w\u00fcnsche ich f\u00fcr die Zukunft nur das Beste.<\/p>\n<p>Und ein wenig stolz bin ich auch darauf, dass ich auch den Weg von Peter Kloeppels Nachfolgerin Robert Bieling einige Jahre begleiten konnte. Die erfahrene TV-Journalistin moderiert jetzt \u201eRTL aktuell\u201c im Wechsel mit Christopher Wittich.<\/p>\n<p><strong>Peter Pionke<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im deutschen Fernsehen geht eine \u00c4ra zu Ende. Zwei TV-Legenden haben sich nach \u00a032 Jahren vom Bildschirm verabschiedet: News- Anchorman Peter Kloeppel und Sportmoderatorin Ulrike von der Groeben. Zwei Gesichter, die den Privatsender RTL ma\u00dfgeblich pr\u00e4gten. Am Freitag (23.08.) moderierte das Duo zum letzten Mal die Nachrichtensendung \u00a0\u201eRTL aktuell\u201c.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-77386","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:58:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=77386"}],"version-history":[{"count":4,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77386\/revisions"}],"predecessor-version":[{"id":77392,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/77386\/revisions\/77392"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=77386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=77386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=77386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}