{"id":76761,"date":"2024-07-23T20:21:46","date_gmt":"2024-07-23T18:21:46","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=76761"},"modified":"2024-08-01T10:47:05","modified_gmt":"2024-08-01T08:47:05","slug":"wsv-startet-mit-remis-gegen-austeiger-in-die-neue-saison","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/07\/23\/wsv-startet-mit-remis-gegen-austeiger-in-die-neue-saison\/","title":{"rendered":"WSV startet mit Remis gegen Austeiger in die neue Saison"},"content":{"rendered":"<div id=\"attachment_76763\" class=\"wp-caption alignnone\" style=\"max-width: 2510px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-76763 size-full\" src=\"\/wp-content\/uploads\/2024\/07\/Classen-27-07-2024-130.jpg\" alt=\"\" width=\"2500\" height=\"1667\" \/><span class=\"wp-caption-text\">Gro\u00dfer Jubel beim WSV nach dem Tor zum 1:1 durch Oguzhan Kefkir &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<p>Die Dortmunder mussten aufgrund fehlender tauglicher Spielst\u00e4tte in Dortmund nach Velbert \u00a0ausweichen. Bereits nach f\u00fcnf Minuten die erste Doppelchance f\u00fcr T\u00fcrkspor. Ein Schuss aus spitzem Winkel konnte die WSV-Abwehr zur Ecke lenken und beim anschlie\u00dfenden Ecksto\u00df war Dag am zweiten Pfosten komplett frei, setzte den Ball aber neben den Kasten.<\/p>\n<p>T\u00fcrkspor machte von Beginn an Druck und zeigte sich als Aufsteiger in seinem ersten Regionalligaspiel sehr mutig. In der 09. Minute wurde der WSV erstmals gef\u00e4hrlich. Kevin Hagemann f\u00fchrte auf der linken Angriffsseite einen Einwurf schnell auf Oguzhan Kefkir aus, der bediente mit einer Flanke Pedro Cejas. Dieser schloss aus der Drehung sofort ab, doch der Ball wurde abgef\u00e4lscht und klatschte\u00a0 an den Torpfosten des Dortmunder Tores.<\/p>\n<p>Anschlie\u00dfend verflachte das Spiel ein wenig. Bis Dominik Bilogrevic ein katastrophaler Fehler unterlief. Er spielte aus dem Mittelfeld einen viel zu kurzen R\u00fcckpass auf Torh\u00fcter Krystian Wozniak. Der Dortmunder Vincent Ocansey konnte den Ball erlaufen und lupfte ich gekonnt \u00fcber WSV-Keeper Wozniak zum 1:0 f\u00fcr die Gastgeber ins Tor (39.).<\/p>\n<p>Mit diesem Spielstand wurden auch die Seiten gewechselt. In der 2. Halbzeit kamen die Sch\u00fctzlinge von WSV-Cheftrainer Ren\u00e9 Klingbeil schnell ins Spiel zur\u00fcck. Nach einem Foul an Pedro Cejas gab es kurz vor dem gegnerischen Strafraum einen \u00a0Freisto\u00df f\u00fcr den WSV. Diesen zirkelte Oguzhan Kefkir mit seinem linken Fu\u00df \u00fcber die Dortmunder Mauer und von der Unterkante der Latte sprang der Ball auf und dann ins Tor zum 1:1-Ausgleich (50.).<\/p>\n<div id=\"attachment_76764\" class=\"wp-caption alignnone\" style=\"max-width: 2510px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-76764 size-full\" src=\"\/wp-content\/uploads\/2024\/07\/Classen-27-07-2024-182.jpg\" alt=\"\" width=\"2500\" height=\"1667\" \/><span class=\"wp-caption-text\">Voll konzentriert im Zweikampf: Kevin Hagemann &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<p>In der 69. Minute dann ein starkes Solo von Dildar Atmaca, der gerade noch so zur Ecke gekl\u00e4rt werden konnte. In der 80. Minute setzte sich der eingewechselte Ali G\u00fcn gut durch und schoss den Ball von der Strafraumgrenze knapp am rechten Torpfosten vorbei.<\/p>\n<p>Doch dann in der 86. Minute ein Schock f\u00fcr den WSV und seinen Anhang. Schiedsrichter Lukas Koch sah ein strafw\u00fcrdiges Foulspiel von Levin M\u00fcller im Strafraum und zeigte auf den Punkt. Doch Krystian Wozniak parierte den Elfmeter von Vincent Ocansey. In der 93. Minute vergab dann Dortmunds Ibrahim Bulut per Kopf freistehend am F\u00fcnfmeterraum den Siegtreffer f\u00fcr T\u00fcrkspor. Der Ball segelte ganz knapp am Tor von Krystian Wozniak vorbei.<\/p>\n<p>Am Ende muss der WSV mit diesem Unentschieden zum Auftakt zufrieden sein. \u00a0Aufgrund der gr\u00f6\u00dferen Torm\u00f6glichkeiten von T\u00fcrkspor h\u00e4tte die Partie auch mit einer Niederlage f\u00fcr den WSV enden k\u00f6nnen.<\/p>\n<p>Weiter geht es f\u00fcr den WSV in der Regionalliga West am 2. Spieltag beim ersten Heimspiel dieser Saison n\u00e4chste Woche Samstag (03.08.) um 14:00 Uhr im Stadion am Zoo gegen Rot-Wei\u00df Oberhausen.<\/p>\n<div id=\"attachment_76765\" class=\"wp-caption alignnone\" style=\"max-width: 2510px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-76765 size-full\" src=\"\/wp-content\/uploads\/2024\/07\/Classen-27-07-2024-148.jpg\" alt=\"\" width=\"2500\" height=\"1666\" \/><span class=\"wp-caption-text\">WSV-Einwechselspieler Dildar Atmaca verletzte sich am Arm und musste nach nur 12 Minuten schon wieder ausgewechselt werden &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<h4>T\u00fcrkspor Dortmund \u2013 Wuppertaler SV 1:1 (1:0)<\/h4>\n<p><strong>Aufstellung T\u00fcrkspor Dortmund:<\/strong><\/p>\n<p>1 Muhammed Acil \u2013 3 Serdar Bing\u00f6l, 21 Mehmet Kaya, 4 Maurice Haar, 11 Migel-Max Schmeling (74. 16 Semih Yigit) \u2013 8 Ibrahim Bulut, 6 Sezer Toy \u2013 7 Ilias Anan (77. 10 Rilind Hetemi), 23 Alessandro Tomasello, 9 Koray Dag (66. 22 Ali G\u00fcn) \u2013 14 Vincent Ocansey Trainer: Sebastian Tyrala<\/p>\n<p><strong>Aufstellung Wuppertaler SV:<\/strong><\/p>\n<p>1 Krystian Wozniak \u2013 22 Levin M\u00fcller, 4 Vincent Gembalies, 14 Oktay Dal, 38 Oguzhan Kefkir \u2013 20 Dominik Bilogrevic (68. 23 Riccardo Grym), 10 Marco Terrazzino \u2013 11 Niek Munsters (60. 17 Dildar Atmaca; 72. 37 Hugo Schmidt), 7 Semir Saric, 9 Kevin Hagemann \u2013 19 Pedro Cejas Trainer: Ren\u00e9 Klingbeil<\/p>\n<p><strong>Tore:<\/strong> 1:0 Ocansey (39.), 1:1 Kefkir (50.)<\/p>\n<p><strong>Stadion:<\/strong> IMS Arena<\/p>\n<p><strong>Zuschauer:<\/strong> 1.780<\/p>\n<p><strong>Schiedsrichter:<\/strong> Lukas Koch \/ Assistenten: Dominik Mynarek, Nils Leichert<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Wuppertaler SV ist mit einem 1:1 (1:0) Unentschieden in die Regionalliga-Saison 2024\/25 gestartet. Das Ausw\u00e4rtsspiel gegen T\u00fcrkspor Dortmund fand in der IMS-Arena in Velbert statt.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-76761","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:59:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/76761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=76761"}],"version-history":[{"count":4,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/76761\/revisions"}],"predecessor-version":[{"id":76768,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/76761\/revisions\/76768"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=76761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=76761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=76761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}