{"id":75390,"date":"2024-05-25T20:04:59","date_gmt":"2024-05-25T18:04:59","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=75390"},"modified":"2024-06-05T11:45:49","modified_gmt":"2024-06-05T09:45:49","slug":"zwillingsschwestern-haoua-und-azera-doga-im-cafe-swane","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/05\/25\/zwillingsschwestern-haoua-und-azera-doga-im-cafe-swane\/","title":{"rendered":"Zwillingsschwestern\u00a0Haoua und Azera Doga im &#8222;Caf\u00e9 Swane&#8220;"},"content":{"rendered":"<div id=\"attachment_75393\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-75393 size-full\" src=\"\/wp-content\/uploads\/2024\/05\/lessoeursdogaviktormarek2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1895\" \/><span class=\"wp-caption-text\">Die Zwillingsschwestern\u00a0Haoua und Azera Doga und Viktor Marek kommen ins Caf\u00e9 Swane &#8211; \u00a9 privat<\/span><\/div>\n<p>Im Juni, hier und da schon angek\u00fcndigt, gibt es einige kleine und gro\u00dfe Highlights, die ich kaum erwarten kann. Hier die \u201eAction\u201c der 1sten\u00a0Woche.<\/p>\n<p><strong>Dienstag \u2013 4. Juni \u2013 12 bis 17 Uhr \u2013 Ebert Platz \u2013 K\u00f6ln \/\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/explore\/tags\/hummustopia\/\"><strong>HUMMUSTOPIA<\/strong><\/a><\/p>\n<p>Im Vorfeld der Europawahl laden wir, die Kampagne vielfalt-vielwert der Caritas, zum Gespr\u00e4ch am K\u00f6lner Ebert-Platz. Bei lecker Essen wollen wir mit den Passantinnen und Passanten ins Gesp\u00e4ch kommen. Mit der &#8222;Zauberbindungskraft&#8220; des Hummus Auge in Auge miteinander plaudern, gerne auch streiten, anstatt wie in den sozialen Medien weit verbreitet, nur noch zu kommentieren. Der Erfinder der Zauberbindungskraft Avraham Rosenblum aus Hamburg wird die Gespr\u00e4che f\u00fchren. Sp\u00e4ter gibt es Live-Musik.<\/p>\n<p><strong>Mittwoch \u2013 5. Juni \u2013 20:30 Uhr \u2013 Swane Caf\u00e9 \u2013 Luisenstra\u00dfe 102a \u2013 Wuppertal \/ Les Soeurs Doga &amp; Viktor Marek\u00a0<\/strong><\/p>\n<p>Die Zwillingsschwestern\u00a0Haoua und Azera Doga und Viktor Marek sind mit ihrer aktuellen Single BAYIA (Fun In The Church) derzeit auf Europa-Tournee. Die Videos zeigen die beiden Schwestern in ihrer Heimat mit gro\u00dfartigem Streetdance und zusammen mit Viktor Marek in Leipzig beim Periphere Sounds Festival.\u00a0N\u00e4chten Mittwoch sind sie im Swane Caf\u00e9 mit viel Platz zum Zuh\u00f6ren und Tanzen. Der Sound und die Performance sind sehr ansteckend!<\/p>\n<p><strong><a href=\"https:\/\/www.youtube.com\/watch?v=su4eruYl_Vk\">Les Soeurs Doga_Burkina Faso<\/a>\u00a0\/\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=ezeJuBkXPco&amp;t=125s\">Les Soeurs Doga &amp; Viktor Marek<\/a><\/strong><\/p>\n<p>Im Anschluss spielen Selly Wane und ich Musik auf der Konsole.<\/p>\n<div id=\"attachment_75394\" class=\"wp-caption alignnone\" style=\"max-width: 410px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-75394 size-full\" src=\"\/wp-content\/uploads\/2024\/05\/Hummustopia.jpg\" alt=\"\" width=\"400\" height=\"400\" \/><span class=\"wp-caption-text\">Das Plakat zur Veranstaltung &#8222;Hummustopia&#8220;<\/span><\/div>\n<p><strong>Eine kleine Vorschau:<\/strong><\/p>\n<ol start=\"15\">\n<li>Juni \/ \u00d6lbergfest \/ Electric Garden DJs bei Listen Here im Est Est Est<\/li>\n<li>Juni \/ Os Barbapapas (Tropical Space Music) aus Sao Paulo \/ Live im IBZ<\/li>\n<\/ol>\n<p><strong>Euer Charles Petersohn<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charles Petersohn, Musiker, Komponist, DJ, Moderator, l\u00e4sst seine Fans in seiner Kolumne regelm\u00e4ssig an seiner k\u00fcnstlerischen und musikalischen Gef\u00fchlswelt teilhaben. Und er macht auch auf Veranstaltungen aufmerksam, bei denen er oder seine Musik-Kolleginnen und -Kollegen f\u00fcr das coole Feeling und den Groove sorgen. <\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-75390","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:59:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/75390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=75390"}],"version-history":[{"count":3,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/75390\/revisions"}],"predecessor-version":[{"id":75395,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/75390\/revisions\/75395"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=75390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=75390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=75390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}