{"id":73981,"date":"2024-04-15T16:44:25","date_gmt":"2024-04-15T14:44:25","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=73981"},"modified":"2024-04-25T08:09:45","modified_gmt":"2024-04-25T06:09:45","slug":"anne-linsel-stefan-kuehn-spannende-gaeste-bei-taltalk","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/04\/15\/anne-linsel-stefan-kuehn-spannende-gaeste-bei-taltalk\/","title":{"rendered":"Anne Linsel &#038; Stefan K\u00fchn: Spannende G\u00e4ste bei &#8222;TalTALK&#8220;"},"content":{"rendered":"<div id=\"attachment_48308\" class=\"wp-caption alignnone\" style=\"max-width: 1010px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-48308\" src=\"\/wp-content\/uploads\/2020\/04\/9107e5b5a6ec253239dc6422fc0105ab-2.jpeg\" alt=\"\" width=\"1000\" height=\"789\" \/><span class=\"wp-caption-text\">Sozialdezernent Dr. Stefan K\u00fchn &#8211; \u00a9 Stadt Wuppertal<\/span><\/div>\n<p>Seit vielen Jahren bringt Uwe Becker die Leser des Satiremagazins \u201eTitanic\u201c mit seinen Foto-Witzen zum Schmunzeln. Am 19. April feiert sein humoristisches Stadtmagazin \u201eITALien\u201c 40. Geburtstag. 2004 ver\u00f6ffentlichte Uwe Becker den Sammelband \u00a0\u201eBegrabt mein Herz in Wuppertal\u201c. Die gleichnamige Kolumne schm\u00fcckt heute noch einmal in der Woche die WZ.<\/p>\n<p>Anne Linsel ist die \u201eGrande Dame\u201c der Wuppertaler Kultur-Szene. Von 1984 bis 1989 moderierte sie das ZDF-Kulturmagazin \u201eAspekte\u201c und war Gastgeberin der ZDF-Reihe \u201e Zeugen des Jahrhunderts\u201c. Seit 1998 schreibt Anne Linsel f\u00fcr die S\u00fcddeutsche Zeitung u.a. Theaterkritiken und Artikel zu kulturpolitischen Themen. Au\u00dferdem konzeptionierte und moderierte Anne Linsel f\u00fcr den TV-Sender \u201eArte\u201c Themenabende u.a. \u00fcber Joseph Beuys, Pina Bausch, Max Ernst und war \u00fcber viele Jahre beim H\u00f6rfunk bei diversen Sendern erfolgreich t\u00e4tig. Aktuell ist sie mit Ihrem Film \u201ePinas Perlen\u201c (Gespr\u00e4che mit der ersten und zweiten Generation des Pina Bausch Ensembles) erfolgreich unterwegs.<\/p>\n<div id=\"attachment_42611\" class=\"wp-caption alignnone\" style=\"max-width: 207px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42611\" src=\"\/wp-content\/uploads\/2021\/10\/bibliographie.jpeg\" alt=\"\" width=\"197\" height=\"291\" \/><span class=\"wp-caption-text\">Anne Linsel &#8211; eine Kulturinstitution in Wuppertal &#8211; \u00a9 privat<\/span><\/div>\n<p>Marte Gr\u00e4f (34) hat sich ihren Jugendtraum erf\u00fcllt und steht mittlerweile als Stand-up-Comedian mit bekannten Gesichtern der Comedy-Szene wie Abdelkarim, Chris Tall, oder David Kebekus erfolgreich auf der B\u00fchne. In ihren Solo-Programmen greift die Remscheiderin humorvoll und pointiert Frauen-Themen auf und nimmt auch so manchen schr\u00e4gen Hype schlagfertig aufs Korn.<\/p>\n<p>Seit 24 Jahren ist Dr. Stefan K\u00fchn Dezernent f\u00fcr Soziales, Gesundheit, Schule und Integration. Dabei hat der geb\u00fcrtige K\u00f6lner und Freund des Karnevals seinen Humor nicht verloren \u2013 trotz Krisen und \u00a0schwieriger Situationen. Ende April geht er in den Ruhestand. Welche pers\u00f6nliche Bilanz zieht Dr. Stefan K\u00fchn und wie sieht er die Zukunft der Stadt Wuppertal, die f\u00fcr ihn zur zweiten Heimat geworden ist?<\/p>\n<div id=\"attachment_62657\" class=\"wp-caption alignnone\" style=\"max-width: 560px;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-62657\" src=\"\/wp-content\/uploads\/2023\/04\/JochenRauschA7_08991-2-scaled.jpg\" alt=\"\" width=\"550\" height=\"391\" \/><span class=\"wp-caption-text\">Moderator Michael Schmidt-Russnak (l.) mit Erfolgsautor Jochen Rausch\u00a0 &#8211; \u00a9 Gesellschaft Concordia<\/span><\/div>\n<p>Als Special Guest begr\u00fc\u00dfen Gabriele Sch\u00e4fer und Michael Schmidt-Russnak \u00a0Annette Marks zum K\u00fcnstlergespr\u00e4ch. Sie studierte an der Kunstakademie D\u00fcsseldorf und war Meistersch\u00fclerin bei Tony Cragg. Seit 2000 lebt und arbeitet sie in Wuppertal. Viele Jahre war Annette Marks Lehrbeauftragte an der Bergischen Universit\u00e4t. Zahlreiche ihrer Werke befinden sich im \u00f6ffentlichen Raum &#8211; wie \u00a0ihr gro\u00dfformatiges Gem\u00e4lde \u201eLos\u201c. Das Bild geh\u00f6rt zu einer Serie von vier Arbeiten, eines davon ist beispielsweise auf\u00a0der\u00a0Nordbahntrasse zu sehen.<\/p>\n<p><strong>Termin:<\/strong><\/p>\n<h4>TalTALK<\/h4>\n<p>Mit: Uwe Becker \u2013 Anne Linsel \u2013 Marte Gr\u00e4f \u2013 Dr. Stefan K\u00fchn \u2013 Annette Marks<\/p>\n<p>Moderation: Gabriele Sch\u00e4fer &amp; Michael Schmidt-Russnak<\/p>\n<p><strong>Mittwoch \u2013 24.04.2024 \u2013 19:30 Uhr \u2013 Einlass: 18:30 Uhr<\/strong><\/p>\n<p>Concordia &#8211; Werth 48 \u2013 42275 Wuppertal<\/p>\n<p><a href=\"https:\/\/www.concordia-wuppertal.de\">www.concordia-wuppertal.de<\/a><\/p>\n<p><strong>Tickets<\/strong> unter <a href=\"http:\/\/www.wuppertal-live.de\">http:\/\/www.wuppertal-live.de<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Fr\u00fchling ist da und schon bl\u00fchen den Fans der beliebten Concordia-Talk-Reihe \u201eTalTALK\u201c f\u00fcnf spannende Gespr\u00e4che. Das Moderatoren-Duo Gabriele Sch\u00e4fer und Michael Schmidt-Russnak begr\u00fc\u00dft am Mittwoch (24.04.) den Satiriker Uwe Becker, Kultur-Legende Anne Linsel, Comedian Marte Gr\u00e4f, den scheidenden Sozialdezernenten Dr. Stefan K\u00fchn und die Malerin Annette Marks.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-73981","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:59:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/73981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=73981"}],"version-history":[{"count":7,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/73981\/revisions"}],"predecessor-version":[{"id":73988,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/73981\/revisions\/73988"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=73981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=73981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=73981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}