{"id":71683,"date":"2024-01-08T10:12:30","date_gmt":"2024-01-08T09:12:30","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=71683"},"modified":"2024-01-10T10:12:43","modified_gmt":"2024-01-10T09:12:43","slug":"musikalische-kaffeetafel-die-stimme-der-violine","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2024\/01\/08\/musikalische-kaffeetafel-die-stimme-der-violine\/","title":{"rendered":"\u201eMusikalische Kaffeetafel\u201c: Die Stimme der Violine"},"content":{"rendered":"<div id=\"attachment_71686\" class=\"wp-caption alignnone\" style=\"max-width: 1736px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71686 size-full\" src=\"\/wp-content\/uploads\/2024\/01\/240121_Musikalische-Kaffeetafel-c-Bettina-Osswald.jpg\" alt=\"\" width=\"1726\" height=\"1272\" \/><span class=\"wp-caption-text\">Annika Boos f\u00fchrt durch das Programm &#8211; \u00a9 Bettina Osswald<\/span><\/div>\n<p>Das Publikum darf sich auf Romantik, Drama und Sch\u00f6nheit freuen. F\u00fcr das leibliche Wohl sorgt die Culinaria, mit leckerem Kuchen und ,,Kaffee\/Kakao bodenlos\u201c.<\/p>\n<p>Durch das Programm f\u00fchrt Sie Annika Boos.<\/p>\n<p><strong>Termin:<\/strong><\/p>\n<h4>&#8222;Musikalische Kaffeetafel&#8220;<\/h4>\n<p><strong>Die Stimme der Violine<\/strong><\/p>\n<p>Sonntag &#8211; 21.01.2024 &#8211; 15:30 Uhr<\/p>\n<p>Historische Stadthalle -Mendelssohn Saal<\/p>\n<p>Karten sind bei der KulturKarte &#8211; Tel. 0202\/ 56 37 666 erh\u00e4ltlich.<\/p>\n<p>24 \u20ac inkl. Kuchen und \u201eKaffee\/Kakao bodenlos\u201c<\/p>\n<p>Kinder bis zu 14 Jahren zahlen 12 \u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Stimme der Geige kann unglaublich vielseitig sein. Studierende aus der Violinenklasse von Prof. Michael Foyle f\u00fchren Bei der Veranstaltung &#8222;Musikalische Kaffeetafel&#8220; am Sonntag (21.01. &#8211; 15:30 Uhr) im Mendelssohn Saal der Historischen Stadthalle kontrastreiche Werke auf und stellen dabei gesangliche Qualit\u00e4t ebenso wie virtuose F\u00e4higkeiten unter Beweis.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-71683","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:58:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/71683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=71683"}],"version-history":[{"count":3,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/71683\/revisions"}],"predecessor-version":[{"id":71687,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/71683\/revisions\/71687"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=71683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=71683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=71683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}