{"id":70952,"date":"2023-12-07T15:55:44","date_gmt":"2023-12-07T14:55:44","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=70952"},"modified":"2023-12-18T09:52:24","modified_gmt":"2023-12-18T08:52:24","slug":"bourbon-street-sorgen-fuer-eine-rockige-bescherung","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2023\/12\/07\/bourbon-street-sorgen-fuer-eine-rockige-bescherung\/","title":{"rendered":"&#8222;Bourbon Street&#8220; sorgen f\u00fcr eine rockige Bescherung"},"content":{"rendered":"<div id=\"attachment_70954\" class=\"wp-caption alignnone\" style=\"max-width: 1052px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70954\" src=\"\/wp-content\/uploads\/2023\/12\/395280468_1479781669438864_935141738916824442_n.jpg\" alt=\"\" width=\"1042\" height=\"723\" \/><span class=\"wp-caption-text\">Jubel nach einem erfolgreichen Konzert: Die Wuppertaler Hardrock-Cover-Bans &#8222;Bourbon Street&#8220; &#8211; \u00a9 OMK &#8211; Oliver Klamke<\/span><\/div>\n<p>Begonnen hat 1991 alles im ehemaligen \u201eAbseits-\/\u201eRoots\u201c-Club, sp\u00e4ter im \u201eOutback\u201c. Seit vielen Jahren ist inzwischen der LCB \u2013 Barmen Heimspiel-Arena f\u00fcr das legend\u00e4re Christmas-Rock-Konzert. Die Jahre gehen, die Song-Klassiker bleiben. Auch diesmal stehen wieder Hardrock-Hymnen von \u201eA\u201c wie \u201eAccept\u201c bis \u201eZ\u201c wie \u201eZZ Top\u201c auf der Setlist.<\/p>\n<p>Alle Jahre wieder ist auch ein Support-Act dabei. Als Special Guest tritt am Samstag \u201eBad Stash\u201c auf, die befreundete Band um die Wuppertaler S\u00e4ngerin Liane Vollmer.<\/p>\n<p>Alle, die vor den beschaulichen Festtagen noch einmal abrocken wollen, sollten den 16.12. in ihrem Smartphone-Kalender blocken.<\/p>\n<div id=\"attachment_70957\" class=\"wp-caption alignnone\" style=\"max-width: 460px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70957\" src=\"\/wp-content\/uploads\/2023\/12\/borbon-street-2015.jpg\" alt=\"\" width=\"450\" height=\"161\" \/><span class=\"wp-caption-text\">Die Rock-Musiker von &#8222;Bourbon Street&#8220; &#8211; \u00a9 Bourbon Street<\/span><\/div>\n<p><strong>Termin:<\/strong><\/p>\n<h4>\u201e32th anniversary X-mas Party&#8220;<\/h4>\n<p><strong>BOURBON STREET<\/strong><\/p>\n<p>Special Guests: \u201cBad Stash\u201d<\/p>\n<p><strong>&#8222;Bourbon Street&#8220;<\/strong> sind: Stefan Mageney (Gesang) . Henning Wanner (Keyboards) \u2013 Wolla B\u00f6hm (Schlagzeug) &#8211; Thomas \u201cBodo\u201d Smuszynski (Ba\u00df) \u2013 Peter Szigeti (Gitarre)<\/p>\n<p><strong>Samstag<\/strong> &#8211; 16.12.2023 \u2013 20:00 Uhr (Einlass: 19:00 Uhr)<\/p>\n<p>Live Club Barmen (LCB) &#8211; Geschwister-Scholl-Platz 4-6 &#8211; 42275 Wuppertal<\/p>\n<p>Tickets unter <a href=\"http:\/\/www.wuppertal-live.de\">http:\/\/www.wuppertal-live.de<\/a><\/p>\n<p>Es ist sicher ratsam vom Vorverkauf Gebrauch zu machen<\/p>\n<p><strong>Link zur Webseite von &#8222;Bourbon Street&#8220;:<\/strong><\/p>\n<p><a href=\"http:\/\/www.bourbon-street-online.de\">http:\/\/www.bourbon-street-online.de<\/a><\/p>\n<p><strong>Link zur Webseite des LCB:<\/strong><\/p>\n<p><a href=\"http:\/\/www.liveclub-barmen.de\/\">www.liveclub-barmen.de<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle Jahre wieder rocken Stefan Mageney und seine Band \u201eBourbon Street\u201c kurz vor Weihnachten so richtig ab. Diesmal bereits zum 32. Mal! Die \u201e32th anniversary X-mas Party\u201d geht am Samstag (16.12.) im Live Club Barmen (LCB) \u00fcber die B\u00fchne.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-70952","post","type-post","status-publish","format-standard","hentry","category-kultur"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:58:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/70952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=70952"}],"version-history":[{"count":6,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/70952\/revisions"}],"predecessor-version":[{"id":70960,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/70952\/revisions\/70960"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=70952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=70952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=70952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}