{"id":69274,"date":"2023-10-25T14:10:40","date_gmt":"2023-10-25T12:10:40","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=69274"},"modified":"2023-10-25T14:10:40","modified_gmt":"2023-10-25T12:10:40","slug":"barmenia-fairplay-pokal-fuer-sc-breite-burschen-barmen","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2023\/10\/25\/barmenia-fairplay-pokal-fuer-sc-breite-burschen-barmen\/","title":{"rendered":"Barmenia-Fairplay-Pokal f\u00fcr SC Breite Burschen Barmen"},"content":{"rendered":"<div id=\"attachment_69277\" class=\"wp-caption alignnone\" style=\"max-width: 2570px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-69277 size-full\" src=\"\/wp-content\/uploads\/2023\/10\/Gewinner-Fairplay-Pokal1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1686\" \/><span class=\"wp-caption-text\">Andreas Eurich mit Heiner Fragemann, Stefan Langerfeld, R\u00fcdiger Vollborn sowie den Preistr\u00e4gern des Barmenia-Fairplay-Pokals &#8211; \u00a9 Barmenia Versicherungen<\/span><\/div>\n<p>Im Jugendwettbewerb freuten sich die Junioren des Sportvereins Blau-Wei\u00df Langerberg \u00fcber die Auszeichnung. Ein unterhaltsamer Talk im Rahmen der feierlichen Siegerehrung in den Barmenia Hauptverwaltungen unter Beteiligung des Ex-Bundesligaprofis R\u00fcdiger Vollborn (Bayer 04 Leverkusen) unterstrich die Bedeutung von Fairness im Amateurfu\u00dfball.<\/p>\n<p>Gro\u00dfer Jubel im Stadtteil Heckinghausen: Die Breiten Burschen gewannen den Barmenia-Fairplay-Pokal im Hauptwettbewerb. Der Verein kann auf eine erfolgreiche Historie im Barmenia-Fairplay-Pokal zur\u00fcckblicken. Bereits f\u00fcnfmal, darunter zweimal die Junioren und dreimal die Senioren, gewannen die Fu\u00dfballer aus Heckinghausen den Preis des fairsten Vereins .<\/p>\n<p>Die Tabelle der vergangenen Saison konnten die Breiten Burschen mit weniger als einem Punkt (0,75) Vorsprung vor dem Mettmann-Sport e.V. abschlie\u00dfen. Knapp dahinter erreichte Fortuna Wuppertal den dritten Platz im Kreis derjenigen, die f\u00fcr Fairness auf und neben dem Platz gepunktet haben.<\/p>\n<p>Im Jugendwettbewerb feierte Blau-Wei\u00df Langenberg seinen dritten Sieg in der Barmenia-Fairplay-Pokal-Geschichte. Der 1964 gegr\u00fcndete Verein f\u00fchrte die Abschlusstabelle mit einem hauchd\u00fcnnen Vorsprung mit 94,17 Punkten an.<\/p>\n<h4>SV J\u00e4gerhaus-Linde auf Platz 2 im Jugendwettbewerb<\/h4>\n<p>Mit 93,71 Punkten erreichte der SV J\u00e4gerhaus-Linde den zweiten Platz. Die Junioren von \u201emettmann-sport\u201c schlie\u00dfen die vergangene Saison erneut auf Platz drei ab. Somit k\u00f6nnen sich die Sportler aus Mettmann dieses Jahr sogar \u00fcber zwei Pl\u00e4tze auf den Podesten freuen.<\/p>\n<p>Die Top 3-Vereine im Haupt- und Jugendwettbewerb wurden in den Barmenia-Hauptverwaltungen mit Spenden und Urkunden f\u00fcr ihre sportlich-fairen Leistungen der Saison 2022\/23 im Rahmen einer feierlichen Siegerehrung ausgezeichnet.<\/p>\n<p>Im Vorfeld der Ehrung hob ein lebendiger Talk die Bedeutung von Fairness auf und neben dem Rasen hervor. Hierzu tauschten sich zu Themen wie Fairness in Wirtschaft und Politik sowie der neue Spielform im Kinderfu\u00dfball aus: R\u00fcdiger Vollborn (Ex-Profifu\u00dfballer des Bayer 04 Leverkusen), Stefan Langerfeld (Vorsitzender des Fu\u00dfballkreises Wuppertal \/ Niederberg), Heiner Fragemann (1. stellvertretender B\u00fcrgermeister der Stadt Wuppertal in Vertretung f\u00fcr Uwe Schneidewind, Schirmherr) und Andreas Eurich (Vorstandsvorsitzender Barmenia Versicherungen). Moderiert wurde der Talk von Saskia K\u00f6cke, PR-Managerin der Barmenia Versicherungen.<\/p>\n<p>Andreas Eurich: \u201eGerade in der momentanen Lage sind die sechs ausgezeichneten Vereine beim Thema Fairness sowohl auf, wie neben dem Platz Vorbilder. Wir als Barmenia unterst\u00fctzen dieses Projekt sehr gerne, da es wichtige Werte wie Ehrlichkeit, Vertrauen, Kameradschaft und Solidarit\u00e4t best\u00e4rkt. Diese sind im Sport genauso relevant wie in der Gesellschaft. Im Namen aller Barmenianer und Barmenianerinnen dr\u00fccke ich den teilnehmenden Vereinen die Daumen f\u00fcr die aktuell laufende 48. Saison des Barmenia-Fairplay-Pokals und w\u00fcnsche viel Erfolg und Fairness.\u201c<\/p>\n<p>Als besonders faire Vereine wurden f\u00fcr die Saison 2022\/2023 geehrt:<\/p>\n<p><strong>Hauptwettbewerb<\/strong><\/p>\n<p>1. Platz: SC Breite Burschen Barmen 1996 e.V. (96,75 Punkte)<\/p>\n<p>2. Platz: Mettmann-Sport e.V. (96,00 Punkte)<\/p>\n<p>3. Platz: TSV Fortuna Wuppertal e.V. (91,80 Punkte)<\/p>\n<p><strong>Jugendwettbewerb<\/strong><\/p>\n<p>1. Platz: Blau-Wei\u00df Langenberg 1964 e.V. (94,17 Punkte)<\/p>\n<p>2. Platz: SV J\u00e4gerhaus-Linde (93,71 Punkte)<\/p>\n<p>3 .Platz: Mettmann-Sport (92,86 Punkte)<\/p>\n<p>Alle Amateurvereine des Fu\u00dfballkreises Wuppertal\/Niederberg nehmen automatisch am Haupt- sowie am Jugendwettbewerb teil, der unter dem Motto: Chancengleichheit, Sportlichkeit und Vereinsarbeit bereits zum 47. Mal seit 1976 vergeben wird. Unabh\u00e4ngig von der Spielst\u00e4rke haben alle Mannschaften die Chance, den Pokal zu gewinnen. Schirmherr des Fairplay-Pokals ist der Oberb\u00fcrgermeister der Stadt Wuppertal, Uwe Schneidewind.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr ihre sportlich-fairen Leistungen in der abgelaufenen Saison 2022\/23 wurden die Siegervereine des 47. Barmenia-Fairplay-Pokals geehrt: Die Breiten Burschen Barmen erreichten mit weniger als einem Punkt Vorsprung den ersten Platz und erhielten damit die begehrte Troph\u00e4e im Hauptwettbewerb.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-69274","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:58:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/69274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=69274"}],"version-history":[{"count":6,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/69274\/revisions"}],"predecessor-version":[{"id":69281,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/69274\/revisions\/69281"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=69274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=69274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=69274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}