{"id":64960,"date":"2023-04-24T18:40:43","date_gmt":"2023-04-24T16:40:43","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=64960"},"modified":"2023-05-04T10:17:18","modified_gmt":"2023-05-04T08:17:18","slug":"schwebebahnhof-doeppersberg-erstrahlt-in-neuem-glanz","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2023\/04\/24\/schwebebahnhof-doeppersberg-erstrahlt-in-neuem-glanz\/","title":{"rendered":"Schwebebahnhof D\u00f6ppersberg erstrahlt in neuem Glanz"},"content":{"rendered":"<div id=\"attachment_64963\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-64963\" src=\"\/wp-content\/uploads\/2023\/04\/wsw.doeppersberg_04-2-1024x719.jpeg\" alt=\"\" width=\"1024\" height=\"719\" \/><span class=\"wp-caption-text\">Vor dem Restaurant im renovierten Schwebebahnhof D\u00f6ppersberg: (V.l.) WSW-Arbeitsdirektor Markus Schlomski, WSW mobil-Gesch\u00e4ftsf\u00fchrerin Sabine Schnake, Oberb\u00fcrgermeister Uwe Schneidewind, Projektleiter D\u00f6ppersberg Andreas Klein, WSW-Vorstandsvorsitzender Markus Hilkenbach &#8211; \u00a9 Wuppertaler Stadtwerke<\/span><\/div>\n<p>Die WSW haben Ende 2019 mit dem Umbau der historischen Station, die t\u00e4glich von rund 16.000 Fahrg\u00e4sten genutzt wird, begonnen. Ziel war es, das Gesamterscheinungsbild des Stationsgeb\u00e4udes aufzuwerten und in die Neugestaltung des D\u00f6ppersbergs zu integrieren.<\/p>\n<p>Au\u00dferdem sollten die Vermietungsfl\u00e4chen der Erdgeschosspassage neu organisiert werden. Eine zusammenh\u00e4ngende Fl\u00e4che m hinteren Teil des Erdgeschosses steht jetzt f\u00fcr Gastronomie zur Verf\u00fcgung. Der bis dahin bestehende Passagendurchgang entf\u00e4llt. Die angrenzende westliche Br\u00fccke dient als Au\u00dfenterrasse.<\/p>\n<h4>Bauarbeiten dauerten drei j\u00e4hre<\/h4>\n<p>Im Laufe der letzten drei Jahre haben die WSW das gesamte Geb\u00e4ude bearbeitet. Das Dach erhielt eine neue Abdichtung und Schiefereindeckung. Eine neue Funkmastanlage \u00fcbertr\u00e4gt Steuersignale an die Schwebebahnwagen.<\/p>\n<p>Der \u00fcberfl\u00fcssig gewordene Leitstand in der Bahnsteigebene existiert nicht mehr. Unter Beachtung des Denkmalschutzes sorgt eine deutlich lichtdurchl\u00e4ssigere Verglasung der Fensterfl\u00e4chen f\u00fcr mehr Helligkeit. Der komplette Innenraum erhielt einen neuen Farbanstrich.<\/p>\n<p>Die Gleiswanne auf der Bahnsteigebene musste neu abgedichtet werden. Die Aufzugstechnik samt Schachteinhausung der Fahrst\u00fchle wird derzeit noch erneuert, um weiterhin zuverl\u00e4ssig den barrierefreien Zugang der Bahnsteige zu gew\u00e4hrleisten. All das im laufenden Betrieb, im Schutze eines quasi \u201efliegenden\u201c und damit sehr anspruchsvollen und aufw\u00e4ndigen Innenger\u00fcsts.<\/p>\n<p>Das Erdgeschoss wurde fast komplett entkernt, die alte technische Geb\u00e4udeausstattung entfernt und durch eine neue ersetzt, dazu geh\u00f6ren Fernw\u00e4rmeheizung, moderne LED-Lichttechnik sowie eine komplett neue Raumlufttechnik mit temperaturgesteuerter Lufterw\u00e4rmung bzw. -k\u00fchlung.<\/p>\n<p>Neu ist auch die Fettabscheideanlage in der Restaurantk\u00fcche. Die denkmalgesch\u00fctzten Gesch\u00e4ftsfassaden in der Passage erstrahlen in neuem Glanz. Im gesamten Erd- und Kellergeschoss wurde der Brandschutz \u00fcberarbeitet.<\/p>\n<div id=\"attachment_64965\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-64965\" src=\"\/wp-content\/uploads\/2023\/04\/wsw.doeppersberg_06-2-1024x683.jpeg\" alt=\"\" width=\"1024\" height=\"683\" \/><span class=\"wp-caption-text\">im renovierten Bahnhof D\u00f6ppersberg: (V.l.): WSW-Arbeitsdirektor Markus Schlomski, WSW mobil-Gesch\u00e4ftsf\u00fchrerin Sabine Schnake, Oberb\u00fcrgermeister Uwe Schneidewind und WSW-Vorstandsvorsitzender Markus Hilkenbach &#8211; \u00a9 Wuppertaler Stadtwerke<\/span><\/div>\n<p>Auch unter der Station tat sich eine Menge. Ein 1300 Quadratmeter gro\u00dfes Arbeitsger\u00fcst in der Wupper erm\u00f6glichte die notwendigen Sandstrahlarbeiten und die Erneuerung der Ver- und Entsorgungsleitungen an der Untersicht.<\/p>\n<p>\u201eDas Ergebnis kann sich sehen lassen. Die Station zeigt sich verj\u00fcngt und hat doch nichts von ihrem historischen Charme verloren. Ein tolles Eingangstor zur Stadt\u201c, zieht Stadtwerke-Chef Markus Hilkenbach Bilanz. Dazu verhilft ein belebtes Erdgeschoss. Am Freitag, 28. April, er\u00f6ffnet als erster Gastro-Mieter das Restaurant \u201e60 seconds to napoli\u201c und kurz danach in der letzten Mietfl\u00e4che das Gastronomie-Unternehmen Cinnamood.<\/p>\n<p>Damit ist die Modernisierung der Schwebebahnstation fast abgeschlossen. In den n\u00e4chsten Wochen f\u00fchren die WSW noch Restarbeiten aus. Der Aufzug S\u00fcd (Fahrtrichtung Oberbarmen) soll am 6. Mai in Betrieb gehen. Danach wird als letztes der Nordaufzug (Fahrtrichtung Vohwinkel) f\u00fcr etwa 11 Wochen erneuert.<\/p>\n<p>Die Modernisierung der Station hat deutlich l\u00e4nger gedauert als geplant. Aus den urspr\u00fcnglich geplanten anderthalb Jahren wurden dreieinhalb Jahre. Daf\u00fcr gibt es Gr\u00fcnde.<\/p>\n<h4>Corona-Pandemie sorgte f\u00fcr Lieferschwierigkeiten<\/h4>\n<p>Erstens: Die Entkernung deckte eine deutlich schlechtere Bausubstanz mit teilweise gravierenden Statikm\u00e4ngeln auf. F\u00fcr die Sanierung der Stahlbetonkonstruktion musste unter gutachterlicher Begleitung der Ruhruniversit\u00e4t Bochum eine Sonderl\u00f6sung gefunden werden. Allein dies hat fast ein Jahr in Anspruch genommen.<\/p>\n<p>Auch die Corona-Pandemie sorgte mit Materiallieferschwierigkeiten und krankheitsbedingten Ausf\u00e4llen von Mitarbeitenden f\u00fcr deutliche Verz\u00f6gerungen. Schlie\u00dflich kamen die Arbeiten durch das Hochwasser im Sommer 2021 teilweise zum Erliegen. Die Wassermassen zerst\u00f6rten das komplette Untersichtger\u00fcst.<\/p>\n<p>Die l\u00e4ngere Bauzeit und weitere Faktoren machten das Projekt zudem teurer. Die Kosten stiegen von urspr\u00fcnglich rd. 5,1 Millionen Euro auf am Ende knapp 7,7 Millionen Euro.<\/p>\n<p>Die Schwebebahnstation D\u00f6ppersberg wurde 1925\/26 erbaut, nach dem die bis dahin bestehende Haltestelle durch das immer h\u00f6her werdende Fahrgastaufkommen im Zentrum Elberfelds zu klein geworden war. Das neue Stationsgeb\u00e4ude wurde im Zeitgeist der 20er Jahre errichtet. Das fast 100j\u00e4hrige Geb\u00e4ude wurde mehrfach umgebaut, zuletzt Mitte der 90er Jahre, und bereits in den 80er Jahren unter Denkmalschutz gestellt.<\/p>\n<p><strong>Link zur Homepage der Wuppertaler Stadtwerke:\u00a0<\/strong><\/p>\n<p><a href=\"http:\/\/www.wsw-online.de\">http:\/\/www.wsw-online.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sogst wie neu! Die Renovierung der Schwebebahnstation Hauptbahnhof ist fast beendet. Kurz vor der Er\u00f6ffnung der Gastronomie haben sich Oberb\u00fcrgermeister Uwe Schneidewind und die Gesch\u00e4ftsf\u00fchrung der WSW mobil im Geb\u00e4ude umgesehen.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-64960","post","type-post","status-publish","format-standard","hentry","category-wuppertal"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:42:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/64960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=64960"}],"version-history":[{"count":7,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/64960\/revisions"}],"predecessor-version":[{"id":64969,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/64960\/revisions\/64969"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=64960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=64960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=64960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}