{"id":61182,"date":"2023-02-15T11:01:46","date_gmt":"2023-02-15T10:01:46","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=61182"},"modified":"2023-02-22T13:56:53","modified_gmt":"2023-02-22T12:56:53","slug":"wuppertaler-sv-24-niederlage-in-unterzahl","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2023\/02\/15\/wuppertaler-sv-24-niederlage-in-unterzahl\/","title":{"rendered":"Wuppertaler SV:  2:4-Niederlage in Unterzahl"},"content":{"rendered":"<div id=\"attachment_61186\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-61186\" src=\"\/wp-content\/uploads\/2023\/02\/Classen-18-02-2023-143-2-1024x678.jpg\" alt=\"\" width=\"1024\" height=\"678\" \/><span class=\"wp-caption-text\">Ein entt\u00e4uschter Torj\u00e4ger Serhat-Semih G\u00fcler nach der Niederlage gegen M\u00f6nchengladbach &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<p>Elf Spiele war der WSV ungeschlagen geblieben, aber die U23 von Borussia M\u00f6nchengladbach stoppte diese Serie eiskalt.\u00a0\u00a0Bereits in der 10. Spielminute ert\u00f6nte die Tor-Hymne im Stadion am Zoo.<span class=\"Apple-converted-space\">\u00a0Serhat-Semih\u00a0<\/span>G\u00fcler hatte in Tor getroffen. Doch das Tor z\u00e4hlte nicht, das Schiedsrichtergespann hatte eine Abseitsstellung erkannt.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>In der 26. Minute fiel dann wirklich das 1:0 f\u00fcr den WSV. Torsch\u00fctze: Serhat-Semih G\u00fcler. Diesmal war alles regelkonform. Bis zur Pause blieb der WSV tonangebend. M\u00fcller probierte es zweimal aus der zweiten Reihe.<\/p>\n<p>Und so ging es auf Seiten des WSV mit einer guten Stimmung in die Kabine. Das sollte sich aber schnell \u00e4ndern. Noah Salau hatte bereits in der ersten Halbszeit wegen eines taktischen Fouls die gelbe Karte gesehen. In der 47. Minute stoppte er<span class=\"Apple-converted-space\">\u00a0 <\/span>seinem Gegenspieler am eigenen Strafraum mit einem Ziehen an der Schulter. Der Schiedsrichter z\u00fcckte die gelbe und die rote Karte. Der WSV nur noch zu zehnt.<\/p>\n<p>Das Spiel drehte sich jetzt. Der M\u00f6nchengladbacher Conor No\u00df erzielte in der 48. Minute das 1:1. Dennoch blieb der der WSV bei seiner offensiven Spielweise. Doch das wurde leider nicht belohnt. Mit einem Doppelschlag zogen die G\u00e4ste auf 1:3 davon : Kaan Kurt traf zum 1:2 (72.) und Sanches Yvandro Borges erzielte das 1:3 (74.). Durch Lion Schweers Anschlusstreffer zum 2:3 in der 77. Minute keimte noch einmal etwas Hoffnung beim WSV \u00a0auf. Doch No\u00df machte mit seinem 2:4 (84.) den Deckel endg\u00fcltig drauf.<\/p>\n<div id=\"attachment_61187\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-61187\" src=\"\/wp-content\/uploads\/2023\/02\/Classen-18-02-2023-075-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><span class=\"wp-caption-text\">Tobias Peitz stemmte sich wie seine Kameraden aifopferungsvoll gegen die Niederlage &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<p>Trotz der Niederlage hat der WSV nicht entt\u00e4uscht, sondern mit zehn Mann aufopferungsvoll gek\u00e4mpft. Das honorierten auch die Zuschauer.<span class=\"Apple-converted-space\">\u00a0Mit 42 Punkten belegen die\u00a0Wuppertaler weiterhin den 2. Tabellenplatz in der Regionalliga-West. 3. ist die die U23 von Borussia\u00a0M\u00f6nchengladbach mit\u00a0ebenfalls 42 Z\u00e4hlern, aber mit einem um ein Tor schlechteren\u00a0<\/span>Torverh\u00e4ltnis.<\/p>\n<p>Am n\u00e4chsten Samstag (25.02.) muss der WSV um 14 Uhr beim SV Straelen antreten.<\/p>\n<div id=\"attachment_61188\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-61188\" src=\"\/wp-content\/uploads\/2023\/02\/Classen-18-02-2023-050-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><span class=\"wp-caption-text\">Um jeden Zentimeter wurde gek\u00e4mpft: Wie hier Kevin Hagemann (Nr. 9) und im Hintergrund Tobias Peitz &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<h4>Wuppertaler SV &#8211; Borussia M\u00f6nchengladbach U23 2:4 (1:0)<\/h4>\n<p><strong>Aufstellung des WSV:<\/strong><\/p>\n<p>Franz Langhoff &#8211; Philipp Hanke (63. Moritz Montag) &#8211; Durim Berisha &#8211; Lion Schweers &#8211; Noah Salau &#8211; Lukas Demming (68. Justus Henke) &#8211; Tobias Peitz (79. Roman Prokoph) &#8211; Bastian M\u00fcller &#8211; Marco Stiepermann (74. Marco K\u00f6nigs) &#8211; Kevin Hagemann &#8211; Serhat-Semih G\u00fcler<\/p>\n<p><strong>Tore:<\/strong> 1:0 G\u00fcler (26.) &#8211; 1:1 No\u00df (48.) &#8211; 1:2 Kurt (72.) &#8211; 1:3 Borges Sanches (74.) &#8211; 2:3 Schweers (77.) &#8211; 2:4 No\u00df (84.)<\/p>\n<h4>Gaetano Manno verl\u00e4sst den WSV<\/h4>\n<div id=\"attachment_61228\" class=\"wp-caption alignnone\" style=\"max-width: 554px;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-61228\" src=\"\/wp-content\/uploads\/2023\/02\/Classen-25-06-2022-468-1024x708.jpg\" alt=\"\" width=\"544\" height=\"376\" \/><span class=\"wp-caption-text\">Gaetano Manno &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<p>Gaetano Manno, ehemaliger Kapit\u00e4n des \u00a0Wuppertaler SV und zuletzt Chef-Scout des Regionalligisten, hat seinen Job aus pers\u00f6nlichen Gr\u00fcnden \u00a0zur Verf\u00fcgung gestellt. Gaetano verl\u00e4sst den Verein, weil er sich beruflich ver\u00e4ndern m\u00f6chte. Die Leitung des WSV kam diesem Wunsch nach.<\/p>\n<p>Gaetano Manno verabschiedet sich: \u201cIch m\u00f6chte mich bei den WSV-Fans, Stephan K\u00fcsters und Friedhelm Runge f\u00fcr das entgegengebrachte Vertrauen und die Zusammenarbeit bedanken.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elf Spiele war der Wuppertaler SV ungeschlagen. Doch jetzt hat es den Regionalligisten erwischt. Gegen die U23 von Borussia M\u00f6nchengladbach unterlag der WSV mit 2:4 (1:0). Und trotzdem haben Stiepermann &#038; Co. nicht entt\u00e4uscht, mussten sie doch ab der 48. Minute mit zehn Mann spielen. Eine Personalie: Chef-Scout Gaetano Mann verl\u00e4sst den WSV.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-61182","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:43:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/61182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=61182"}],"version-history":[{"count":8,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/61182\/revisions"}],"predecessor-version":[{"id":61229,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/61182\/revisions\/61229"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=61182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=61182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=61182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}