{"id":57379,"date":"2022-12-02T08:57:57","date_gmt":"2022-12-02T07:57:57","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=57379"},"modified":"2022-12-08T14:17:43","modified_gmt":"2022-12-08T13:17:43","slug":"torhueter-rudeck-brachte-melsunger-zur-verzweiflung","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2022\/12\/02\/torhueter-rudeck-brachte-melsunger-zur-verzweiflung\/","title":{"rendered":"Torh\u00fcter Rudeck brachte Melsunger zur Verzweiflung"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div id=\"attachment_57177\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-57177\" src=\"\/wp-content\/uploads\/2022\/11\/Frederik-Ladefoged-classen-2-1024x662.jpg\" alt=\"\" width=\"1024\" height=\"662\" \/><span class=\"wp-caption-text\">Frederik Ladefoged erzielte gegen Melsungen zwei Treffer &#8211; \u00a9 Archivfoto Jochen Classen<\/span><\/div>\n<p>Die Deckung der Lo\u0308wen legte den Grundstein zum historischen Erfolgserlebnis. Nach neun erfolglosen Bundesliga-Partien und einer Pokal-Niederlage durfte der BHC im elften Versuch mit einem guten Gefu\u0308hl nach Hause fahren.<\/p>\n<p>Dabei machte der BHC unmittelbar nach dem Schlusspfiff gar nicht den Eindruck, dass er sich u\u0308ber den Za\u0308hler freuen wu\u0308rde. Tom Kare Nikolaisen hatte bei Andre\u0301 Gomes&#8216; letztem Versuch den Ball im Gesicht abbekommen. Die Kugel tippte ins Aus, die Sirene erto\u0308nte. Zufriedenheit und ein wenig Jubel kehrte erst nach und nach ein &#8211; schlie\u00dflich war die Chance gro\u00df gewesen, das Spiel sogar zu gewinnen.<\/p>\n<p>In der zweiten Halbzeit dominierte der BHC mit einer extrem gut eingestellten Deckung das Geschehen. Die Melsunger rieben sich auf, kamen kaum zu richtig zwingenden Gelegenheiten. Und wenn sie da waren, war Christopher Rudeck sehr ha\u0308ufig zur Stelle.<\/p>\n<p>Der Torhu\u0308ter parierte nicht nur Schu\u0308sse aus neun Metern, sondern blieb auch bei Abschlu\u0308ssen von Au\u00dfen sowie im Gegensto\u00df Sieger. Dazu kam Peter Johannesson fu\u0308r einen Siebenmeter aufs Feld &#8211; und auch er entscha\u0308rfte gegen Aidenas Malasinskas. All das zusammen fu\u0308hrte zu einer Halbzeit mit nur sieben Gegentoren &#8211; viel besser geht es kaum.<\/p>\n<div id=\"attachment_33863\" class=\"wp-caption alignnone\" style=\"max-width: 561px;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-33863\" src=\"\/wp-content\/uploads\/2021\/03\/9f20eac3d624ba3eca48c353ad6da56a-2.jpg\" alt=\"\" width=\"551\" height=\"379\" \/><span class=\"wp-caption-text\">Torh\u00fcter Christopher Rudeck war wieder ein gro\u00dfer R\u00fcckhalt &#8211; \u00a9 BHC 06<\/span><\/div>\n<p>Dass es trotzdem nicht zum Sieg reichte, lag zum einen am ebenfalls guten Nebojsa Simic im MT- Tor sowie seiner Abwehr. Auch die Lo\u0308wen taten sich schwer, hatten bei einer 20:18-Fu\u0308hrung zwar die Chance zur Vorentscheidung, doch die Umstellung der nordhessischen Deckung auf eine 5:1- Variante stoppte den eigentlich in diesem Moment guten BHC-Lauf.<\/p>\n<p>Beim 20:20 reagierte BHC- Coach Jamal Naji und brachte im Angriff den siebten Feldspieler. Das Rezept ging auf. Fabian Gutbrod schraubte seine Bilanz auf sechs Tore hoch und war damit fu\u0308r die letzten vier BHC-Tore des Spiels in der Crunchtime verantwortlich.<\/p>\n<p>Wa\u0308re in den letzten fu\u0308nf Minuten keine Unterzahl-Situation dazwischen gekommen, in der die Lo\u0308wen sich zwei Tore von der Au\u00dfenposition gefangen haben, ha\u0308tten sie am Ende wohl noch lauter gejubelt.<\/p>\n<p>Bereits in der ersten Halbzeit waren die Ga\u0308ste ordentlich gestartet. Ohne den kurzfristig mit einer Bauchmuskelverletzung ausgefallenen Linus Arnesson u\u0308bernahm Tomas Babak erfolgreich die Regie. Nach einem guten Beginn mit scho\u0308nen Toren von Djibril M&#8217;Bengue setzten sich die Ga\u0308ste kurz auf 7:4 ab.<\/p>\n<p>Auch hier reagierte Naji mit einer Auszeit, die Vera\u0308nderung brachte. Die Abwehr packte in der Folge noch konsequenter zu und verhalf zur fru\u0308hen Wende. Mehrere Male glichen die Bergischen vor der Pause aus &#8211; durch Babak, Lukas Stutzke und Noah Beyer. Trotzdem retteten sich die Nordhessen noch mit einem 15:13-Vorsprung in die Halbzeit.<\/p>\n<div id=\"attachment_41179\" class=\"wp-caption alignnone\" style=\"max-width: 396px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-41179 \" src=\"\/wp-content\/uploads\/2021\/09\/210902_eh_Autogrammkarte_Gutbrod-3.jpg\" alt=\"\" width=\"386\" height=\"320\" \/><span class=\"wp-caption-text\">Fabian Gutbrod war mit sechs Toren bester BHC-Werfer &#8211; \u00a9 BHC 06<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Der hatte danach nicht mehr lange Bestand. Tom Kare Nikolaisen traf zum 15:15, beim 17:16 zur ersten Fu\u0308hrung und war am letzten Schuss des Gegners dran. Sein Wille, die Rothenbach-Halle nicht als Verlierer zu verlassen, stand beispielhaft fu\u0308r das gesamte Team.<\/p>\n<h4>Stimmen zum Spiel<\/h4>\n<p><strong>Jamal Naji:<\/strong> \u201eDer Punkt fu\u0308hlt sich wirklich gut an. Aktuell haben wir einige Probleme mit einigen Verletzungen, weswegen Linus Arnesson und Csaba Szu\u0308cs nicht mit angereist sind und hatten in den letzten Tagen eine Erka\u0308ltungswelle im Team, sodass wir so fluktuativ wechseln mussten, dass es nicht nur mich gestresst hat, sondern auch die Mannschaft. Es war aber einfach unabdingbar heute, weil ganz viele Spieler heute alle fu\u0308nf Minuten kamen und eine Pause brauchten. Das hat Melsungen gerade in der ersten Ha\u0308lfte zu viel Tempo eingeladen. Und sie haben einige Tempotore in der ersten Halbzeit gemacht. Im zweiten Durchgang haben wir dann den Fokus auf den Ru\u0308ckzug gelegt und konnten in der Wechselstrategie etwas umstellen. Es ist dann eine absolute Abwehrschlacht, die wir 9:7 gewinnen. Wir haben eine sehr gute Abwehr, sehr gute Kooperation Torwart und Innenblock. Wir erarbeiten uns gute Wu\u0308rfe, die wir so haben wollten. Das einzige Problem war die Achse Casado und Arnarsson, die kaum zu verteidigen war. Alles in allem ein verdientes Unentschieden und ich bin sehr froh. Wir sind aktuell sehr stabil was die Mentalita\u0308t angeht. Wir glauben zu jedem Zeitpunkt an uns und das stimmt mich sehr froh fu\u0308r die kommenden Wochen.\u201c<\/p>\n<p><strong>Roberto Garcia Parrondo:<\/strong> \u201eGratulation an den Bergischen HC zu diesem Punktgewinn. Sie haben heute stark gespielt mit viel Einsatz und hoher Intensita\u0308t. In der ersten Halbzeit haben wir nicht gut in der Abwehr gestanden und waren nicht auf dem Level was wir eigentlich bra\u0308uchten. In der zweiten Halbzeit war der Torhu\u0308ter des BHC auf dem Posten \u2013 wir hatten zahlreiche Chancen, die wir nicht genutzt haben und so konnten wir das Spiel nicht zu unseren Gunsten entscheiden. Wir haben verschiedene Formationen und Positionsbesetzungen probiert, um uns Mo\u0308glichkeiten zu erarbeiten und ha\u0308tten aus acht Metern mehr Tore machen ko\u0308nnen. Zugegeben, da stand uns Rudeck im Weg. In der Schlussphase hat die Defensive gut gestanden &#8211; es bleibt aber beim Unentschieden am Ende, weil wir einige Ba\u0308lle liegenlassen.\u201c<\/p>\n<p><strong>Jo\u0308rg Fo\u0308ste:<\/strong> \u201eWir haben eine leidenschaftliche Leistung geboten u\u0308ber 60 Minuten. Man kann der Mannschaft nur Tribut zollen fu\u0308r das, was sie herein geschmissen hat. Wir haben geka\u0308mpft mit allem, was wir hatten, und sind letztlich mit einem Punktgewinn belohnt worden. Das ist der erste, den wir hier holen. Da kann man einen Punkt hinter machen. Beide Mannschaften waren sichtbar und ho\u0308rbar nicht zufrieden mit dem Ergebnis. Beide hatten den Eindruck, dass mehr mo\u0308glich war. Wir hatten sicher die eine oder andere Gelegenheit, den Dolchsto\u00df zu setzen &#8211; besonders in der letzten Viertelstunde mehrfach.\u201c<\/p>\n<h4>MT Melsungen &#8211; Bergischer HC 22:22 (15:13)<\/h4>\n<p><strong>MT Melsungen<\/strong>: Simic, Morawski &#8211; Ku\u0308hn, Malasinskas (1\/1), Casado (4), Ignatow (1), Beekmann (1), Drosten, Jonsson (2), Arnarsson (5), Gomes (3), Kalarash (1), Ha\u0308fner (2), Ho\u0308rr, Fuchs (2). Trainer: Roberto Garcia Parrondo<\/p>\n<p><strong>Bergischer HC:<\/strong> Rudeck, Johannesson &#8211; Beyer (3\/1), Schmitz, Gutbrod (6), Weck, Stutzke (1), Babak (3), Ladefoged (2), Nikolaisen (3), Bergner, M&#8217;Bengue (3), Gunnarsson, Persson (1). Trainer: Jamal Naji<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 3\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Schiedsrichter: Martin Tho\u0308ne und Marijo Zupanovic<br \/>\nSiebenmeter: 1\/2 &#8211; 1\/3<\/p>\n<p>Zeitstrafen: 1 &#8211; 3 (Jonsson &#8211; Gutbrod, Beyer, M&#8217;Bengue)<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ws geht doch! Der Bergische HC hat zum ersten Mal bei der MT Melsungen gepunktet. Zwar reichte es beim 22:22 in der Rothenbach-Halle nur zu einem Z\u00e4hler, den hatte sich die Mannschaft allerdings hart erarbeitet. Im Mittelpunkt stand Torh\u00fcter Christopher Rudeck, der die Hausherren mit tollen Paraden zur Verzweiflung brachte.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-57379","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:43:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/57379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=57379"}],"version-history":[{"count":7,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/57379\/revisions"}],"predecessor-version":[{"id":57386,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/57379\/revisions\/57386"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=57379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=57379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=57379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}