{"id":44283,"date":"2021-12-18T10:53:00","date_gmt":"2021-12-18T09:53:00","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=44283"},"modified":"2021-12-20T14:37:41","modified_gmt":"2021-12-20T13:37:41","slug":"jahr100wissen-froschherzen-im-dreivierteltakt","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2021\/12\/18\/jahr100wissen-froschherzen-im-dreivierteltakt\/","title":{"rendered":"Jahr100Wissen: Froschherzen im Dreivierteltakt"},"content":{"rendered":"<div id=\"attachment_44287\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-44287\" src=\"\/wp-content\/uploads\/2021\/12\/Bornhorst-Jarych1-2-1024x707.jpg\" alt=\"\" width=\"1024\" height=\"707\" \/><span class=\"wp-caption-text\">Dr. Juloa Bornhorst &#8211; \u00a9 Sebastian Jarych<\/span><\/div>\n<p>Die Lebensmittelchemikerin Prof. Dr. Julia Bornhorst berichtet in einem Interview mit Uwe Blass im Rahmen der Reihe &#8222;Jahr100Wissen&#8220; \u00fcber die Funktion solcher Transmitter und welche Rolle Umwelteinfl\u00fcsse und Ern\u00e4hrung spielen.<\/p>\n<p><strong>Bis 1921 glaubte man noch, dass nur elektrische Impulse zwischen den Nervenzellen vermitteln. Der Mediziner Otto Loewi konnte vor genau 100 Jahren dann aber die Existenz von chemischen Tr\u00e4gerstoffen beweisen. Wie gelang ihm das?<\/strong><\/p>\n<p>Dr. Julia Bornhorst: &#8222;Henry Hallett Dale und Otto Loewi erhielten zusammen 1936 f\u00fcr ihre Entdeckungen bei der chemischen \u00dcbertragung der Nervenimpulse den Nobelpreis f\u00fcr Physiologie oder Medizin. 1921 konnte Loewi die chemische Weiterleitung von Nervenimpulsen entdecken. Es ist ein spannendes Experiment, zu dem er Fr\u00f6sche benutzte. Er hat dem Frosch das Herz entnommen und es in ein gesondertes Becherglas mit einer Kochsalzl\u00f6sung gelegt. Dann hat er bei dem Frosch den Vagusnerv, einen der l\u00e4ngsten Hirnnerven, den auch wir haben, durch einen elektrischen Impuls stimuliert. Das Resultat war, der Herzschlag verlangsamte sich.<\/p>\n<p>Dann ging er einen Schritt weiter und entnahm mit einer Pipette die Blutersatzl\u00f6sung (physiologische Salzl\u00f6sung) aus der Herzkammer. Diese tauschte er mit der L\u00f6sung in einem zweiten isolierten Froschherzen aus, das daraufhin langsamer schlug, genau so, als ob sein Vagusnerv gereizt worden w\u00e4re. Damit hatte Loewi gezeigt, dass der Effekt der Vagusreizung \u00fcber einen Stoff im Extrazellul\u00e4rraum vermittelt wird. Nur durch die L\u00f6sung aus der Pipette verlangsamte sich die Herzrate des zweiten Frosches. Dies ist das Prinzip der chemischen synaptischen \u00dcbertragung und der \u00dcbertr\u00e4gerstoff ist Acetylcholin.&#8220;<\/p>\n<p><strong>Der Botenstoff, Acetylcholin (ACh) ist ein Neurotransmitter. Was bedeutet das und wo findet man ihn?<\/strong><\/p>\n<p>Dr. Julia Bornhorst: &#8222;Neurotransmitter sind erst einmal allgemein Botenstoffe von Nervenzellen. Mit ihnen wird ein elektrisches Signal von einem Neuron in ein chemisches Signal umgebildet und kann dann in der n\u00e4chsten Zelle ein elektrisches Signal hervorrufen. Das ist der Botenstoff. Eines der wichtigsten Neurotransmitter ist das Acetylcholin, welches an vielen unterschiedlichen Prozessen beteiligt ist. Wir finden es im zentralen Nervensystem, also im Gehirn und R\u00fcckenmark, aber auch im peripheren Nervensystem, d.h. au\u00dferhalb des genannten Bereiches.&#8220;<\/p>\n<p><strong>Diese Entdeckung war bahnbrechend f\u00fcr die Behandlung von Menschen. Warum?<\/strong><\/p>\n<p>Dr. Julia Bornhorst: &#8222;Alles, was wir verstehen, hilft uns, neue Therapieans\u00e4tze zu finden. Gerade das Verst\u00e4ndnis von Neurotransmittern im Gehirn nutzen wir heute bei Therapien von neurodegenerativen Erkrankungen. Bei der Alzheimer Krankheit liegt beispielsweise ein Acetylcholinmangel vor, da bei den Betroffenen auch Acetylcholin produzierende Nervenzellen absterben. Bei Morbus Parkinson kommt es zu einem relativen \u00dcberschuss an Acetylcholin, der zustande kommt, wenn beim Untergang von Hirnregionen ein Ungleichgewicht zwischen den Botenstoffen entsteht, also ein Ungleichgewicht zwischen Acetylcholin und Dopamin zugunsten von Acetylcholin. Acetylcholin hat einen starken Einfluss auf die Motorik, und daher kann man unter anderem auch das Muskelzittern beim Morbus Parkinson erkl\u00e4ren. Durch dieses Wissen hat man Therapiem\u00f6glichkeiten gefunden.&#8220;<\/p>\n<p><strong>Zu den bekanntesten Transmittern geh\u00f6ren Dopamin und Serotonin, die eine erregende sowie d\u00e4mpfende Wirkung haben. Wie setzt man diese Transmitter ein?<\/strong><\/p>\n<p>Dr. Julia Bornhorst: &#8222;Dopamin (DA) und Serotonin (SRT) sind Monoamin-Neurotransmitter, die bei vielen Aspekten der Funktionen des Nervensystems von S\u00e4ugetieren eine Schl\u00fcsselrolle spielen. Zu den am besten untersuchten Funktionen von Dopamin im Nervensystem geh\u00f6ren Kognition, Motorik, Belohnungsmechanismen durch Hirnstimulation, Ess- und Trinkverhalten, Sexualverhalten, neuroendokrine Regulation sowie selektive Aufmerksamkeit. Ver\u00e4nderungen des Dopaminlevels, also die Ver\u00e4nderung der Aussch\u00fcttung im K\u00f6rper, f\u00fchren zu schweren neurologischen und psychiatrischen St\u00f6rungen. Die bekannteste St\u00f6rung ist die Parkinson-Krankheit, die durch einen Zellverlust verursacht wird.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44288\" src=\"\/wp-content\/uploads\/2021\/12\/image001-2.jpg\" alt=\"\" width=\"430\" height=\"138\" \/><\/p>\n<p>Andere St\u00f6rungen, die auf eine abnorme Dopaminfunktion zur\u00fcckzuf\u00fchren sind, sind beispielsweise Sucht, Schizophrenie, bipolare St\u00f6rungen, Chorea Huntington, Aufmerksamkeitsdefizit-Hyperaktivit\u00e4tsst\u00f6rung und auch das Tourette-Syndrom.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Das Serotonin wiederum besitzt im menschlichen Organismus insbesondere auf das Herz-Kreislauf-System, den Magen-Darm-Trakt und das Nervensystem vielf\u00e4ltige Wirkungen. Serotonin ist wahrscheinlich am bekanntesten f\u00fcr seine Rolle bei der Vermittlung eines Gef\u00fchls der Zufriedenheit und des Gl\u00fccks. Es ist an praktisch jeder Art von Verhalten beteiligt, z. B. an appetitiven, emotionalen, motorischen, kognitiven und autonomen Funktionen.<\/p>\n<p>Ver\u00e4nderungen im serotonergen System (SRTergic) spielen bei vielen Erkrankungen, darunter Depressionen, Schizophrenie, Migr\u00e4ne, Angstzust\u00e4nde und Demenz eine Rolle. Daran sieht man, wie wichtig die richtige Regulation der Neurotransmitter f\u00fcr die Gesundheit ist.&#8220;<\/p>\n<p><strong>Was tut man, wenn die Neurotransmitter nicht mehr richtig funktionieren?<\/strong><\/p>\n<p>Dr. Julia Bornhorst: &#8222;An vielen neurodegenerativen Erkrankungen wird heute geforscht. Wir versuchen z.B. durch die Gabe von Vorstufen der Neurotransmitter oder der Beeinflussung von Synthese\/Abbau gezielt einen Verlust oder eine Defizienz auszugleichen. Wir sollten immer gen\u00fcgend, aber auch nicht zu viel Dopamin und Serotonin im K\u00f6rper haben. Die richtige Balance ist wichtig. Wenn wir nun von etwas zu wenig haben, ist das immer nachteilig f\u00fcr die Gesundheit. Im Falle der Parkinson-Erkrankung behandelt man daher mit Levodopa (L-Dopa), einer Vorstufe des Dopamins. Das ist derzeit die wirksamste medikament\u00f6se Standardtherapie, die, je nachdem in welchem Stadium der\/die Patient\/in sich befindet, eine Linderung der Symptome bringt. Eine andere M\u00f6glichkeit sind sogenannte MAO- und COMT-Hemmer, die daf\u00fcr sorgen, dass das Dopamin nicht mehr im Gehirn abgebaut wird. Das sind nur zwei Ans\u00e4tze, wobei man sagen muss, dass wir bis heute neurodegenerative Erkrankungen noch immer unzureichend verstanden haben. Und f\u00fcr das, was wir nicht ganz verstehen, fehlen uns nat\u00fcrlich auch die geeigneten Therapieans\u00e4tze. Es besteht viel Forschungsbedarf, um vor allem noch bessere Therapien zu erm\u00f6glichen, da der Anteil an neurodegenerativer Erkrankungen in der Bev\u00f6lkerung zunimmt.&#8220;<\/p>\n<p><strong>Inwieweit spielen Umweltfaktoren und die Ern\u00e4hrung eine Rolle?<\/strong><\/p>\n<p>Dr. Julia Bornhorst:<span class=\"Apple-converted-space\">\u00a0&#8222;<\/span>Bei der Parkinson-Erkrankung wissen wir, dass nur 10% genetischen Ursprungs sind. Es ist also sehr wichtig, Substanzen in der Umwelt zu identifizieren, die ein neurodegeneratives Potential aufweisen. Wir besch\u00e4ftigen uns im Rahmen unserer Forschung beispielsweise mit der Neurotoxizit\u00e4t durch Lebensmittel-\/ und Umwelt-relevante Metallverbindungen. Ich erkl\u00e4re das einmal am Beispiel Mangan: Eine berufliche oder ern\u00e4hrungsbedingte \u00dcberversorgung mit dem Spurenelement Mangan kann zu toxischen Effekten auf das Nervensystem f\u00fchren, die eine Reihe von Symptomen ausl\u00f6sen k\u00f6nnen, wie beispielsweise Gang\u00e4nderungen, Koordinationsst\u00f6rungen, Halluzinationen oder mentale Reizbarkeit.<\/p>\n<p>Diese f\u00fchren letztendlich zu einem irreversiblen Krankheitsbild, welches als Manganismus bezeichnet wird. Dieses weist mit der Pr\u00e4senz von motorischen und kognitiven Beeintr\u00e4chtigungen eine \u00e4hnliche Neuropathologie auf wie die Parkinson`sche Krankheit. Die neurotoxischen Effekte von Mangan sind seit mittlerweile 175 Jahren bekannt und seine Wirkmechanismen sind im Laufe des letzten Jahrhunderts intensiv erforscht worden. Trotzdem sind bis heute die Mechanismen der manganvermittelten Neurotoxizit\u00e4t unzureichend aufgekl\u00e4rt. L-Dopa hilft da nicht im Therapieansatz, d.h. es muss etwas anderes Mechanistisches sein. Ein Zusammenhang mit oxidativem Stress, mitochondrialer Dysfunktion und Proteinaggregation wird zwar vermutet, ist aber noch nicht bewiesen.<\/p>\n<p>Das Alter erkl\u00e4rt nicht immer alles, sondern auch Umweltfaktoren tragen zu Krankheitsbildern bei. Hier m\u00fcssen wir meiner Ansicht nach ansetzen. Wir m\u00fcssen herausfinden, inwieweit Umweltfaktoren ein Risikofaktor f\u00fcr neurodegenerative Erkrankungen sind und zur Krankheitsbildung beitragen. Dann kann ich auch versuchen, dass sich Menschen bestimmten Risikofaktoren nicht mehr aussetzen. Wenn bestimmte Metalle z.B. in einer \u00dcberdosierung nachteilig sind, k\u00f6nnen wir diese Erkenntnis an die Bev\u00f6lkerung weitergeben, damit sie die M\u00f6glichkeit haben, sich dem zu entziehen oder sich zu sch\u00fctzen.&#8220;<\/p>\n<p><strong>Welche Modelle nutzen Sie an der BUW f\u00fcr neurodegenerative Erkrankungen?<\/strong><\/p>\n<p>Dr. Julia Bornhorst: &#8222;Wir besch\u00e4ftigen uns mit dem Einfluss lebensmittel\/ und umweltrelevanter Metallverbindungen auf neuronale Zellen. Da gibt es unterschiedliche Modelle. Zum einen Zellkulturmodelle und zum anderen den Fadenwurm C. elegans.<\/p>\n<p>Um die neurotoxische bzw. neuroprotektive (positiv beeinflussende) Wirksamkeit einer ins Gehirn transferierten Verbindung absch\u00e4tzen zu k\u00f6nnen, setzen wir in der Zellkultur menschliche Neuronen ein. So konnten wir j\u00fcngst zeigen, dass eine \u00dcberversorgung mit dem Spurenelement Mangan das Neuritenwachstum &#8211; das sind die Verbindungen zwischen den Neuronen &#8211; negativ beeinflusst. Das eigentlich sch\u00f6n anzusehende Netzwerk im gesunden Organismus (links) wird durch die Trennung der Verbindungen zerst\u00f6rt.<\/p>\n<p>Wir k\u00f6nnen also sehen, diese Substanzen f\u00fchren zu einer Neurodegeneration. Und dann k\u00f6nnen wir erforschen, warum das geschieht und evtl. Stoffe einsetzen, damit das nicht passiert.<\/p>\n<p>Zudem nutzen wir den Fadenwurm C. elegans. Dabei handelt es sich um den ersten multizellul\u00e4ren Organismus, dessen Genom vollst\u00e4ndig sequenziert wurde, was die genetische Manipulierbarkeit dieses Modellorganismus recht einfach gestaltet. Aufgrund des hoch spezialisierten Nervensystems bestehend aus 302 Neuronen und mehr als 700 Synapsen stellt der Wurm auch eine innovative und leistungsf\u00e4hige Plattform in Bezug auf die Untersuchung neuronaler und eventueller neurodegenerativer Prozesse dar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44291\" src=\"\/wp-content\/uploads\/2021\/12\/Intaktes-Netzwerk.jpg\" alt=\"\" width=\"348\" height=\"260\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-44290\" src=\"\/wp-content\/uploads\/2021\/12\/Defekte-Neuronen.jpg\" alt=\"\" width=\"348\" height=\"260\" \/><\/p>\n<p>Fluoreszenzmikroskopische Aufnahme von menschlichen Hirnzellen (Neuronen); das neuronale Netzwerk ist in gr\u00fcn zu erkennen. Auf dem linken Bild handelt es sich um unbehandelte Neurone, w\u00e4hrend auf dem rechten Bild<span class=\"Apple-converted-space\">\u00a0 <\/span>Neurone nach Mangan\u00fcberversorgung (Mangan ist ein Spurenelement) abgebildet sind. Hier gibt es kein intaktes neuronales Netzwerk mehr. \u00a9 (Bild: Lebensmittelchemie Bergische Universit\u00e4t)<\/p>\n<p>Die Testung auf eine m\u00f6gliche Neurotoxizit\u00e4t im Fadenwurm kann durch unterschiedliche Methoden erfolgen. Man kann die transparenten W\u00fcrmer einsetzen und deren Neuronen mit einem Fluoreszenzsignal spezifisch markieren, also einf\u00e4rben. So kann man entsprechend betroffene Neuronen mikroskopisch identifizieren. Bei der Aufnahme von Giftstoffen erkennt man dann sehr deutlich, wie der Neuron gesch\u00e4digt wurde und abstirbt. Zellk\u00f6rper sind dann nur noch ganz klein, Verbindungen werden gekappt, es liegt also ein neurodegeneratives Potential durch eine Substanz vor.<\/p>\n<p>Auch das Verhalten des Wurms wird durch Neurotransmitter gesteuert. Wir k\u00f6nnen uns die Schl\u00e4ngelrate ansehen, und wenn ein Wurm mit einem Metall gef\u00fcttert wird und sich die Schl\u00e4ngelrate ver\u00e4ndert, dann wissen wir sofort, dass etwas im Neurotransmittersystem nicht mehr stimmt.<\/p>\n<p>Zus\u00e4tzlich entwickeln wir eine Methode, um auch instrumentell-analytisch die Neurotransmitter zu erfassen, d.h. wir k\u00f6nnen sie quantifizieren, die genaue Menge an Dopamin, Serotonin oder Acetylcholin in W\u00fcrmern benennen und Aussagen \u00fcber den Abbau der Stoffe machen. Und wir k\u00f6nnen den Wurm auch genetisch manipulieren. Wir haben sogenannte Parkinson-W\u00fcrmer, deren Gen manipuliert wurde, so dass sie ein hohes Risiko f\u00fcr Parkinson haben. Wenn wir nun wissen wollen, wie ist denn jetzt das Risiko f\u00fcr eine neurodegenerative Erkrankung, wenn die Genetik sich also ver\u00e4ndert hat und wir f\u00fcttern den Wurm auch noch mit dem Metall, dann k\u00f6nnen wir sehen, ob er sensibler oder weniger sensibel ist. Dadurch k\u00f6nnen wir die Genetik und die Umweltfaktoren besser verstehen und bestimmen.&#8220;<\/p>\n<p><strong>Uwe Blass<\/strong><\/p>\n<h4>\u00dcber Dr. Julia Bornhorst<\/h4>\n<p>Julia Bornhorst studierte und promovierte an der Westf\u00e4lischen Wilhelms Universit\u00e4t M\u00fcnster. Sie arbeitete f\u00fcnf Jahre am Institut f\u00fcr Ern\u00e4hrungswissenschaft der Universit\u00e4t Potsdam. Seit Januar 2019 ist sie Professorin f\u00fcr Lebensmittelchemie an der Bergischen Universit\u00e4t.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor 100 Jahren konnte der Mediziner Otto Loewi erstmals die Existenz von chemischen Tr\u00e4gerstoffen, den sogenannten Neurotransmittern, beweisen. Die Entdeckung dieser Botenstoffe der Nervenzellen war bahnbrechend f\u00fcr die Behandlung diverser Krankheiten.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-44283","post","type-post","status-publish","format-standard","hentry","category-wissen"],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:44:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/44283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=44283"}],"version-history":[{"count":8,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/44283\/revisions"}],"predecessor-version":[{"id":44325,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/44283\/revisions\/44325"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=44283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=44283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=44283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}