{"id":40030,"date":"2021-08-06T10:06:37","date_gmt":"2021-08-06T08:06:37","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=40030"},"modified":"2021-08-10T09:21:08","modified_gmt":"2021-08-10T07:21:08","slug":"wsv-unterliegt-vfl-bochum-im-pokal-krimi-mit-12","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2021\/08\/06\/wsv-unterliegt-vfl-bochum-im-pokal-krimi-mit-12\/","title":{"rendered":"WSV unterliegt VfL Bochum im Pokal-Krimi mit 1:2"},"content":{"rendered":"<div id=\"attachment_40033\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-40033\" src=\"\/wp-content\/uploads\/2021\/08\/Classen-08-08-2020-035-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><span class=\"wp-caption-text\">Semir Saric (Mitte) bejubelt mit seinen Mannschaftskameraden sein Tot zum 1:0 &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<p>Es war das erste DFB-Pokal-Spiel des WSV seit 14 Jahren. Die 4.990 Zuschauer, die unter Corona-Bedingungen live im Stadion dabei sein durften und die vielen Fans vor den Fernsehern, erlebten ein packendes Spiel. Nichts war zun\u00e4chst von einem Klassenunterschied zu sehen.<\/p>\n<p>WSV-Chef-Trainer Bj\u00f6rn Mehnert setzte auf eine F\u00fcnferkette. Nach Ballgewinnen ging sofort die Post nach vorne ab. In der 20. Minute resultierte aus diesem taktischen Schachzug beinahe das 1:0 f\u00fcr den WSV. Kevin Hagemann k\u00e4mpfte sich auf der linken Seite bis zur Grundlinie durch und passte scharf nach innen. Dort stand Marco K\u00f6nigs und knallte den Ball direkt aufs Bochumer Tor.<span class=\"Apple-converted-space\">\u00a0<\/span>Doch Torh\u00fcter Manuel Riemann konnte den Ball mit einem tollen Reflex abwehren.<\/p>\n<p>Schon drei Minute sp\u00e4ter hatten die Wuppertaler dann Grund zum Jubeln.<span class=\"Apple-converted-space\">\u00a0<\/span>Niklas Heidemann passte von der linke Seite auf Semir Saric und der knallte den Ball volley ins Bochumer Tor. 1:0 f\u00fcr den Au\u00dfenseiter!<\/p>\n<p>Was viele Besucher im Stadion und vor den TV-Ger\u00e4ten \u00fcberraschte: WSV-Torh\u00fcter Sebastian Patzler verlebte eine v\u00f6llig ruhige erste Halbzeit, musste so gut wie gar nicht eingreifen.<\/p>\n<p>Bochums Trainer Thomas Reis reagierte und wechselte in der Halbzeit gleich zweimal: F\u00fcr Armel Bella Kotchap kam Vasileios Lampropoulos und f\u00fcr<span class=\"Apple-converted-space\">\u00a0<\/span>Gerrit Holtmann St\u00fcrmer Christopher Antwi-Adjei.<span class=\"Apple-converted-space\">\u00a0<\/span>Und diese Einwechselungen sollte auch schnell Fr\u00fcchte tragen.<\/p>\n<div id=\"attachment_40034\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40034 size-large\" src=\"\/wp-content\/uploads\/2021\/08\/Classen-08-08-2020-079-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><span class=\"wp-caption-text\">Packender Zweikampf zwischen dem Wuppertaler Kevin Hagemann (r.) und Gamboa (VfL Bochum) &#8211; \u00a9 Jochen Classen<\/span><\/div>\n<p>Der WSV verlor in der Vorw\u00e4rtsbewegung in der eigenen H\u00e4lfte den Ball. Dann ging alles ganz schnell: Antwi-Adjei wurde steil auf der linken Au\u00dfenbahn angespielt, er marschierte in den Strafraum und passte auf Mittelst\u00fcrmer Simon Zoller. Der fackelte nicht lange und zog aus drei Metern direkt ab. Der Ausgleich f\u00fcr die G\u00e4ste!<\/p>\n<p>Der Bundesligist war in der 2. Halbzeit klar spielbestimmend. Der WSV konnte sich keine klare M\u00f6glichkeit mehr herausspielen. Auf der anderen Seite mussten die Wuppertaler Fans bei einer Gro\u00df-Chance von Takuma Asano zittern. Er traf zum Gl\u00fcck f\u00fcr die Gastgeber aus kurzer Distanz nur die Unterseite der Latte.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Nach knapp 97 Minuten pfiff Schiedsrichter Patrick Alt die Partie ab. Verl\u00e4ngerung!<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Bei beiden Mannschaften wurde jetzt der enorme Kr\u00e4fteverschlei\u00df sichtbar. Der Bundesligist hatte in der ersten H\u00e4lfte der Verl\u00e4ngerung durch Pantovic eine Chance (100.) und der WSV durch Phillip Aboagye (102.).<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>In den zweiten 15 Minuten dann die Entscheidung: Nach einem Eckball von Milos Pantovic verl\u00e4ngerte Simon Zoller auf Robert Tesche und der traf aus sieben Metern zum 1:2-Endstand (111.).<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Der VfL Bochum erreichte mit dem gl\u00fccklichen, aber nicht unverdienten 2:1-Sieg die 2. Runde des DFB-Pokals.<\/p>\n<p>Die Spieler des WSV, die tapfer gek\u00e4mpft hatten, wurden von den Fans mit einem Riesenapplaus verabschiedet. Gerade in der 1. Halbzeit hatte der Regionalligisten den Bundesligisten sogar dominiert. Das sah auch der Bochumer Coach Thomas Reis so. Er w\u00fcnschte dem Traditionsverein Wuppertaler SV f\u00fcr die Regionalliga-Saison f\u00fcr vel Gl\u00fcck.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>WSV-Trainer Bj\u00f6rn Mehnert zeigte als fairer Verlierer. Auf 120 Minuten gesehen sei der Erfolg des Bundesligisten nicht unvberdient.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<div id=\"attachment_40035\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-40035\" src=\"\/wp-content\/uploads\/2021\/08\/Classen-07-08-2021-204-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><span class=\"wp-caption-text\">Wuppertaler SV : VfL Bochum, DFB Pokal, Saison 2021\/2022<\/span><\/div>\n<p><strong>Die Spieldaten<span class=\"Apple-converted-space\">\u00a0<\/span><\/strong><\/p>\n<h4>Wuppertaler SV &#8211; VfL Bochum (1:0 &#8211; 1:1) 1:2 n.V.<\/h4>\n<p><b>Aufstellung Wuppertaler SV:<\/b><\/p>\n<p>1 Sebastian Patzler &#8211; 14 Philipp Hanke (63. 2 Moritz Montag), 21 Noah Salau, 26 Dominik Bilogrevic, 27 Kevin Pytlik, 33 Niklas Heidemann &#8211; 5 Felix Backszat (90.+6 Lion Schweers), 10 Kevin Rodrigues Pires &#8211; 7 Semir Saric (90.+5 11 Xhuljo Tabaku), 9 Kevin Hagemann (90.+5 23 Phillip Aboagye) &#8211; 48 Marco K\u00f6nigs (80., 18 Roman Prokoph)<\/p>\n<p>Trainer: Bj\u00f6rn Mehnert<\/p>\n<p><b>Aufstellung VfL Bochum:<\/b><\/p>\n<p>1 Manuel Riemann &#8211; 2 Christian Gamboa Luna, 37 Armel Bella Kotchap (46. 24 Vasileios Lampropoulos), 29 Maxim Leitsch, 3 Danilo Soares &#8211; 23 Robert Tesche, 8 Anthony Losilla &#8211; 10 Takuma Asano (73. 35 Silvere Ganvoula Mboussy), 20 Elvis Rexhbecaj (91. 27 Milos Pantovic), 17 Gerrit Holtmann (46. 22 Christopher Antwi-Adjei) &#8211; 9 Simon Zoller<\/p>\n<p>Trainer: Thomas Reis<\/p>\n<p><b>Stadion: <\/b>Stadion am Zoo<\/p>\n<p><b>Zuschauer: <\/b>4.990 (ausverkauft; 800 G\u00e4ste)<\/p>\n<p><b>Tore:<\/b> 1:0 Saric (23.), 1:1 Zoller (53.), 1:2 Tesche (111.)<\/p>\n<p><b>Gelbe Karten: <\/b>Mehnert (71.), Salau (100.) \u2013 Tesche (44.), Leitsch (71.), Zoller (71.), Pantovic (118.)<\/p>\n<p><b>Gelb-Rote Karte:<\/b> Rodrigues Pires (119.)<\/p>\n<p><b>Rote Karte:<\/b> El Hajjaj (90.+3)<\/p>\n<p><b>Schiedsrichter: <\/b>Patrick Alt<\/p>\n","protected":false},"excerpt":{"rendered":"<p>War das ein Pokal-Krimi! Der Regionalligist Wuppertaler SV unterlag\u00a0 dem Bundesliga-Aufsteiger VfL Bochum in der ersten Runde des DFB-Pokals nach aufopferungsvollen Kampf nach Verl\u00e4ngerung knapp mit 1:2. Den entscheidenden Treffer erzielte Tesche in der 111. Minute.\u00a0<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-40030","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:04:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/40030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=40030"}],"version-history":[{"count":4,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/40030\/revisions"}],"predecessor-version":[{"id":40037,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/40030\/revisions\/40037"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=40030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=40030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=40030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}