{"id":38173,"date":"2021-06-04T11:58:34","date_gmt":"2021-06-04T09:58:34","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=38173"},"modified":"2021-06-04T13:59:17","modified_gmt":"2021-06-04T11:59:17","slug":"die-gwg-wuppertal-uebertrifft-wieder-ihre-wirtschaftliche-ziele","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2021\/06\/04\/die-gwg-wuppertal-uebertrifft-wieder-ihre-wirtschaftliche-ziele\/","title":{"rendered":"Die GWG Wuppertal \u00fcbertrifft wieder ihre wirtschaftliche Ziele"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div id=\"attachment_38177\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-38177\" src=\"\/wp-content\/uploads\/2021\/06\/GWG-Geschaeftsfuehrer-Oliver-Zier-2-1024x740.jpg\" alt=\"\" width=\"1024\" height=\"740\" \/><span class=\"wp-caption-text\">GWG-Gesch\u00e4ftsf\u00fchrer Oliver Zier &#8211; \u00a9 GWG<\/span><\/div>\n<p>Die Gemeinnu\u0308tzige Wohnungsbaugesellschaft mbH Wuppertal (GWG) als 95prozentige sta\u0308dtische Tochter und gro\u0308\u00dfte Vermieterin Wuppertals besitzt derzeit rund 5.600 Wohnungen, davon 120 Senioren-Service-Wohnungen. Au\u00dferdem vermietet sie rund 40.000 m2 Gewerbefla\u0308che.<\/p>\n<p>Trotz der Einschra\u0308nkungen durch die Pandemie war Wuppertals gro\u0308\u00dfte Vermieterin zu jeder Zeit und zuverla\u0308ssig fu\u0308r die Anliegen ihrer Mieterinnen und Mieter da. Ebenfalls konnte sie zu jeder Zeit Wohnungsanfragen bedienen und so neue Kundinnen und Kunden gewinnen.<\/p>\n<p>Damit folgt die GWG zielgerichtet ihrer ju\u0308ngst verabschiedeten Unternehmens-Vision: \u201eWir gestalten die nachhaltigen Quartiere der Zukunft \u2013 fu\u0308r ein lebenswertes Zuhause.\u201c<\/p>\n<h4>Kennzahlen zum Jahresabschluss 2020<\/h4>\n<p>Das Wirtschaftsjahr 2020 schloss mit einem Gewinn von rund 1,9 Mio. \u20ac (Vorjahr 1,7 Mio. \u20ac). Gegenu\u0308ber dem Plan ergibt sich eine Verbesserung von 830.000 \u20ac. Rund 12,6 Mio. \u20ac hat die GWG in 2020 fu\u0308r sonstige betriebliche Aufwendungen, Personal und Zinsen ausgegeben \u2013 im Vorjahr waren es rund 12,4 Mio. \u20ac.<\/p>\n<p>Der Anstieg resultiert insbesondere aus zusa\u0308tzlichen Aufwendungen fu\u0308r Digitalisierungsprojekte. Die Umsa\u0308tze aus der Hausbewirtschaftung haben sich von 36,5 Mio. \u20ac im Vorjahr auf 36,6 Mio. \u20ac in 2020 leicht erho\u0308ht. Dadurch ist auch das Rohergebnis (21,91 Mio. \u20ac in 2020) im Vergleich zum Vorjahr (21,65 Mio. \u20ac) leicht gestiegen.<\/p>\n<p>Die Eigenkapitalbasis konnte weiter ausgebaut werden. Trotz des Bilanzsummenwachstums blieb die Eigenkapitalquote (rund 25,4 %) daher anna\u0308hernd gleich.<\/p>\n<h4>Immobilienmanagement<\/h4>\n<p>In den na\u0308chsten zehn Jahren wird die GWG rund 189 Mio. \u20ac in den Wohnstandort Wuppertal investieren. Hiervon entfallen rund 176 Mio. \u20ac auf nachhaltige Ma\u00dfnahmen zur Verbesserung der Wohnqualita\u0308t im derzeitigen Bestand.<\/p>\n<p>So kann die Attraktivita\u0308t der Geba\u0308ude und Wohnungen weiter gesteigert werden. Dies gewa\u0308hrleistet zudem die Werterhaltung der Ha\u0308user. Hinzu kommen gezielte Neubauprojekte, die dazu dienen, den Gesamtbestand aufzufrischen und neue Angebote fu\u0308r die rege Nachfrage in Wuppertal zu schaffen.<\/p>\n<p>Auch in 2020 setzte die GWG wieder umfangreiche Modernisierungsma\u00dfnahmen um. Neben dem Umbau und der Erweiterung von Fla\u0308chen fu\u0308r eine Tagespflegeeinrichtung in der Heckinghauser Stra\u00dfe wurden verschiedene Giebel und Fassaden sowie Da\u0308cher im Bestand erneuert.<\/p>\n<div id=\"attachment_38174\" class=\"wp-caption alignnone\" style=\"max-width: 1034px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-38174\" src=\"\/wp-content\/uploads\/2021\/06\/heidter-carre-1024x502.jpg\" alt=\"\" width=\"1024\" height=\"502\" \/><span class=\"wp-caption-text\">Die Arbeiten am Heider Carr\u00e9 sind im vollen Gange &#8211; \u00a9 GWG<\/span><\/div>\n<p>Zudem hat die GWG insgesamt 171 Wohnungen modernisiert. Der Um-\/Ausbau der Lise-Meitner-Stra\u00dfe wurde in 2020 begonnen. Die Fla\u0308chen sind an die Mieter im Mai 2021 u\u0308bergeben worden.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Die Planung fu\u0308r die Gro\u00dfmodernisierung Wuppertaler Hof wurde abgeschlossen. Hier sollen moderne, kundenfreundliche Bu\u0308rofla\u0308chen fu\u0308r den Stadtkonzern entstehen, die auch einen Einstieg in die \u201eArbeitswelten 4.0\u201c ermo\u0308glichen.<\/p>\n<p>Die Rohbauarbeiten fu\u0308r das \u201eheidter carre\u0301\u201c sind in vollem Gange. An der Untere Lichtenplatzer Stra\u00dfe entsteht das erste Neubauvorhaben der GWG seit Ende der 1990er Jahre. Auf dem verbliebenen Grundstu\u0308ck der ehemaligen Bremme-Brauerei in Wuppertal Heckinghausen werden 30 barrierefreie Wohnungen mit einer Kindertagessta\u0308tte kombiniert.<\/p>\n<p>Die positive Leerstandsentwicklung der letzten Jahre setzte sich ebenfalls in 2020 fort. Zum Jahresende standen rund 2,9 % (2019: 3,3 %) der GWG-Wohnungen leer. Dies entspricht einer Verbesserung von u\u0308ber 12 % im Vergleich zum Vorjahr. Damit liegt der Anteil leerstehender Wohnungen im Bestand der GWG deutlich unter dem gesamtsta\u0308dtischen Wert (2019: 5,3 %). Eine weitere Senkung des Leerstands ist fu\u0308r die na\u0308chsten Jahre geplant.<\/p>\n<h4>Dreiklang der Nachhaltigkeit<\/h4>\n<p>Die GWG hat in den letzten Jahren \u2013 insbesondere seit 2018 \u2013 erfolgreich an den Themen Soziales, Umwelt und O\u0308konomie gearbeitet und einen bemerkenswerten Aufschwung vollzogen. Seit diesem Jahr arbeitet sie intensiv daran, diese drei Aspekte sowie deren Balance noch mehr in den Mittelpunkt ihrer Unternehmensstrategie und ihrer ta\u0308glichen Arbeit zu ru\u0308cken.<\/p>\n<p>Die GWG hat auch im Jahr 2020 ihre digitale Transformation vorangetrieben. Die Pandemie hat sich hierbei als zusa\u0308tzlicher Beschleuniger erwiesen. So hat sie entlang ihrer Digitalisierungsstrategie im letzten Jahr bereits viele Projekte umgesetzt und viele weitere sind in Planung.<\/p>\n<p>Ziel dabei ist es auch weiterhin, die sta\u0308dtische Tochter fu\u0308r neue, komplexe und immer schneller werdende Anforderungen von heute sowie morgen leistungsstark aufzustellen. Auf diese Weise ko\u0308nnen die wesentlichen Ziele der Kundenzentrierung und Wirtschaftlichkeit noch besser verfolgt werden.<\/p>\n<h4>Personalentwicklung und Kulturwandel<\/h4>\n<p>Eine kontinuierliche Ausbildungsarbeit im Berufsbild Immobilienkaufmann\/-frau wird bei der GWG seit Jahren gro\u00dfgeschrieben. So schlossen im August 2020 wieder zwei junge Mitarbeiter ihre Ausbildung erfolgreich ab und sind nun Teil des GWG-Teams.<\/p>\n<p>Im Sommer 2021 wird diese Erfolgsgeschichte mit dem Ausbildungsbeginn von mindestens zwei neuen jungen Nachwuchskra\u0308ften fortgeschrieben.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Jahresabschluss 2020 zeigt es deutlich: Wie schon im Vorjahr \u00fcbertrifft die Gemeinn\u00fctzige Wohnungsbaugesellschaft mbH Wuppertal (GWG) ihre wirtschaftlichen Ziele. Dies dr\u00fcckt sich zum einen im deutlich gestiegenen Investitionsvolumen, aber auch in der Umsetzung einer Vielzahl innovativer Projekte aus.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-38173","post","type-post","status-publish","format-standard","hentry","category-wirtschaft"],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:45:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/38173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=38173"}],"version-history":[{"count":3,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/38173\/revisions"}],"predecessor-version":[{"id":38179,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/38173\/revisions\/38179"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=38173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=38173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=38173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}