{"id":37704,"date":"2021-05-21T07:44:25","date_gmt":"2021-05-21T05:44:25","guid":{"rendered":"https:\/\/www.die-stadtzeitung.de\/?p=37704"},"modified":"2021-05-26T07:53:12","modified_gmt":"2021-05-26T05:53:12","slug":"gegen-minden-soll-endlich-wieder-ein-sieg-her","status":"publish","type":"post","link":"https:\/\/www.die-stadtzeitung.de\/index.php\/2021\/05\/21\/gegen-minden-soll-endlich-wieder-ein-sieg-her\/","title":{"rendered":"Gegen Minden soll endlich wieder ein Sieg her"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div id=\"attachment_37707\" class=\"wp-caption alignnone\" style=\"max-width: 1000px;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37707\" src=\"\/wp-content\/uploads\/2021\/05\/200817_NA_Autogrammkarte_Damm-2.jpg\" alt=\"\" width=\"990\" height=\"724\" \/><span class=\"wp-caption-text\">Sebastian Damm steht dem BHC wieder zur Verf\u00fcgung &#8211; \u00a9 BHC 06<\/span><\/div>\n<p>&#8222;Nach Balingen musste es schnell gehen. Wir haben das Spiel in Gespra\u0308chen aufgearbeitet&#8220;, sagt Trainer Hinze. &#8222;Wir haben natu\u0308rlich einfache Fehler gemacht, zu viele Ba\u0308lle verworfen. Aber das gro\u00dfe Problem ist, dass die Misserfolge im Spiel derzeit eine zu gro\u00dfe Wirkung haben. Wir setzen alles daran, dass sich das bald a\u0308ndert.&#8220;<\/p>\n<p>Der Coach macht seiner Mannschaft keinen Vorwurf. Sie trainiert eifrig, investiert alles im Spiel, doch der Kopf ist nicht frei. &#8222;Ein Erfolgserlebnis wird uns helfen. Das wollen wir schaffen. Der Weg dorthin kann aber nicht mit zusa\u0308tzlichem Druck von mir aufgebaut werden&#8220;, erkla\u0308rt der 42-Ja\u0308hrige.<\/p>\n<p>Um die Niederlagen-Serie von nunmehr vier Partien rei\u00dfen zu lassen, beno\u0308tige die Mannschaft eine positive Grundstimmung, die von einzelnen schlechten Aktionen nicht getru\u0308bt werden kann. &#8222;Wenn man einen guten Lauf hat, ist das automatisch so. Da schu\u0308ttelt man das einfach ab&#8220;, sagt der Trainer. &#8222;Jetzt mu\u0308ssen wir es in dieser schweren Phase trotzdem hinbekommen. Unser Fokus muss weg von den negativen Kleinigkeiten.&#8220;<\/p>\n<p>Dies soll am Mittwochabend ausgerechnet gegen GWD Minden gelingen. Denn die Ostwestfalen befinden sich derzeit in ihrer besten Phase. &#8222;Bei ihnen ist es eigentlich genau umgedreht wie bei uns: Sie waren zu einem anderen Zeitpunkt da, wo wir jetzt sind. Und im Moment gewinnen sie sogar Spiele, die eigentlich schon verloren sind&#8220;, meint der Trainer.<\/p>\n<h4>Minden hatte zuletzt guten Lauf<\/h4>\n<p>Bestes Beispiel dafu\u0308r ist der ju\u0308ngste Erfolg gegen die TSV Hannover-Burgdorf. Die Mindener lagen konstant hinten, standen auch in der Schlussphase mit dem Ru\u0308cken zur Wand, als die Niedersachsen ihren letzten Angriff hatten. Doch beim Stand von 27:27 fing Mats Korte den Ball ab und befo\u0308rderte ihn in letzter Sekunde u\u0308ber das gesamte Spielfeld ins leere Hannoveraner Tor zum 28:27-Endstand.<\/p>\n<p>GWD ist damit seit sechs Spielen ungeschlagen und hat sich im Kampf um den Klassenerhalt einen Puffer von sechs Punkten auf den ersten Abstiegsrang erarbeitet. &#8222;Die Ausgangssituation im Vergleich zum Hinspiel ist natu\u0308rlich eine vo\u0308llig andere&#8220;, wei\u00df Hinze. &#8222;Minden hat jetzt eine extreme Stabilita\u0308t gefunden.&#8220; In Maximilian Janke und Miro Schluroff ist es GWD-Trainer Frank Carstens gelungen, zwei Zuga\u0308nge zu integrieren. Dazu pra\u0308sentieren sich zwischendurch verletzte Handballer wie Doruk Pehlivan, Lucas Meister und Joshua Thiele wieder in guter Form.<\/p>\n<p>Ru\u0308ckraum-Shooter und Top-Torschu\u0308tze Christoffer Rambo sowie Mittelmann Juri Knorr sind auf dem Feld die beiden Leistungstra\u0308ger der Mannschaft. Im Tor ist Malte Semisch zur Nummer eins avanciert, wa\u0308hrend Carsten Lichtlein gerade zuletzt wieder fu\u0308r ganz wichtige Paraden gut war. &#8222;Grundsa\u0308tzlich sind es gegen Minden immer Spiele, in denen es auf die Tagesform ankommt&#8220;, wei\u00df Hinze.<\/p>\n<p>Beim 36:29 im Hinspiel waren die Lo\u0308wen klar besser. Um auch in der Klingenhalle Erfolg zu haben, verfolgt Hinze einen disziplinierten Angriffsplan. &#8222;Minden setzt auf Steals und Konter. Wir mu\u0308ssen ihnen das Tempospiel wegnehmen so gut es geht, so dass wir im Positionsangriff sehr gute Entscheidungen beno\u0308tigen.&#8220;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Personell bekommt der Coach eine Option mehr. Sebastian Damm ist wieder voll einsatzbereit. Ob der Linksau\u00dfen im Kader steht, hat Hinze allerdings noch nicht entschieden. Nach Lage der Dinge stehen dem Coach 18 Spieler zur Verfu\u0308gung, so dass er am Spieltag auf zwei verzichten muss.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Entt\u00e4uschung nach der 25:27-Niederlage in Balingen war gro\u00df beim Bergischen HC. Daher kommt es Sebastian Hinze und seinem Team nicht einmal ungelegen, dass die Pausen zwischen den Spielen derzeit kurz sind und bereits am Mittwoch die n\u00e4chste Aufgabe in der LIQUI-MOLY HBL ansteht. Um 19 Uhr ist mit GWD Minden eine der Mannschaften der Stunde zu Gast in der Klingenhalle.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-37704","post","type-post","status-publish","format-standard","hentry","category-sport"],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:45:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/37704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/comments?post=37704"}],"version-history":[{"count":3,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/37704\/revisions"}],"predecessor-version":[{"id":37708,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/posts\/37704\/revisions\/37708"}],"wp:attachment":[{"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/media?parent=37704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/categories?post=37704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-stadtzeitung.de\/index.php\/wp-json\/wp\/v2\/tags?post=37704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}